{"id":99929,"date":"2023-03-07T15:55:00","date_gmt":"2023-03-07T15:55:00","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2023\/03\/07\/el-ciad-conmemorara-el-dia-internacional-de-la-mujer\/"},"modified":"2023-03-07T15:55:00","modified_gmt":"2023-03-07T15:55:00","slug":"el-ciad-conmemorara-el-dia-internacional-de-la-mujer","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2023\/03\/07\/el-ciad-conmemorara-el-dia-internacional-de-la-mujer\/","title":{"rendered":"El CIAD conmemorara el Dia Internacional de la Mujer"},"content":{"rendered":"<p class=\"MsoNormal\"><span lang=\"ES\">El Centro de Investigaci&oacute;n en Alimentaci&oacute;n y Desarrollo (CIAD) conmemorar&aacute; el D&iacute;a Internacional de la Mujer 2023 a trav&eacute;s de una serie de actividades acad&eacute;micas y de divulgaci&oacute;n del conocimiento relacionadas con la historia de la participaci&oacute;n de las mujeres en la lucha por sus derechos civiles, as&iacute; como sobre la evoluci&oacute;n de la investigaci&oacute;n en salud femenina.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES\">Los eventos tienen el prop&oacute;sito de recordar la lucha por la igualdad de los derechos de las mujeres, concientizar sobre la discriminaci&oacute;n y los diferentes tipos de violencia que a&uacute;n persisten e inspirar a las futuras generaciones a continuar trabajando por la igualdad de g&eacute;nero. <\/span><\/p>\n<p class=\"MsoNormal\"><strong><span lang=\"ES\">Tejiendo historias: di&aacute;logo sobre nuestros feminismos<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES\">La primera jornada se llevar&aacute; a cabo el martes 7 de marzo pr&oacute;ximo a trav&eacute;s de la realizaci&oacute;n del conversatorio &ldquo;Tejiendo historias: di&aacute;logo sobre nuestros feminismos&rdquo;, en el que participar&aacute;n Carmen Reyes Murillo, integrante del &ldquo;Colectivo Comaletzin&rdquo; y fundadora de La Casa de la Mujer en &Aacute;lamos, Sonora; Susana Vidales Rodr&iacute;guez, quien recibi&oacute; el premio estatal de periodismo (1996- Sonora) y fue creadora de <em>Quehaceres<\/em>, primer suplemento que difundi&oacute; las ideas del feminismo en Sonora, y fuera integrante del &ldquo;Colectivo de mujeres&rdquo; en la d&eacute;cada de los a&ntilde;os setenta, y Gilda Salazar Ant&uacute;nez, antrop&oacute;loga feminista integrante del &ldquo;Grupo de mujeres aut&oacute;nomas&rdquo; en Sinaloa durante la &eacute;poca de los a&ntilde;os ochenta, y quien es actualmente acad&eacute;mica del CIAD en la Coordinaci&oacute;n de Desarrollo Regional y cofundadora de la primera c&aacute;tedra en <em>teor&iacute;as de g&eacute;nero y salud<\/em> del Centro.<\/span><\/p>\n<p class=\"MsoNormal\"><strong><span lang=\"ES\">Desarticulando violencias, tejiendo coincidencias<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES\">El 8 de marzo el CIAD emprender&aacute; una campa&ntilde;a cibern&eacute;tica a trav&eacute;s de las redes sociales de la instituci&oacute;n, que tiene como objetivo difundir informaci&oacute;n sobre <span style=\"color: #222222;background: white\">prevenci&oacute;n de la violencia de g&eacute;nero para estudiantes y personal administrativo y docente de Instituciones de Educaci&oacute;n Superior; esta iniciativa se desprende del proyecto &#8220;Desarticulando la violencia juvenil y de g&eacute;nero en las IES de M&eacute;xico&#8221;, que encabeza la profesora del CIAD Rosario Rom&aacute;n P&eacute;rez, esfuerzo apoyado por el Consejo Nacional de Ciencia y Tecnolog&iacute;a (Conacyt) como parte de los Programas Nacionales Estrat&eacute;gicos, y que cuenta con la participaci&oacute;n de doce instituciones mexicanas. <\/span><\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES\">Vinculado al mencionado proyecto, el 17 de marzo se realizar&aacute; el conversatorio &ldquo;<\/span><span lang=\"ES\">Desarticulando las violencias, tejiendo coincidencias&rdquo;, evento en el que se compartir&aacute;n los primeros hallazgos del proyecto interinstitucional mencionado en la Universidad Aut&oacute;noma de Sinaloa y El Colegio de la Frontera Sur, exposici&oacute;n que estar&aacute; a cargo de las profesoras coordinadoras de la investigaci&oacute;n en dichas academias <\/span><span lang=\"ES\">Beatriz Eugenia Rodr&iacute;guez P&eacute;rez y <\/span><span lang=\"ES\">Ang&eacute;lica Aremy Evangelista Garc&iacute;a, respectivamente. Esta jornada es organizada por la profesora Rosario Rom&aacute;n P&eacute;rez.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES\">Para concluir con esta conmemoraci&oacute;n, el jueves 23 de marzo se llevar&aacute; a cabo el conversatorio &ldquo;Mujeres, salud y pol&iacute;ticas p&uacute;blicas: di&aacute;logos entre investigaci&oacute;n e intervenci&oacute;n&rdquo;, en el que participar&aacute;n Graciela Caire Juvera, investigadora de la Coordinaci&oacute;n de Nutrici&oacute;n y actualmente directora general del CIAD, cuyos estudios en salud han estado enfocados hacia el bienestar de las mujeres, y Hilda Garc&iacute;a P&eacute;rez, quien es acad&eacute;mica de El Colegio de la Frontera Norte y actualmente coordinadora de la Unidad Nogales de la misma instituci&oacute;n; su l&iacute;nea de investigaci&oacute;n incluye el estudio de las disparidades en salud de la poblaci&oacute;n femenina adulta y adolescente. En este conversatorio tambi&eacute;n participar&aacute; Marcia Contreras L&oacute;pez, pionera en defensa de los derechos a la salud y desarrollo comunitario y fundadora del centro comunitario para la salud de las mujeres en la colonia Eusebio Kino en Hermosillo, Sonora, y actualmente directora del programa &ldquo;Jefas autogestoras de la transformaci&oacute;n social&rdquo; de la Secretar&iacute;a de Desarrollo Social. Este conversatorio es organizado por la profesora Gilda Salazar Ant&uacute;nez.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES\">&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El CIAD conmemorara el Dia Internacional de la Mujer<\/p>\n","protected":false},"author":1,"featured_media":99930,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[245],"class_list":["post-99929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-ciad"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1678229700_9908.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/99929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=99929"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/99929\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/99930"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=99929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=99929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=99929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}