{"id":98379,"date":"2023-04-11T13:20:29","date_gmt":"2023-04-11T13:20:29","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2023\/04\/11\/chile-aprueba-la-jornada-laboral-de-40-horas-semanales\/"},"modified":"2023-04-11T13:20:29","modified_gmt":"2023-04-11T13:20:29","slug":"chile-aprueba-la-jornada-laboral-de-40-horas-semanales","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2023\/04\/11\/chile-aprueba-la-jornada-laboral-de-40-horas-semanales\/","title":{"rendered":"Chile aprueba la jornada laboral de 40 horas semanales"},"content":{"rendered":"<p><strong>El Congreso de Chile aprob&oacute; este martes reducir la jornada laboral semanal de 45 a 40 horas, convirtiendo a ese pa&iacute;s en la naci&oacute;n de Am&eacute;rica Latina con la semana de trabajo m&aacute;s corta, junto con Ecuador.<\/strong><\/p>\n<p>La propuesta, que fue sancionada por la C&aacute;mara de Diputados luego de su aprobaci&oacute;n un&aacute;nime en el Senado, reduce gradualmente las horas de trabajo en un plazo de cinco a&ntilde;os.<\/p>\n<p>Al a&ntilde;o de su aplicaci&oacute;n se reducir&aacute; la jornada a 44 horas semanales. A los tres a&ntilde;os el l&iacute;mite ser&aacute; de 42 horas y al cabo de un lustro se llegar&aacute; a las 40 horas, que es el tiempo de trabajo recomendado por la Organizaci&oacute;n Internacional del Trabajo (OIT).<\/p>\n<p>La ley prev&eacute; la posibilidad de trabajar cuatro d&iacute;as y descansar tres (a diferencia de la legislaci&oacute;n actual que obliga a un m&iacute;nimo de cinco d&iacute;as laborales).<\/p>\n<p>Y contempla la posibilidad de hacer un m&aacute;ximo de 5 horas extras por semana (hoy se pueden hacer hasta 12 horas extras).<\/p>\n<p>Fabio Bertranou, director de la oficina regional de la OIT en Santiago, le dijo a BBC Mundo que la ley prev&eacute; un r&eacute;gimen especial para los sectores que requieren jornadas laborales extraordinarias, como el minero o el de transporte.<\/p>\n<p>En esos casos se permitir&aacute; que los empleados hagan jornadas de hasta 52 horas por semana, siempre y cuando luego tengan una mayor cantidad de d&iacute;as libres para compensar.<\/p>\n<div class=\"div-pos-7\">&nbsp;<\/div>\n<p>&#8220;La ley contempla la posibilidad de que las 40 horas semanales se alcancen haciendo un promedio de cuatro semanas. As&iacute; que, si alguna semana se trabaja m&aacute;s, lo importante es que el promedio d&eacute; 40&#8221;, explic&oacute;.<\/p>\n<p><strong>Con esta ley Chile se convierte en el segundo pa&iacute;s de Am&eacute;rica Latina, despu&eacute;s de Ecuador, en aprobar la semana laboral recomendada por la OIT.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chile aprueba la jornada laboral de 40 horas semanales<\/p>\n","protected":false},"author":1,"featured_media":98380,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[182],"tags":[3579],"class_list":["post-98379","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-chile"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1681244429_203355.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/98379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=98379"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/98379\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/98380"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=98379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=98379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=98379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}