{"id":9519,"date":"2014-08-18T16:06:30","date_gmt":"2014-08-18T16:06:30","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2014\/08\/18\/hay-que-endurecer-medidas-contra-grupo-mxico-cesar-augusto-marcor\/"},"modified":"2014-08-18T16:06:30","modified_gmt":"2014-08-18T16:06:30","slug":"hay-que-endurecer-medidas-contra-grupo-mxico-cesar-augusto-marcor","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2014\/08\/18\/hay-que-endurecer-medidas-contra-grupo-mxico-cesar-augusto-marcor\/","title":{"rendered":"Hay que endurecer medidas contra Grupo M&eacute;xico: Cesar Augusto Marcor"},"content":{"rendered":"<p><strong>Por Rafael Renter&iacute;a<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\"><span>Se suma el Partido Verde Ecologista de M&eacute;xico en el estado a los llamados de exigencia para que Grupo M&eacute;xico solvente en todos los sentidos el grave problema que ocasion&oacute; con la contaminaci&oacute;n del Rio Sonora. <\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>Cesar Augusto Marcor, se&ntilde;al&oacute; que desde hace a&ntilde;os e incluso cuando era diputado local se solicit&oacute; exhortar a todos los niveles de gobierno para exigirle a esa empresa minera el trabajar en la m&aacute;s estricta normatividad que evitar&aacute; alguna situaci&oacute;n como la que provocaron en los &uacute;ltimos d&iacute;as, por ello y ante este lamentable episodio es fundamental ponerles un alto y sobre todo que remedien cualquier problema ocasionado.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><strong><span>&ldquo;Se est&aacute; pidiendo a la empresa no solo una investigaci&oacute;n y que sean responsables del tema del medio ambiente, sino que tambi&eacute;n se tienen que hacer responsables de la ciudadan&iacute;a porque habr&aacute; muchos enfermos y por eso exhorto a las personas a que ya se acerquen al grupo M&eacute;xico para buscar una soluci&oacute;n a sus casos y sobre todo que esa empresa transnacional ya deje de evitarlos porque tenemos informaci&oacute;n que a varios afectados no los quieren atender lo cual es adem&aacute;s otra acci&oacute;n de ilegalidad que est&aacute;n llevando a cabo&rdquo;, afirm&oacute;.<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>A&ntilde;adi&oacute; que las autoridades deber&aacute;n poner mucho cuidado en la reparaci&oacute;n de los da&ntilde;os en &aacute;mbitos como el impacto ambiental,&nbsp; ecol&oacute;gico, la contaminaci&oacute;n del agua, pozos pero sobre todo de la salud de las personas que habitan en la zona del Rio Sonora porque con este antecedente podr&iacute;an salir muchas enfermedades en los pr&oacute;ximos meses y a&ntilde;os.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>Finalmente coment&oacute; que esperaba que Grupo M&eacute;xico pudiera recular y hacer las cosas de la mejor manera para ayudar en la reparaci&oacute;n de todo el da&ntilde;o ocasionado y sobre todo le solicit&oacute; a la clase pol&iacute;tica sonorense el no tomar este asunto como bandera pol&iacute;tica y aprovecharse de esta desgracia.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><strong><span>&ldquo;La gente est&aacute; pidiendo a gritos una soluci&oacute;n al problema que est&aacute;n viviendo lo m&aacute;s r&aacute;pido posible, piden a gritos agua, pero lo malo de este caso es que muchos pol&iacute;ticos se est&aacute;n agarrando de esta desgracia y no se vale aprovecharse de esta forma cuando mejor deber&iacute;an exigir resultados r&aacute;pidos y que Grupo M&eacute;xico repare lo que provoc&oacute;&rdquo;, finaliz&oacute;.<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\">&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se suma el Partido Verde Ecologista de M&eacute;xico en el estado a los llamados de exigencia para que Grupo M&eacute;xico solvente en todos los sentidos el grave problema que ocasion&oacute; con la contaminaci&oacute;n del Rio Sonora.<\/p>\n","protected":false},"author":1,"featured_media":25241,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[193],"class_list":["post-9519","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-cuate-marcor"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2014\/08\/1408403190_cuatemarw.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/9519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=9519"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/9519\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/25241"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=9519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=9519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=9519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}