{"id":90070,"date":"2023-11-22T08:34:54","date_gmt":"2023-11-22T08:34:54","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2023\/11\/22\/avances-legislativos-en-sonora-defensoria-publica-transparencia-en-obras\/"},"modified":"2023-11-22T08:34:54","modified_gmt":"2023-11-22T08:34:54","slug":"avances-legislativos-en-sonora-defensoria-publica-transparencia-en-obras","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2023\/11\/22\/avances-legislativos-en-sonora-defensoria-publica-transparencia-en-obras\/","title":{"rendered":"Avances Legislativos en Sonora: defensoria publica, transparencia en obras"},"content":{"rendered":"<div>Hermosillo, Sonora, 21 de noviembre de 2023.- Una Defensor&iacute;a P&uacute;blica con procesos m&aacute;s eficientes y personal mejor capacitado para prestar el noble servicio que el estado de Sonora le ha encomendado, garantizar el acceso a la justicia a los que menos tienen, fue el objeto de las reformas y adiciones aprobadas por el Congreso de Sonora a la ley que rige dicha instituci&oacute;n.<\/div>\n<div>&nbsp;<\/div>\n<div>La iniciativa fue presentada por las y los diputados del grupo parlamentario de Morena, a efecto de establecer una reingenier&iacute;a administrativa a trav&eacute;s de las facultades del titular de la Defensor&iacute;a P&uacute;blica y de las &aacute;reas que la componen, los cargos de los servidores p&uacute;blicos que la integran, sus atribuciones y otros aspectos.<\/div>\n<div>&nbsp;<\/div>\n<div>La diputada Mar&iacute;a Jes&uacute;s Castro Urquijo (Morena) dio lectura al documento, en el que destaca la redefinici&oacute;n del proceso para ingresar a laborar en la instituci&oacute;n, y la formaci&oacute;n y capacitaci&oacute;n de su personal, con la finalidad de mejorar el servicio que ofrece a la ciudadan&iacute;a, pero en especial a las personas que no tienen acceso a una defensa particular.<\/div>\n<div>&nbsp;<\/div>\n<div>En el desarrollo de la sesi&oacute;n ordinaria, la diputada Natalia Rivera Grijalva present&oacute;, a nombre del grupo parlamentario de Movimiento Ciudadano, una iniciativa con proyecto de decreto que adiciona diversos art&iacute;culos a la Ley de Obras P&uacute;blicas y Servicios Relacionados con las Mismas, con el objeto de elevar a rango de ley la plataforma de transparencia de las contrataciones de obra p&uacute;blica, para que pase de ser un acto voluntario de transparencia proactiva a ser una obligaci&oacute;n normativa cuyo incumplimiento d&eacute; lugar a la responsabilidad administrativa de los funcionarios omisos. Se turn&oacute; para estudio a la Comisi&oacute;n de Obras y Servicios P&uacute;blicos.<\/div>\n<div>&nbsp;<\/div>\n<div>Por considerar que la Ley de Transporte del Estado de Sonora tiene un retraso significativo, ya que ante el dinamismo del sector sus disposiciones han quedado desfasadas, el diputado Ricardo Lugo Moreno (Morena) present&oacute; una iniciativa con proyecto de una nueva ley en la materia que cubra los vac&iacute;os legales de la actual norma.<\/div>\n<div>&nbsp;<\/div>\n<div>La Comisi&oacute;n de Movilidad y Seguridad Vial estudiar&aacute; dicha iniciativa, en tanto a la Comisi&oacute;n de Obras y Servicios P&uacute;blicos se turn&oacute; para estudio una iniciativa con proyecto de decreto que reforma el Art&iacute;culo 32 de la Ley de Obras P&uacute;blicas y Servicios Relacionados con las Mismas, presentado por el grupo parlamentario de Acci&oacute;n Nacional, a fin de establecer que el Comit&eacute; de Contralor&iacute;a Social participar&aacute; como observador en todas las etapas relativas a la determinaci&oacute;n del alcance de la obra: planeaci&oacute;n, conceptualizaci&oacute;n, proyecto ejecutivo, presupuestaci&oacute;n, licitaci&oacute;n, contrataci&oacute;n de obra, ejecuci&oacute;n y entrega final, indic&oacute; el diputado Jos&eacute; Armando Guti&eacute;rrez.<\/div>\n<div>&nbsp;<\/div>\n<div>Por su parte, la diputada Rosa Elena Trujillo Llanes (MC) present&oacute; iniciativa para ampliar, dentro de la Ley de Acceso de las Mujeres a una Vida Libre de Violencia para el Estado de Sonora, las dependencias que conforman el Sistema Estatal para Prevenir, Atender, Sancionar y Erradicar la Violencia contra las Mujeres, previsto en el Art&iacute;culo 20 de la norma, con el fin de reforzar los esfuerzos interdisciplinarios y el trabajo transversal al elevar a rango de ley la obligaci&oacute;n de dar respuesta a solicitudes de Alerta de Violencia de G&eacute;nero contra las Mujeres. Se turn&oacute; a la Comisi&oacute;n para la Igualdad de G&eacute;nero.<\/div>\n<div>&nbsp;<\/div>\n<div>Y para establecer las bases normativas necesarias para hacer funcional y eficiente el Fondo para el Aprovechamiento de las Fuentes Renovables de Energ&iacute;a y Eficiencia Energ&eacute;tica en el Estado de Sonora, la diputada Lirio Anah&iacute; Del Castillo Salazar (Partido Verde) propuso que este sea administrado por un fideicomiso integrado por un comit&eacute; t&eacute;cnico, y que sea conformado por recursos de la Ley de Ingresos y Presupuesto de Egresos de los tres niveles de gobierno. Ser&aacute; estudiada en la Comisi&oacute;n de Energ&iacute;a, Medio Ambiente y Cambio Clim&aacute;tico.<\/div>\n<div>&nbsp;<\/div>\n<div>Finalmente, la asamblea aprob&oacute; un acuerdo que resuelve exhortar a los 72 ayuntamientos del estado para que, de acuerdo a su disponibilidad presupuestal, a partir del ejercicio fiscal 2024 implementen y pongan en operaci&oacute;n programas permanentes de esterilizaci&oacute;n gratuita para perros y gatos, para el control de sobrepoblaci&oacute;n, iniciativa presentada por las diputadas del grupo parlamentario de Morena, Rebeca Irene Silva Gallardo, Elia Sahara Sallard Hern&aacute;ndez y Celeste Taddei Arriola.<\/div>\n<div>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Avances Legislativos en Sonora: defensoria publica, transparencia en obras y compromisos sociales<\/p>\n","protected":false},"author":1,"featured_media":90071,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[298],"class_list":["post-90070","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-congreso"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1700667295_378232008.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/90070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=90070"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/90070\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/90071"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=90070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=90070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=90070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}