{"id":89944,"date":"2023-11-25T10:37:01","date_gmt":"2023-11-25T10:37:01","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2023\/11\/25\/acuerdan-sec-sonora-e-isssteson-establecer-acciones-educativas\/"},"modified":"2023-11-25T10:37:01","modified_gmt":"2023-11-25T10:37:01","slug":"acuerdan-sec-sonora-e-isssteson-establecer-acciones-educativas","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2023\/11\/25\/acuerdan-sec-sonora-e-isssteson-establecer-acciones-educativas\/","title":{"rendered":"Acuerdan SEC Sonora e Isssteson establecer acciones educativas"},"content":{"rendered":"<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px\" align=\"left\"><span style=\"color: #262c30\">Hermosillo, Sonora; 25 de noviembre de 2023.- Tomando como punto de partida que la educaci&oacute;n y la salud son servicios p&uacute;blicos a los que deben tener acceso todas las ni&ntilde;as, ni&ntilde;os y adolescentes como derecho fundamental, el Gobierno de Sonora brindar&aacute; atenci&oacute;n educativa y cultural a estudiantes internados en el Centro M&eacute;dico &#8220;Dr. Ignacio Ch&aacute;vez&#8221;.<\/span><\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px\" align=\"left\">&nbsp;<\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px\" align=\"left\"><span style=\"color: #262c30\">Aar&oacute;n Grageda Bustamante, secretario de Educaci&oacute;n y Cultura, y Froyl&aacute;n G&aacute;mez Gamboa, director general del Instituto de Seguridad y Servicios Sociales de los Trabajadores del Estado de Sonora (Isssteson) firmaron el convenio de colaboraci&oacute;n para beneficiar al alumnado que se ve ocasionalmente impedido de continuar con sus estudios de educaci&oacute;n b&aacute;sica de forma temporal.<\/span><\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px\" align=\"left\">&nbsp;<\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px\" align=\"left\"><span style=\"color: #262c30\">El titular de la SEC resalt&oacute; que, como resultado de dicho convenio nombrado &ldquo;Sigamos aprendiendo en el hospital&rdquo;, va acorde a los principios de la Nueva Escuela Mexicana (NEM) que impulsa trayectorias educativas completas, continuas y de excelencia, adem&aacute;s de responder a la trasversalidad que promueve el gobernador Alfonso Durazo Monta&ntilde;o.<\/span><\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px\" align=\"left\">&nbsp;<\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px\" align=\"left\"><span style=\"color: #262c30\">Reconoci&oacute; que se trata de un reto significativo, por tratarse de un entorno que no est&aacute; dise&ntilde;ado para los procesos de aprendizaje, pero asegur&oacute; que ambas instituciones cuenten con el compromiso y profesionalismo para atender de forma permanente a las infancias.&nbsp;<\/span><\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px\" align=\"left\">&nbsp;<\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px\" align=\"left\"><span style=\"color: #262c30\">Por su parte, Froyl&aacute;n G&aacute;mez Gamboa agradeci&oacute; la vinculaci&oacute;n con la SEC para concretar el proyecto, que en un inicio beneficiar&aacute; a 15 ni&ntilde;as, ni&ntilde;os y adolescentes, adem&aacute;s de garantizar el apoyo del personal de Isssteson para que las condiciones de infraestructura y el material a utilizar sean los adecuados.<\/span><\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px\" align=\"left\">&nbsp;<\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px\" align=\"left\"><span style=\"color: #262c30\">A&ntilde;adi&oacute; que la atenci&oacute;n educativa de los menores hospitalizados, responde a una inquietud externada por los padres y madres de familia ante la interrupci&oacute;n de sus estudios derivado de estancias prolongadas por cuestiones de salud.<\/span><\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px\" align=\"left\">&nbsp;<\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px\" align=\"left\"><span style=\"color: #262c30\">Puntualiz&oacute; que este convenio tendr&aacute; un impacto positivo en la recuperaci&oacute;n de ni&ntilde;as, ni&ntilde;as y adolescentes, quienes conservan sus facultades cognitivas en condici&oacute;n de atender el aprendizaje, sin que ello les signifique cargas que compliquen su condici&oacute;n y por lo contrario, favorecen su buen &aacute;nimo y condici&oacute;n psicoemocional.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acuerdan SEC Sonora e Isssteson establecer acciones educativas en beneficio de estudiantes hospitalizados<\/p>\n","protected":false},"author":1,"featured_media":89945,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[211],"class_list":["post-89944","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-sec"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1700933821_9321e9ba-6b48-477d-a0f9-966c44b1eb9d.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/89944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=89944"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/89944\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/89945"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=89944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=89944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=89944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}