{"id":89490,"date":"2023-12-08T08:11:38","date_gmt":"2023-12-08T08:11:38","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2023\/12\/08\/brindara-consejeria-juridica-asesoria-gratuita-a-mas-de-600-personas-jubiladas\/"},"modified":"2023-12-08T08:11:38","modified_gmt":"2023-12-08T08:11:38","slug":"brindara-consejeria-juridica-asesoria-gratuita-a-mas-de-600-personas-jubiladas","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2023\/12\/08\/brindara-consejeria-juridica-asesoria-gratuita-a-mas-de-600-personas-jubiladas\/","title":{"rendered":"Brindara Consejeria Juridica asesoria gratuita a mas de 600 personas jubiladas"},"content":{"rendered":"<p><strong style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\">Hermosillo, Sonora; 8 de diciembre de 2023.-<\/strong><span style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\">&nbsp;Para asesorar y representar jur&iacute;dicamente y de manera gratuita a personas jubiladas y pensionadas de ISSSTESON, se firm&oacute; un convenio de colaboraci&oacute;n conjunta entre el Instituto y la Consejer&iacute;a Jur&iacute;dica y la Defensor&iacute;a P&uacute;blica del Estado de Sonora, el cual incluye un cat&aacute;logo de servicios en las &aacute;reas penal, civil-familiar y administrativa.<\/span><br style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\" \/><br style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\" \/><span style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\">El convenio, con vigencia de un a&ntilde;o a partir de su firma, estipula que se trata de un servicio para m&aacute;s de 600 personas, miembros activos de los talleres en alguna de las cuatro Casas Club del Pensionado y Jubilado de ISSSTSON, ubicadas en Hermosillo, Cajeme, San Luis R&iacute;o Colorado y Nogales.<\/span><br style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\" \/><br style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\" \/><span style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\">Adem&aacute;s, como parte de los beneficios, se incluye a los familiares directos de jubilados y pensionados inscritos en talleres de Casas Club que lo requieran y no cuenten con los recursos econ&oacute;micos suficientes para contratar abogado particular, en los asuntos o tr&aacute;mites jur&iacute;dicos que se encuentren dentro del cat&aacute;logo de servicios que otorga la Defensor&iacute;a P&uacute;blica a la ciudadan&iacute;a.<\/span><br style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\" \/><br style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\" \/><span style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\">Froyl&aacute;n G&aacute;mez Gamboa y Adriel C&oacute;rdova Pimentel, titulares de ISSSTESON y la Secretar&iacute;a de la Consejer&iacute;a Jur&iacute;dica, respectivamente, firmaron el convenio con el cual se beneficiar&aacute; a m&aacute;s de 600 personas jubiladas y pensionadas que participan activamente en los talleres de las Casas Club del Instituto.<\/span><br style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\" \/><br style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\" \/><span style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\">Dicho convenio incluye, entre otros aspectos, asesor&iacute;a y defensor&iacute;a jur&iacute;dica en procedimientos penales, divorcios, constituci&oacute;n de patrimonio familiar, pensi&oacute;n alimenticia, custodia de menores, juicios sucesorios testamentarios o intestamentarios y defensa en procesos de responsabilidad administrativa<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Brindara Consejeria Juridica asesoria gratuita a mas de 600 personas jubiladas y pensionadas de ISSSTESON<\/p>\n","protected":false},"author":1,"featured_media":89491,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[602],"class_list":["post-89490","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-isssteson"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1702048298_158516228.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/89490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=89490"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/89490\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/89491"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=89490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=89490"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=89490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}