{"id":89311,"date":"2023-12-13T09:46:52","date_gmt":"2023-12-13T09:46:52","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2023\/12\/13\/un-exito-el-tradicional-concierto-coral-navideno-de-isssteson\/"},"modified":"2023-12-13T09:46:52","modified_gmt":"2023-12-13T09:46:52","slug":"un-exito-el-tradicional-concierto-coral-navideno-de-isssteson","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2023\/12\/13\/un-exito-el-tradicional-concierto-coral-navideno-de-isssteson\/","title":{"rendered":"Un exito el tradicional Concierto Coral Navideno de Isssteson"},"content":{"rendered":"<p><strong style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\">Hermosillo, Sonora; 13 de diciembre de 2023.-&nbsp;<\/strong><span style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\">Como cada a&ntilde;o, Isssteson, a trav&eacute;s de la Casa Club del Jubilado y Pensionado, llev&oacute; a cabo el tradicional Concierto Coral Navide&ntilde;o en las escalinatas de Palacio de Gobierno.<\/span><br style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\" \/><br style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\" \/><span style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\">Froyl&aacute;n G&aacute;mez Gamboa, director general de Isssteson, acompa&ntilde;ado de autoridades del Instituto y del Sueisssteson, dio la bienvenida a los asistentes que llenaron el recinto para deleitarse con el talento de jubilados y pensionados, as&iacute; como de invitados especiales.<\/span><br style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\" \/><br style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\" \/><span style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\">Artistas vocales y musicales como el coro de musicoterapia de la Casa de la Cultura Norte, dirigidos por el maestro Guadalupe Ch&aacute;vez, el coro Amistad y Canto con la direcci&oacute;n del maestro Carlos Taraz&oacute;n Fuentes, as&iacute; como el Orfe&oacute;n Sonora con la batuta del maestro Isidro Amaya, fueron los invitados de la noche.<\/span><br style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\" \/><br style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\" \/><span style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\">Adem&aacute;s, como anfitriones se cont&oacute; con la participaci&oacute;n de talentosos jubilados y pensionados de la Casa Club de Isssteson, como el coro de Adultos Mayores y la Orquesta Did&aacute;ctica Odamis, dirigidos por el maestro Mart&iacute;n V&eacute;jar Ram&iacute;rez, y alumnos del taller de artes pl&aacute;sticas del maestro Enrique D&iacute;az, quienes expusieron sus pinturas con tema navide&ntilde;o.<\/span><br style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\" \/><br style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\" \/><span style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\">Durante la noche se escucharon canciones navide&ntilde;as como &#8220;Los peces en el r&iacute;o&#8221;, &#8220;Ojitos de cascabel&#8221;, &#8220;Posadas mexicanas&#8221;, &#8220;El rey de Israel&#8221;, &#8220;&Aacute;ngeles cantando est&aacute;n&#8221;, &#8220;Holy night&#8221;, &#8220;Aleluya&#8221; de Haendel, entre muchos otros temas que reforzaron el esp&iacute;ritu navide&ntilde;o de los asistentes.<\/span><br style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\" \/><br style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\" \/><span style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\">Al final, los aplausos para los participantes cerraron con broche de oro el Concierto Coral Navide&ntilde;o de la Casa Club del Jubilado y Pensionado de Isssteson.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un exito el tradicional Concierto Coral Navideno de Isssteson<\/p>\n","protected":false},"author":1,"featured_media":89312,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[602],"class_list":["post-89311","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-isssteson"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1702486012_7655.jpeg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/89311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=89311"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/89311\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/89312"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=89311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=89311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=89311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}