{"id":89217,"date":"2023-12-15T09:53:08","date_gmt":"2023-12-15T09:53:08","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2023\/12\/15\/el-pt-sonora-contribuira-al-proyecto-de-claudia-sheinbaum\/"},"modified":"2023-12-15T09:53:08","modified_gmt":"2023-12-15T09:53:08","slug":"el-pt-sonora-contribuira-al-proyecto-de-claudia-sheinbaum","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2023\/12\/15\/el-pt-sonora-contribuira-al-proyecto-de-claudia-sheinbaum\/","title":{"rendered":"El PT Sonora contribuira al proyecto de Claudia Sheinbaum"},"content":{"rendered":"<p>Hermosillo, Sonora, 15 de diciembre del 2023; Con la visita de la pre candidata a la presidencia de la Rep&uacute;blica Claudia Sheinbaum, por la coalici&oacute;n &ldquo;Sigamos Haciendo Historia&rdquo; el Partido del Trabajo en la entidad refrenda su compromiso de apoyar el proyecto y de contribuir con buenos cuadros que garanticen que la principal encomienda contin&uacute;e dando buenos resultados a los m&aacute;s desprotegidos.<\/p>\n<p>&nbsp;<\/p>\n<p>El comisionado estatal del PT Ram&oacute;n Flores, se&ntilde;al&oacute; que tuvo oportunidad de platicar con la precandidata presidencial, a quien le expuso el compromiso fuerte de que los pr&oacute;ximos candidatos petistas a diferentes cargos de elecci&oacute;n, ser&aacute;n hombres y mujeres que le garanticen no solo la continuidad del proyecto, sino tambi&eacute;n contribuir al mismo.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;Somos conscientes dentro del partido que debemos impulsar cuadros con trayectoria y con conocimiento del proyecto nacional, pero sobre todo con el firme compromiso que van a una &ldquo;batalla&rdquo; de no permitir que los de antes lleguen nuevamente al poder, ya que la 4T a&uacute;n no logra el prop&oacute;sito final y para ello se ocupan gente que lo defienda en las diferentes trincheras&rdquo;, puntualiz&oacute;.<\/p>\n<p>&nbsp;<\/p>\n<p>El partido visitar&aacute; cada rinc&oacute;n de Sonora, con el prop&oacute;sito de recordarle a la gente que el presidente Andr&eacute;s Manuel L&oacute;pez Obrador ha sido el &uacute;nico presidente que NO se ha servido con &ldquo;la cuchara de la corrupci&oacute;n&rdquo;&nbsp; como lo hicieron los antecesores del PRI y del PAN, y por qu&eacute; debemos seguir apoyando a nuestra precandidata Claudia, precis&oacute; Ram&oacute;n Flores.<\/p>\n<p>&nbsp;<\/p>\n<p>El PT estuvo presente en los diferentes eventos que encabez&oacute; la doctora Claudia Sheinbaum en los municipios de #Guaymas y #Huatabampo mostrando fortaleza y unidad entre los miles de militantes y simpatizantes que acudieron a recibir y sobre todo a escuchar las propuestas de la precandidata, adem&aacute;s, de participar los alcaldes y diputados locales petistas Diana Karina Barrera e Iram Sol&iacute;s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El PT Sonora contribuira al proyecto de Claudia Sheinbaum &acirc;\u0080\u009cSigamos Haciendo Historia&acirc;\u0080\u009d: Ramon Flores<\/p>\n","protected":false},"author":1,"featured_media":89218,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[240],"class_list":["post-89217","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estatal","tag-pt-sonora"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1702659188_WhatsAppImage2023-12-14at4.18.04PM(1).jpeg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/89217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=89217"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/89217\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/89218"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=89217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=89217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=89217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}