{"id":89129,"date":"2023-12-18T19:31:58","date_gmt":"2023-12-18T19:31:58","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2023\/12\/18\/fortalece-uts-participacion-ciudadana-y-democracia-entre-los-jovenes\/"},"modified":"2023-12-18T19:31:58","modified_gmt":"2023-12-18T19:31:58","slug":"fortalece-uts-participacion-ciudadana-y-democracia-entre-los-jovenes","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2023\/12\/18\/fortalece-uts-participacion-ciudadana-y-democracia-entre-los-jovenes\/","title":{"rendered":"Fortalece UTS participacion ciudadana y democracia entre los jovenes"},"content":{"rendered":"<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px\" align=\"left\"><span style=\"color: #000000\">Cajeme, Sonora; 18 de diciembre de 2023.- Que las nuevas generaciones participen activamente en la construcci&oacute;n de una sociedad democr&aacute;tica y participativa tambi&eacute;n forma parte de los objetivos de la Universidad Tecnol&oacute;gica del Sur de Sonora (UTS), resaltaron autoridades universitarias.<\/span><\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px;text-align: center\">&nbsp;<\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px\" align=\"left\"><span style=\"color: #000000\">La instituci&oacute;n fue sede del conversatorio &ldquo;La importancia del voto razonado&rdquo;, impartido por Rafael Antonio L&oacute;pez Oroz, coordinador de Participaci&oacute;n Ciudadana en el Instituto Estatal Electoral y de Participaci&oacute;n Ciudadana (IEE Sonora).<\/span><\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px;text-align: center\">&nbsp;<\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px\" align=\"left\"><span style=\"color: #000000\">En la charla, se les habl&oacute; a los estudiantes sobre las elecciones, a trav&eacute;s de las cuales la ciudadan&iacute;a elige a sus representantes para cargos p&uacute;blicos y tambi&eacute;n expresan sus intereses y demandas para que puedan ser traducidas en pol&iacute;ticas p&uacute;blicas.<\/span><\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px;text-align: center\">&nbsp;<\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px\" align=\"left\"><span style=\"color: #000000\">Por su parte, los universitarios plantearon algunas de las razones por las cuales no acuden a votar el d&iacute;a de las elecciones, a lo cual el expositor les invit&oacute; a mejorar sus niveles de participaci&oacute;n electoral, para que pueda ejercer su derecho al voto de manera independiente, con autonom&iacute;a y de manera informada.<\/span><\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px;text-align: center\">&nbsp;<\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px\" align=\"left\"><span style=\"color: #000000\">En el encuentro tambi&eacute;n se les explic&oacute; sobre los instrumentos de la participaci&oacute;n ciudadana, como lo es el plebiscito, refer&eacute;ndum, iniciativa popular y la consulta vecinal, consulta popular, presupuesto participativo, agendas de desarrollo local, entre otras formas de fortalecer la democracia en Sonora y M&eacute;xico.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fortalece UTS participacion ciudadana y democracia entre los jovenes<\/p>\n","protected":false},"author":1,"featured_media":89130,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[5875],"class_list":["post-89129","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estatal","tag-uts"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1702953118_UTS-IE.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/89129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=89129"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/89129\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/89130"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=89129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=89129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=89129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}