{"id":88603,"date":"2024-01-10T19:51:46","date_gmt":"2024-01-10T19:51:46","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2024\/01\/10\/toman-protesta-al-consejo-directivo-2024-2025-de-asociacion-mexicana-de-agentes\/"},"modified":"2024-01-10T19:51:46","modified_gmt":"2024-01-10T19:51:46","slug":"toman-protesta-al-consejo-directivo-2024-2025-de-asociacion-mexicana-de-agentes","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2024\/01\/10\/toman-protesta-al-consejo-directivo-2024-2025-de-asociacion-mexicana-de-agentes\/","title":{"rendered":"Toman protesta al Consejo Directivo 2024-2025 de Asociacion Mexicana de Agentes"},"content":{"rendered":"<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px\" align=\"left\"><span style=\"color: #000000\">Hermosillo, Sonora; 10 de enero de 2024.- Estrechar relaciones entre el gobierno de Sonora y la Asociaci&oacute;n Mexicana de Agentes de Seguros y Fianzas, as&iacute; como participar en las actividades que organiza la secretar&iacute;a de Econom&iacute;a, ser&aacute;n las l&iacute;neas de acci&oacute;n que establecer&aacute;n con la AMASFAC.<\/span><\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px;text-align: center\">&nbsp;<\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px\" align=\"left\"><span style=\"color: #000000\">Margarita V&eacute;lez de la Rocha, secretaria de Econom&iacute;a al tomar protesta al Consejo Directivo 2024-2025 de la AMASFAC, que presidir&aacute; Jorge Armando V&aacute;zquez Pesqueira, dijo que con esta asociaci&oacute;n mantendr&aacute;n estrecha comunicaci&oacute;n para que como gremio se integren a las Expo Negocios y puedan ofrecer sus servicios como parte del gran crecimiento econ&oacute;mico que se viene para el estado de Sonora.<\/span><\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px;text-align: center\">&nbsp;<\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px\" align=\"left\"><span style=\"color: #000000\">&ldquo;Para instancias de los tres &oacute;rdenes de gobierno, las afianzadoras son un elemento clave para que los proveedores y prestadores de servicios aseguren el cumplimiento de sus obligaciones, mediante el instrumento que brinda legalidad, solidez y confiabilidad en las transacciones comerciales y contractuales&rdquo;, se&ntilde;al&oacute; la titular de Econom&iacute;a.<\/span><\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px;text-align: center\">&nbsp;<\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px\" align=\"left\"><span style=\"color: #000000\">V&eacute;lez de la Rocha dijo que los agentes de seguros y fianzas han contribuido mediante la fortaleza de su sector al desarrollo econ&oacute;mico de Sonora, por lo que su labor de brindar asesor&iacute;a profesional y especializada a las personas para que puedan tomar las mejores decisiones para la protecci&oacute;n de sus familias, su salud y su patrimonio, son fundamentales.<\/span><\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px;text-align: center\">&nbsp;<\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px\" align=\"left\"><span style=\"color: #000000\">Desde la secretar&iacute;a de Econom&iacute;a siempre estamos dispuestos y con las puertas abiertas para el di&aacute;logo entre gobierno y el sector privado y para trabajar unidos en metas comunes tan importantes, como lo son brindar certeza jur&iacute;dica y proteger el patrimonio de las y los sonorenses, puntualiz&oacute; la titular de la dependencia.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toman protesta al Consejo Directivo 2024-2025 de Asociacion Mexicana de Agentes de Seguros y Fianzas<\/p>\n","protected":false},"author":1,"featured_media":88604,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[1120],"class_list":["post-88603","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-sec-economia"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1704941506_241025582.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/88603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=88603"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/88603\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/88604"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=88603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=88603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=88603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}