{"id":86693,"date":"2024-03-01T23:31:53","date_gmt":"2024-03-01T23:31:53","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2024\/03\/01\/hoy-me-va-a-conocer-mexico-dice-maynez-al-iniciar-campana\/"},"modified":"2024-03-01T23:31:53","modified_gmt":"2024-03-01T23:31:53","slug":"hoy-me-va-a-conocer-mexico-dice-maynez-al-iniciar-campana","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2024\/03\/01\/hoy-me-va-a-conocer-mexico-dice-maynez-al-iniciar-campana\/","title":{"rendered":"Hoy me va a conocer Mexico, dice Maynez al iniciar campana"},"content":{"rendered":"<p style=\"margin: 0px 0px 17px;padding: 0px;font-size: 16px;line-height: 1.8;text-align: justify;color: #313131;font-family: Lato, sans-serif\">El candidato presidencial de Movimiento Ciudadano, Jorge &Aacute;lvarez M&aacute;ynez, llev&oacute; a cabo su primer mitin de campa&ntilde;a en Lagos de Moreno, Jalisco, uno de los municipios m&aacute;s violentos de la entidad y basti&oacute;n emecista.<\/p>\n<p style=\"margin: 0px 0px 17px;padding: 0px;font-size: 16px;line-height: 1.8;text-align: justify;color: #313131;font-family: Lato, sans-serif\">&ldquo;Vamos a atajar el peor de los problemas, de los horrores que tiene M&eacute;xico, que es el problema de la violencia, de la impunidad, de la seguridad&rdquo;, prometi&oacute;.<\/p>\n<p style=\"margin: 0px 0px 17px;padding: 0px;font-size: 16px;line-height: 1.8;text-align: justify;color: #313131;font-family: Lato, sans-serif\">Durante su discurso, acus&oacute; al gobierno federal de olvidar proteger a varios estados del pa&iacute;s, donde faltan polic&iacute;as y perciben sueldos precarios.<\/p>\n<p style=\"margin: 0px 0px 17px;padding: 0px;font-size: 16px;line-height: 1.8;text-align: justify;color: #313131;font-family: Lato, sans-serif\">Tambi&eacute;n critic&oacute; el la propuesta de seguridad de su oponente X&oacute;chitl G&aacute;lvez, candidata de la alianza conformada por el PRI, PAN y PRD, que prometi&oacute; construir una enorme prisi&oacute;n para atender el problema de la inseguridad.<\/p>\n<p style=\"margin: 0px 0px 17px;padding: 0px;font-size: 16px;line-height: 1.8;text-align: justify;color: #313131;font-family: Lato, sans-serif\">&ldquo;El problema de la inseguridad no se arregla con una carcelota. Eso solo lo puede plantear quien est&aacute; pensando en votos y no en serio&rdquo;, lanz&oacute;.<\/p>\n<p style=\"margin: 0px 0px 17px;padding: 0px;font-size: 16px;line-height: 1.8;text-align: justify;color: #313131;font-family: Lato, sans-serif\">&Aacute;lvarez M&aacute;ynez arremeti&oacute; adem&aacute;s contra el PRI y el PAN, a quienes acus&oacute; de iniciar la militarizaci&oacute;n del pa&iacute;s que, se&ntilde;al&oacute;, continu&oacute; Morena.<\/p>\n<p style=\"margin: 0px 0px 17px;padding: 0px;font-size: 16px;line-height: 1.8;text-align: justify;color: #313131;font-family: Lato, sans-serif\">&ldquo;Y eso no es culpa de nuestras Fuerzas Armadas&rdquo;, subray&oacute;.<\/p>\n<p style=\"margin: 0px 0px 17px;padding: 0px;font-size: 16px;line-height: 1.8;text-align: justify;color: #313131;font-family: Lato, sans-serif\">Sin mencionar el hallazgo de siete cuerpos horas antes de su evento, &Aacute;lvarez M&aacute;ynez asegur&oacute; otros pol&iacute;ticos no tienen empat&iacute;a porque son protegidos mientras la ciudadan&iacute;a no.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy me va a conocer Mexico, dice Maynez al iniciar campana<\/p>\n","protected":false},"author":1,"featured_media":86694,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[6497],"class_list":["post-86693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-jorge-alvarez-maynez"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1709361113_Jorge\u00c1lvarezMaynez.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/86693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=86693"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/86693\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/86694"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=86693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=86693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=86693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}