{"id":86657,"date":"2024-03-03T18:46:47","date_gmt":"2024-03-03T18:46:47","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2024\/03\/03\/asesinan-a-alfredo-gonzalez-diaz-candidato-del-pt-en-guerrero\/"},"modified":"2024-03-03T18:46:47","modified_gmt":"2024-03-03T18:46:47","slug":"asesinan-a-alfredo-gonzalez-diaz-candidato-del-pt-en-guerrero","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2024\/03\/03\/asesinan-a-alfredo-gonzalez-diaz-candidato-del-pt-en-guerrero\/","title":{"rendered":"Asesinan a Alfredo Gonzalez Diaz, candidato del PT en Guerrero"},"content":{"rendered":"<p>El aspirante del PT a la alcald&iacute;a de Atoyac, en la Costa Grande del estado de Guerrero,&nbsp;<span style=\"font: inherit !important;color: inherit !important;margin: 0px !important;padding: 0px !important;border: none !important\">Alfredo Gonz&aacute;lez&nbsp;<\/span><span style=\"font: inherit !important;color: inherit !important;margin: 0px !important;padding: 0px !important;border: none !important\">D&iacute;az<\/span><span style=\"font: inherit !important;color: inherit !important;margin: 0px !important;padding: 0px !important;border: none !important\">, fue asesinado a balazos la tarde de este domingo,<\/span>&nbsp;inform&oacute; la Fiscal&iacute;a General del Estado (FGE).<\/p>\n<p>A trav&eacute;s de un comunicado,&nbsp;<strong>la FGE inform&oacute; que alrededor de las 3 de la tarde, cuando Gonz&aacute;lez D&iacute;az viajaba en un veh&iacute;culo<\/strong>&nbsp;sobre el bulevar Juan &Aacute;lvarez en la cabecera municipal de Atoyac,&nbsp;<span style=\"font: inherit !important;color: inherit !important;margin: 0px !important;padding: 0px !important;border: none !important;background-image: initial !important;background-position: initial !important;background-size: initial !important;background-repeat: initial !important;background-attachment: initial !important;background-color: #f1c40f\">fue asesinado por &#8220;arma de fuego&#8221; y se abri&oacute; una carpeta de investigaci&oacute;n por homicidio<\/span>.<\/p>\n<h3>Suman 20 los pol&iacute;ticos y candidatos asesinados en lo que va del proceso electoral<\/h3>\n<p>Durante los &uacute;ltimos 4 meses se ha reportado el homicidio de varios aspirantes o candidatos en diferentes partes del pa&iacute;s, sumando cifras a los &iacute;ndices de violencia del pa&iacute;s.<\/p>\n<h4>Diciembre 23<\/h4>\n<ul>\n<li style=\"margin: 0px;padding: 0px 0px 0px 10px;font-size: 18px;line-height: 21px\">Jaime Damaso Sol&iacute;s, aspirante a alcalde de Zitlala en Guerrero<\/li>\n<li style=\"margin: 10px 0px 0px;padding: 0px 0px 0px 10px;font-size: 18px;line-height: 21px\">Miguel &Aacute;ngel Cruz Robles, quien buscaba la candidatura a la Presidencia municipal de Villa del Carb&oacute;n en el Estado de M&eacute;xico por Morena.<\/li>\n<li style=\"margin: 10px 0px 0px;padding: 0px 0px 0px 10px;font-size: 18px;line-height: 21px\">Wilman Monje Morales, exalcalde del municipio de Guti&eacute;rrez Zamora, Veracruz, y aspirante a la diputaci&oacute;n local por MC<\/li>\n<li style=\"margin: 10px 0px 0px;padding: 0px 0px 0px 10px;font-size: 18px;line-height: 21px\">Alejandro Lanuza Hern&aacute;ndez, regidor panista de Salvatierra quien buscaba ser candidato a la Presidencia municipal<\/li>\n<li style=\"margin: 10px 0px 0px;padding: 0px 0px 0px 10px;font-size: 18px;line-height: 21px\">Javier Torres Barrera, excandidato del PAN a la alcald&iacute;a de Chiautla de Tapia en Puebla y buscaba la presidencia municipal<\/li>\n<li style=\"margin: 10px 0px 0px;padding: 0px 0px 0px 10px;font-size: 18px;line-height: 21px\">Dagoberto Garc&iacute;a, aspirante a la candidatura por la presidencia municipal de Maravat&iacute;o Rivera por Morena<\/li>\n<li style=\"margin: 10px 0px 0px;padding: 0px 0px 0px 10px;font-size: 18px;line-height: 21px\">Ricardo Taja Ram&iacute;rez, precandidato a la alcald&iacute;a de Acapulco, Guerrero por Morena. Fue asesinado en una pozoler&iacute;a en la zona Diamante de Acapulco.<\/li>\n<\/ul>\n<h4>Enero 24<\/h4>\n<ul>\n<li style=\"margin: 0px;padding: 0px 0px 0px 10px;font-size: 18px;line-height: 21px\"><strong>Jueves 4<\/strong>. Giovanni Lezama Barrera, secretario general del PAN en Morelos, fue asesinado a balazos en el interior de un gimnasio en el municipio de Cuautla, Morelos, donde fung&iacute;a como regidor y estaba perfilado para contender por una diputaci&oacute;n federal.<\/li>\n<li style=\"margin: 10px 0px 0px;padding: 0px 0px 0px 10px;font-size: 18px;line-height: 21px\"><strong>Viernes 5<\/strong>. David Rey Gonz&aacute;lez Moreno, aspirante a la presidencia municipal de Suchiate, Chiapas, por el Frente Amplio por M&eacute;xico. Fue asesinado cuando viajaba en una motocicleta en la zona lim&iacute;trofe con Guatemala.<\/li>\n<li style=\"margin: 10px 0px 0px;padding: 0px 0px 0px 10px;font-size: 18px;line-height: 21px\"><strong>Viernes 5<\/strong>. Sergio Hueso, aspirante a la candidatura de Movimiento Ciudadano (MC) a la alcald&iacute;a de Armer&iacute;a, Colima. Fue asesinado a balazos por varios sujetos.<\/li>\n<li style=\"margin: 10px 0px 0px;padding: 0px 0px 0px 10px;font-size: 18px;line-height: 21px\"><strong>Jueves 11<\/strong>. Miriam Nohem&iacute; R&iacute;os R&iacute;os, dirigente de Movimiento Ciudadano (MC) en el municipio de Jacona, Michoac&aacute;n. Fue asesinada a tiros en el municipio de Zamora cuando atend&iacute;a su puesto de gorras.<\/li>\n<li style=\"margin: 10px 0px 0px;padding: 0px 0px 0px 10px;font-size: 18px;line-height: 21px\"><strong>Mi&eacute;rcoles 24<\/strong>. Marcelino Ru&iacute;z Esteban, perredista exalcalde de Atlixtac, Guerrero aspiraba a ser el candidato del PRD a la alcald&iacute;a de Atlixtac. En el mismo ataque fue asesinada su esposa Guadalupe Guzm&aacute;n Cano, consejera estatal del sol azteca. Ambos fueron emboscados en la carretera federal Chilapa-Tlapa.<\/li>\n<li style=\"margin: 10px 0px 0px;padding: 0px 0px 0px 10px;font-size: 18px;line-height: 21px\"><strong>S&aacute;bado 27<\/strong>. Jos&eacute; Alejandro Naredo Garc&iacute;a, El dirigente del PRD en el municipio veracruzano de Cuitl&aacute;huac, fue asesinado a tiros en la calle.<\/li>\n<\/ul>\n<h4>Febrero 24<\/h4>\n<ul>\n<li style=\"margin: 0px;padding: 0px 0px 0px 10px;font-size: 18px;line-height: 21px\"><strong>Jueves 1<\/strong>. Jaime Vera, precandidato del PVEM a la alcald&iacute;a de Mascota, Jalisco, fue asesinado en el municipio de Zapopan.<\/li>\n<li style=\"margin: 10px 0px 0px;padding: 0px 0px 0px 10px;font-size: 18px;line-height: 21px\"><strong>Mi&eacute;rcoles 7<\/strong>. Juan P&eacute;rez Guardado, secretario de Desarrollo Social del municipio de Fresnillo, Zacatecas, fue asesinado. El hombre tambi&eacute;n era cu&ntilde;ado del senador Ricardo Monreal.<\/li>\n<li style=\"margin: 10px 0px 0px;padding: 0px 0px 0px 10px;font-size: 18px;line-height: 21px\"><strong>Mi&eacute;rcoles 7<\/strong>. El coordinador de Movimiento Ciudadano (MC) en Guerrero, Juli&aacute;n L&oacute;pez Galeana, fue privado de su libertad en la autopista del Sol, a la altura de Chilpancingo, Guerrero, junto con otros dos miembros del partido. Lo golpearon y despu&eacute;s fue liberado. Se&ntilde;alan &#8220;equivocaci&oacute;n&#8221; de los agresores.<\/li>\n<li style=\"margin: 10px 0px 0px;padding: 0px 0px 0px 10px;font-size: 18px;line-height: 21px\"><strong>S&aacute;bado 10<\/strong>. Yair Mart&iacute;n Romero Segura, precandidato a diputaci&oacute;n federal por Morena, en presunto ataque armado fue asesinado junto a su hermano en Ecatepec.<\/li>\n<li style=\"margin: 10px 0px 0px;padding: 0px 0px 0px 10px;font-size: 18px;line-height: 21px\"><strong>Lunes 26<\/strong>. Miguel &Aacute;ngel Zavala Reyes, precandidato de Morena a la alcald&iacute;a de Maravat&iacute;o, Michoac&aacute;n.<\/li>\n<\/ul>\n<p>Informaci&oacute;n de El informador<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asesinan a Alfredo Gonzalez Diaz, candidato del PT en Guerrero<\/p>\n","protected":false},"author":1,"featured_media":86658,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[179],"class_list":["post-86657","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-pt"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1709516807_Alfredo-Gonza\u0301lez-03032024-El-Sur-copia-1132x670.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/86657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=86657"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/86657\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/86658"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=86657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=86657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=86657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}