{"id":80858,"date":"2024-08-01T18:45:55","date_gmt":"2024-08-01T18:45:55","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2024\/08\/01\/britney-spears-tendra-su-propia-biopic-con-universal\/"},"modified":"2024-08-01T18:45:55","modified_gmt":"2024-08-01T18:45:55","slug":"britney-spears-tendra-su-propia-biopic-con-universal","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2024\/08\/01\/britney-spears-tendra-su-propia-biopic-con-universal\/","title":{"rendered":"Britney Spears tendra su propia biopic con Universal"},"content":{"rendered":"<p><em>The Woman in Me,<\/em>&nbsp;el libro de memorias de la cantante y estrella del pop Britney Spears, ser&aacute; llevado al cine por Universal en&nbsp;<strong><span style=\"text-decoration: underline\">formato &#8220;biopic&#8221; y ser&aacute; dirigido por el estadounidense Jon Chu<\/span><\/strong>, informan este jueves medios especializados.<\/p>\n<p>El proyecto llegar&aacute; a la gran pantalla luego de que los estudios Universal se hicieran con los derechos de las memorias publicadas por la int&eacute;rprete en 2023 y que&nbsp;<strong><span style=\"text-decoration: underline\">se convirtieran en un inmediato &eacute;xito de ventas, con m&aacute;s de 2.5 millones de copias vendidas solo en Estados Unidos.<\/span><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Chu, quien estuvo al frente de la exitosa &#8220;Crazy Rich Asians&#8221; (2018) y que estrenar&aacute; este a&ntilde;o la primera parte de la esperada adaptaci&oacute;n del musical &#8220;Wicked&#8221;,<strong style=\"font-weight: bold\"><span style=\"text-decoration: underline\"><span>&nbsp;<\/span>ser&aacute; quien se ponga detr&aacute;s de c&aacute;maras, mientras que Marc Platt correr&aacute; a cargo de la producci&oacute;n del futuro filme.&nbsp;<\/span><\/strong><\/p>\n<p>Con la adquisici&oacute;n de los derechos de estas memorias Universal apuesta sobre seguro, en especial despu&eacute;s del eco que desat&oacute; el libro al dar a conocer detalles reveladores,&nbsp;<strong>entre ellos que la ganadora del Grammy tuvo un aborto durante los a&ntilde;os en que sal&iacute;a con Justin Timberlake.&nbsp;<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>El audiolibro de esta publicaci&oacute;n, le&iacute;do por la actriz Michelle Williams, fue el m&aacute;s escuchado de 2023 en la plataforma Spotify y ostenta para el sello Simon &amp; Schuster el r&eacute;cord de ventas m&aacute;s r&aacute;pidas de su historia.&nbsp;<\/strong><\/p>\n<p><strong style=\"font-weight: bold\"><span style=\"text-decoration: underline\"><br \/><\/span><\/strong><\/p>\n<p class=\"st-inarticle-paragraph\">&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Britney Spears tendra su propia biopic con Universal<\/p>\n","protected":false},"author":1,"featured_media":80859,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[219],"tags":[335],"class_list":["post-80858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculos","tag-britney-spears"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1722563155_BritneySpears.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/80858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=80858"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/80858\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/80859"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=80858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=80858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=80858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}