{"id":8079,"date":"2014-06-23T14:26:03","date_gmt":"2014-06-23T14:26:03","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2014\/06\/23\/el-pri-bloquea-democracia-en-sonora-juan-valencia\/"},"modified":"2014-06-23T14:26:03","modified_gmt":"2014-06-23T14:26:03","slug":"el-pri-bloquea-democracia-en-sonora-juan-valencia","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2014\/06\/23\/el-pri-bloquea-democracia-en-sonora-juan-valencia\/","title":{"rendered":"El PRI bloquea democracia en Sonora: Juan Valencia"},"content":{"rendered":"<p>Por Redacci&oacute;n<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<\/p>\n<p style=\"margin-bottom: 0cm;line-height: 115%\" align=\"JUSTIFY\"><a name=\"_GoBack\"><\/a> <em><span style=\"font-family: Calibri,serif\"><em><strong>Hermosillo, Sonora 23 de junio de 2014.- <\/strong><\/em><\/span><\/em><em><span style=\"font-family: Calibri,serif\"><em>El PRI sigue bloqueando el avance de la armonizaci&oacute;n de la Reforma Pol&iacute;tica electoral en Sonora, pues no le conviene<\/em><\/span><\/em><em><\/em><em><span style=\"font-family: Calibri,serif\"><em>para sus intereses con miras a 2015, donde har&aacute; todo lo posible para regresar al Estado al pasado y no desea que los sonorenses tengan m&aacute;s democracia, asegur&oacute; el Presidente del Comit&eacute; Directivo Estatal del PAN, Juan Valencia Durazo, quien exigi&oacute; al tricolor, sus diputados y alcaldes, m&aacute;s trabajo y menos simulaci&oacute;n.<\/em><\/span><\/em><\/p>\n<p>&nbsp;<\/p>\n<p style=\"margin-bottom: 0cm;line-height: 115%\" align=\"JUSTIFY\">&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"margin-bottom: 0cm;line-height: 115%\" align=\"JUSTIFY\"><em><span style=\"font-family: Calibri,serif\"><em>Dijo que en este tema <\/em><\/span><\/em><span style=\"font-family: Calibri,serif\">hay que ser muy claros y aunque la dirigencia del PRI se rasgue las vestiduras asegurando en desplegados y en entrevistas que ellos impulsan la democracia y la Reforma Pol&iacute;tica en el Estado, la realidad es que no se avanza en este tema, as&iacute; como en muchos otros, porque no existe la disposici&oacute;n de llegar a acuerdos y sus diputados se niegan a trabajar. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"margin-bottom: 0cm;line-height: 115%\" align=\"JUSTIFY\">&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"margin-bottom: 0cm;line-height: 115%\" align=\"JUSTIFY\"><span style=\"font-family: Calibri,serif\">Record&oacute; que la mejor prueba de esto es que el diputado pri&iacute;sta Jos&eacute; Abraham Mend&iacute;vil, quien es el responsable directo de conducir los trabajos para la armonizaci&oacute;n de la reforma pol&iacute;tico electoral, pr&aacute;cticamente dej&oacute; tirada su responsabilidad para irse de vacaciones.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"margin-bottom: 0cm;line-height: 115%\" align=\"JUSTIFY\">&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"margin-bottom: 0cm;line-height: 115%\" align=\"JUSTIFY\">&ldquo;<span style=\"font-family: Calibri,serif\">El se&ntilde;or dej&oacute; tirado el trabajo sin importarle que con su irresponsabilidad pusiera en riesgo de crisis pol&iacute;tica a Sonora en 2015, pues tenemos el proceso electoral pr&aacute;cticamente encima y aun no contamos con una legislaci&oacute;n armonizada a la federal, pero no s&oacute;lo esto, c&oacute;mo puede el PRI decir que les preocupa el tema cuando ni uno s&oacute;lo de sus alcaldes aval&oacute; esta armonizaci&oacute;n, en una muestra clara que la l&iacute;nea marcada por la Dirigencia pri&iacute;sta es bloquearla&rdquo;.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"margin-bottom: 0cm;line-height: 115%\" align=\"JUSTIFY\">&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"margin-bottom: 0cm;line-height: 115%\" align=\"JUSTIFY\"><span style=\"font-family: Calibri,serif\">Valencia Durazo resalt&oacute; que Acci&oacute;n Nacional es el principal promotor de esta Reforma, no s&oacute;lo en Sonora sino a nivel nacional, pues gracias a esta se logra plasmar en la Constituci&oacute;n, ideas y aspiraciones de la agenda panista de siempre.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"margin-bottom: 0cm;line-height: 115%\" align=\"JUSTIFY\">&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"margin-bottom: 0cm;line-height: 115%\" align=\"JUSTIFY\"><span style=\"font-family: Calibri,serif\">Dej&oacute; en claro que la reforma pol&iacute;tico Electoral es un gran avance para la democracia en M&eacute;xico, que <\/span><span style=\"font-family: Calibri,serif\">necesitaba entrar a una nueva etapa para que en todas las regiones se contara con los elementos y la certeza jur&iacute;dica de tener procesos electorales transparentes, y eso es precisamente lo que ha venido impulsando el PAN y que los liderazgos del PRI Sonora tratan de bloquear, aun en contra del mandato de su propio partido a nivel nacional y del Presidente Enrique Pe&ntilde;a Nieto, pues estos tambi&eacute;n avalan la nueva ley.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"margin-bottom: 0cm;line-height: 115%\" align=\"JUSTIFY\">&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dijo que mientras el tricolor dice impulsar la<br \/>\nReforma Pol&iacute;tica en el Estado, la realidad es<br \/>\nque la armonizaci&oacute;n con la ley federal no avanza<br \/>\nporque sus diputados se niegan a trabajar<\/p>\n","protected":false},"author":1,"featured_media":23883,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[242],"class_list":["post-8079","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-pan-sonora"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2014\/06\/1403558763_JVDJUNIO.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/8079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=8079"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/8079\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/23883"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=8079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=8079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=8079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}