{"id":7841,"date":"2014-06-16T09:02:49","date_gmt":"2014-06-16T09:02:49","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2014\/06\/16\/se-prepara-pt-internamente-para-el-proceso-electoral-del-2015\/"},"modified":"2014-06-16T09:02:49","modified_gmt":"2014-06-16T09:02:49","slug":"se-prepara-pt-internamente-para-el-proceso-electoral-del-2015","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2014\/06\/16\/se-prepara-pt-internamente-para-el-proceso-electoral-del-2015\/","title":{"rendered":"Se prepara PT internamente para el proceso electoral del 2015"},"content":{"rendered":"<p><strong>Por Redacci&oacute;n<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><span style=\"font-size: 14.0pt\">Hermosillo, Sonora.- El Partido del Trabajo realiz&oacute; este domingo la reuni&oacute;n estatal donde se analizan los diferentes escenarios que se pueden presentar en Sonora en el proceso electoral del 2015 y se prepara internamente con el fin de contar con la estructura electoral que representar&aacute; al partido en las casillas y de la defensa de los votos.<\/span><\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><span style=\"font-size: 14.0pt\">&nbsp;<\/span><\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><span style=\"font-size: 14.0pt\">En la reuni&oacute;n de car&aacute;cter estatal, a la cual asistieron los integrantes de la Comisi&oacute;n Ejecutiva Estatal del partido, los representantes de los municipios, regidores de los municipios, as&iacute; como el sector de mujeres, el Comisionado Pol&iacute;tico en Sonora, Jaime Moreno Berry, se&ntilde;al&oacute; que en este a&ntilde;o electoral se tienen que superar los problemas que se han presentado en los procesos anteriores.<\/span><\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><span style=\"font-size: 14.0pt\">&nbsp;<\/span><\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><span style=\"font-size: 14.0pt\">&ldquo;Hoy queremos conformar esos cuadros antes para cuando se llegue el momento el partido tenga a las personas para representarnos y defiendan los votos cuando se haga el conteo de los votos&rdquo;, explic&oacute; Moreno Berry.<\/span><\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><span style=\"font-size: 14.0pt\">&nbsp;<\/span><\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><span style=\"font-size: 14.0pt\">Respecto a la selecci&oacute;n de aspirantes a cargos de elecci&oacute;n popular para el pr&oacute;ximo proceso electoral del 2015, el Comisionado Pol&iacute;tico Nacional, manifest&oacute; que en el caso del candidato a gobernador, el PT se mantiene en la postura de que solo si es Ana Guevara el partido llevar&aacute; candidato, si no har&aacute; valer el voto &uacute;til con otro partido que considere m&aacute;s conveniente.<\/span><\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><span style=\"font-size: 14.0pt\">&nbsp;<\/span><\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><span style=\"font-size: 14.0pt\">&ldquo;El Partido del Trabajo se ha manifestado de que en el proceso electoral del 2015 llevar&aacute; un perfil ganador, con ambici&oacute;n de ganar para ayudar a los sonorenses, y ese perfil solo lo llena Ana Guevara, ya sea como candidata propia del PT o como candidata de las izquierdas&rdquo;, manifest&oacute;.<\/span><\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><span style=\"font-size: 14.0pt\">&nbsp;<\/span><\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><span style=\"font-size: 14.0pt\">Durante la reuni&oacute;n de abordaron los diferentes temas pendientes de la agenda pol&iacute;tica del partido donde cada uno de los representantes de los municipios, los regidores y el sector de mujeres expusieron el trabajo realizado durante estos primeros meses del a&ntilde;o en los diferentes municipios de Sonora de manera conjunta donde se destaca la labor realizada en la jornada de afiliaci&oacute;n y reafiliaci&oacute;n donde se registraron m&aacute;s de 13 mil sonorenses.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\">&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Partido del Trabajo realiz&oacute; este domingo la reuni&oacute;n estatal donde se analizan los diferentes escenarios que se pueden presentar en Sonora en el proceso electoral del 2015 <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[240],"class_list":["post-7841","post","type-post","status-publish","format-standard","hentry","category-estatal","tag-pt-sonora"],"jetpack_featured_media_url":"","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/7841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=7841"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/7841\/revisions"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=7841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=7841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=7841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}