{"id":7779,"date":"2014-06-13T16:47:24","date_gmt":"2014-06-13T16:47:24","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2014\/06\/13\/mantendremos-los-precios-bajos-todo-el-ao-javier-gndara-magaa-2\/"},"modified":"2014-06-13T16:47:24","modified_gmt":"2014-06-13T16:47:24","slug":"mantendremos-los-precios-bajos-todo-el-ao-javier-gndara-magaa-2","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2014\/06\/13\/mantendremos-los-precios-bajos-todo-el-ao-javier-gndara-magaa-2\/","title":{"rendered":"&quot;Mantendremos los precios bajos todo el a&ntilde;o&quot;: Javier G&aacute;ndara Maga&ntilde;a"},"content":{"rendered":"<p>Por Redacci&oacute;n<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><strong><span>Hermosillo, Sonora.-<\/span><\/strong><span> El Mercadito Ganfer, programa de apoyo en donde se pueden adquirir varios productos de la canasta b&aacute;sica a un menor precio, llegar&aacute; este s&aacute;bado 14 de junio a partir de las 8 de la ma&ntilde;ana a Magdalena, Nogales y Cajeme, inform&oacute; Javier G&aacute;ndara Maga&ntilde;a.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><span>El presidente de la Fundaci&oacute;n Ganfer, asegur&oacute; que las familias pueden estar seguras de contar con los precios bajos durante lo que resta del a&ntilde;o, gracias al apoyo de los proveedores y toda la gente que apoya este programa.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><span>&ldquo;Sabemos que el Mercadito Ganfer es una gran ayuda para la econom&iacute;a familiar, es por eso que mantendremos los precios bajos todo el a&ntilde;o, eso es un compromiso que tenemos primeramente como Fundaci&oacute;n y en lo personal como empresario socialmente responsable&rdquo;, coment&oacute; Javier G&aacute;ndara.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><span>Las ubicaciones del Mercadito Ganfer ser&aacute;n las siguientes:<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><span>Magdalena: Plaza San Mart&iacute;n, ubicada en las calles Ru&iacute;z Cortines, entre Dr. Plank y Pedro T&eacute;llez, frente al pante&oacute;n municipal, Col. San Mart&iacute;n.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><span>Nogales: Parque y cancha de basquetbol de la Col. Pueblo Nuevo, calles Municipio de Huatabampo y Municipio la Colorada, Col. Pueblo Nuevo.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><span>Cajeme: Esc. Primaria Jos&eacute; Mar&iacute;a Leyva, ubicada en calle Pascual Orozco entre Maximiliano R. L&oacute;pez y Alfonso Esparza, Col. Cajeme.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de la Fundaci&oacute;n Ganfer, asegur&oacute; que las familias pueden estar seguras de contar con los precios bajos durante lo que resta del a&ntilde;o, gracias al apoyo de los proveedores y toda la gente que apoya este programa.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[1679],"class_list":["post-7779","post","type-post","status-publish","format-standard","hentry","category-local","tag-fundacion-ganfer"],"jetpack_featured_media_url":"","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/7779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=7779"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/7779\/revisions"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=7779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=7779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=7779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}