{"id":77300,"date":"2024-12-30T19:36:36","date_gmt":"2024-12-30T19:36:36","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2024\/12\/30\/duplica-gobierno-del-estado-registro-de-sonorenses-en-2024\/"},"modified":"2024-12-30T19:36:36","modified_gmt":"2024-12-30T19:36:36","slug":"duplica-gobierno-del-estado-registro-de-sonorenses-en-2024","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2024\/12\/30\/duplica-gobierno-del-estado-registro-de-sonorenses-en-2024\/","title":{"rendered":"Duplica Gobierno del Estado registro de sonorenses en 2024"},"content":{"rendered":"<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px\" align=\"left\"><span style=\"color: #000000\">Hermosillo, Sonora; 30 de diciembre de 2024.- El Registro Civil de Sonora le dio identidad a un total de 31 mil 39 menores en el 2024, lo que representa un incremento del 133 por ciento con respecto al a&ntilde;o 2023, en el que se registraron a 13 mil 316 nuevos sonorenses.<\/span><\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px;text-align: center\">&nbsp;<\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px\" align=\"left\"><span style=\"color: #000000\">Mari&aacute;n Mart&iacute;nez Rodr&iacute;guez, titular de la dependencia, dio a conocer que fue octubre el mes en que fueron registrados m&aacute;s beb&eacute;s con un total de 3 mil 493 y el mes de julio fue cuando hubo una menor cantidad de este tipo de tr&aacute;mites.<\/span><\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px;text-align: center\">&nbsp;<\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px\" align=\"left\"><span style=\"color: #000000\">&ldquo;En el tema de registro oportuno cabe destacar que se unieron esfuerzos entre el gobierno federal y el estatal para hacer campa&ntilde;as en conjunto donde pudi&eacute;ramos acercar este servicio a las comunidades m&aacute;s remotas, logramos tener un gran registro de dobles nacionalidades y podemos estar satisfechos que en este 2024 logramos registrar y atender a las ni&ntilde;as y los ni&ntilde;os del estado que no hab&iacute;an tenido la oportunidad de haber sido registrados&rdquo;, extern&oacute;.<\/span><\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px;text-align: center\">&nbsp;<\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px\" align=\"left\"><span style=\"color: #000000\">En los &uacute;ltimos 10 a&ntilde;os se han registrado un total de 171 mil 865 menores y es el 2024 el a&ntilde;o en que se ha presentado una cifra m&aacute;s alta de registros y el 2020 fue cuando hubo menos registrados con 10 mil 643.<\/span><\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px;text-align: center\">&nbsp;<\/p>\n<p style=\"margin: 0px;padding: 0px;color: #606d78;font-family: Helvetica, Arial, sans-serif;font-size: 16px\" align=\"left\"><span style=\"color: #000000\">La funcionaria record&oacute; que el tr&aacute;mite es gratuito e inst&oacute; a los sonorenses a que acudan a cualquier oficial&iacute;a del Registro Civil con el aviso de nacimiento que emite la Secretar&iacute;a de Salud, la identificaci&oacute;n de los padres y dos testigos con copia de su INE para registrar a sus hijos.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Duplica Gobierno del Estado registro de sonorenses en 2024<\/p>\n","protected":false},"author":1,"featured_media":101041,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[2507],"class_list":["post-77300","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-registro-civil"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2024\/12\/1735612596_unnamed(1).jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/77300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=77300"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/77300\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/101041"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=77300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=77300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=77300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}