{"id":7650,"date":"2014-06-10T19:02:26","date_gmt":"2014-06-10T19:02:26","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2014\/06\/10\/tiene-pan-gobierno-quebrado-al-isssteson-pri\/"},"modified":"2014-06-10T19:02:26","modified_gmt":"2014-06-10T19:02:26","slug":"tiene-pan-gobierno-quebrado-al-isssteson-pri","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2014\/06\/10\/tiene-pan-gobierno-quebrado-al-isssteson-pri\/","title":{"rendered":"Tiene PAN Gobierno &quot;quebrado&quot; al  ISSSTESON: PRI"},"content":{"rendered":"<p>Por Redacci&oacute;n<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.299999237060547px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15.454545021057129px;text-align: justify\"><strong><span style=\"line-height: 18.399999618530273px;font-size: 12pt;font-family: Arial, sans-serif\">Hermosillo, Sonora, 10 de junio de 2014<\/span><\/strong><span style=\"line-height: 18.399999618530273px;font-size: 12pt;font-family: Arial, sans-serif\">.-&nbsp; De ser uno de los mejores servicios m&eacute;dicos,&nbsp; el ISSSTESON no s&oacute;lo perdi&oacute; una importante certificaci&oacute;n en su hospital Ignacio Ch&aacute;vez, en los &uacute;ltimos 4 a&ntilde;os representa una factura muy cara para la sociedad ante la inexperiencia de la autoridad estatal, que dej&oacute; crecer deudas y no aporta recursos para cubrir el rubro de pensiones y jubilaciones, expuso el dirigente estatal del PRI, Alfonso El&iacute;as Serrano.<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.299999237060547px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15.454545021057129px;text-align: justify\"><span style=\"line-height: 18.399999618530273px;font-size: 12pt;font-family: Arial, sans-serif\">El esfuerzo que realizaron los buenos gobiernos del PRI &ldquo;se fue a la basura&rdquo;, se&ntilde;al&oacute; en conferencia de prensa, el l&iacute;der priista acompa&ntilde;ado de la secretaria general del partido, Natalia Rivera, al hacer un comparativo, que refleja el deterioro originado por la corrupci&oacute;n del PAN Gobierno que hizo crecer la deuda &nbsp;en el &uacute;ltimo a&ntilde;o a 519 millones de pesos.<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.299999237060547px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15.454545021057129px;text-align: justify\"><span style=\"line-height: 18.399999618530273px;font-size: 12pt;font-family: Arial, sans-serif\">&ldquo;Independientemente de que ten&iacute;a que hacerlo o no, el gobierno estatal del PRI, le aport&oacute; al ISSSTESON 2 mil 163 millones de pesos, el Gobierno actual aport&oacute; cero. Es para la sociedad&nbsp; una factura muy cara por de la inexperiencia, la incapacidad, la impunidad,&nbsp; al corrupci&oacute;n y todos los adjetivos que le podamos poner a una p&eacute;sima actuaci&oacute;n del PAN Gobierno&rdquo;, puntualiz&oacute; El&iacute;as Serrano.<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.299999237060547px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15.454545021057129px;text-align: justify\"><span style=\"line-height: 18.399999618530273px;font-size: 12pt;font-family: Arial, sans-serif\">La situaci&oacute;n actual del ISSSTESON es de un servicio deficiente, necesita inversi&oacute;n en equipamiento, enfrenta una alta subrogaci&oacute;n, un ejercicio deficitario del presupuesto, a pesar de contar con recursos, recalc&oacute; El&iacute;as Serrano, quien detall&oacute; que la certificaci&oacute;n obtenida durante un buen Gobierno del PRI, se perdi&oacute; durante la actual administraci&oacute;n estatal.<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.299999237060547px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15.454545021057129px;text-align: justify\"><span style=\"line-height: 18.399999618530273px;font-size: 12pt;font-family: Arial, sans-serif\">&ldquo;Debemos seguir cuestionando al actual Gobierno porque, entre otras anomal&iacute;as, perdi&oacute; la certificaci&oacute;n obtenida por un gobierno priista, demostrando nuevamente que a la autoridad no le importa la salud de los sonorenses, Teresita Liz&aacute;rraga no ha querido o no la han dejado acudir al Congreso, pero ella tiene que ir a explicar, esos m&aacute;s de 3 mil millones de pesos que deb&iacute;an de estar en el fondo de pensiones en el ISSSTESON&rdquo;, se&ntilde;al&oacute; El&iacute;as Serrano.<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.299999237060547px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15.454545021057129px;text-align: justify\"><span style=\"line-height: 18.399999618530273px;font-size: 12pt;font-family: Arial, sans-serif\">En lo referente a la deuda, durante el 2009, representaba 84 millones 519 mil &nbsp;pesos, en los &uacute;ltimos 4 a&ntilde;os creci&oacute; hasta 519 millones, 675 mil pesos, en la partida &ldquo;Gastos de Orden Social&rdquo; el presupuesto original del 2012, era de 3 millones 344 mil 756 pesos y el ejercido fue de 9 millones 945 mil 657 dando un sobregiro de 6 millones 600 mil 901 pesos, mismos que forman parte de la demanda penal contra Teresa Liz&aacute;rraga y&nbsp; funcionarios. el abasto de medicamento fue del 98 por ciento, hoy dichos datos se desconocen, expuso el l&iacute;der del priismo sonorense.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>   Exige Alfonso El&iacute;as  dar la cara a pensionados y jubilados<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[268],"class_list":["post-7650","post","type-post","status-publish","format-standard","hentry","category-local","tag-pri-sonora"],"jetpack_featured_media_url":"","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/7650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=7650"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/7650\/revisions"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=7650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=7650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=7650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}