{"id":74129,"date":"2017-05-18T14:05:00","date_gmt":"2017-05-18T14:05:00","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2017\/05\/18\/imparten-platicas-sobre-la-verdad-del-cristal-a-los-seris\/"},"modified":"2017-05-18T14:05:00","modified_gmt":"2017-05-18T14:05:00","slug":"imparten-platicas-sobre-la-verdad-del-cristal-a-los-seris","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2017\/05\/18\/imparten-platicas-sobre-la-verdad-del-cristal-a-los-seris\/","title":{"rendered":"Imparten platicas sobre La verdad del cristal a los Seris"},"content":{"rendered":"<p>La Procuradur&iacute;a General de la Rep&uacute;blica (PGR), a trav&eacute;s de la Subprocuradur&iacute;a de Control Regional, Procedimientos Penales y Amparo SCRPPA, Delegaci&oacute;n Sonora, ofreci&oacute; una serie de pl&aacute;ticas informativas correspondiente al programa &#8220;Los Fiscales Visitan tu Escuela&#8221;, sobre prevenci&oacute;n de adicciones, delitos federales y de la campa&ntilde;a estatal &#8220;La Verdad de Cristal&#8221;, para ni&ntilde;os y padres de familia, en la localidad de Punta Chueca, Sonora.<\/p>\n<p>&nbsp;<\/p>\n<p>La pl&aacute;tica informativa, se llev&oacute; a efecto en la escuela primaria biling&uuml;e &#8220;Benito Ju&aacute;rez&#8221;, en la comunidad &eacute;tica &#8220;Seris&#8221; de Punta Chueca, en donde alrededor de 25 personas, alumnos, padres de familia y autoridades tradicionales, recibieron una amplia informaci&oacute;n respecto a &#8220;Prevenci&oacute;n de Adicciones&#8221;, &#8220;Prevenci&oacute;n de Delitos Federales&#8221; y sobre las consecuencias fisiol&oacute;gicas, psicol&oacute;gicas y legales sobre el consumo y posesi&oacute;n del &#8220;Cristal&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>Esta actividad estuvo a cargo de la Psic&oacute;loga Liliana Rodr&iacute;guez Talamante, enlace del Departamento de Prevenci&oacute;n al Delito y Servicios a la Comunidad, en donde participaron servidores p&uacute;blicos de la Instituci&oacute;n, el Lic. Jos&eacute; Luis Cardoza Cece&ntilde;a, Ministerio P&uacute;blico Federal, la Qu&iacute;mica Aurora Patricia Ordu&ntilde;a Pastrana y la agente de Investigaci&oacute;n Criminal, Gabriela Ruvalcaba Azuceno, mismos que continuar&aacute;n realizando pl&aacute;ticas en esta comunidad, as&iacute; como en otras escuelas de la entidad. &nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Imparten platicas sobre La verdad del cristal a los Seris<\/p>\n","protected":false},"author":1,"featured_media":76626,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[283],"class_list":["post-74129","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-ayuntamiento"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2017\/05\/1495141500_512959120.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/74129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=74129"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/74129\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/76626"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=74129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=74129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=74129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}