{"id":73950,"date":"2017-05-12T17:55:06","date_gmt":"2017-05-12T17:55:06","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2017\/05\/12\/robo-de-combustible-riesgo-de-seguridad-interior-meade\/"},"modified":"2017-05-12T17:55:06","modified_gmt":"2017-05-12T17:55:06","slug":"robo-de-combustible-riesgo-de-seguridad-interior-meade","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2017\/05\/12\/robo-de-combustible-riesgo-de-seguridad-interior-meade\/","title":{"rendered":"Robo de combustible, riesgo de seguridad interior: Meade"},"content":{"rendered":"<p style=\"margin: 1em 3em 1em 0px;padding: 0px;font-family: arial, helvetica, clean, sans-serif\"><span style=\"font-weight: bold\">CIUDAD DE M&Eacute;XICO<\/span>&nbsp;<span style=\"font-weight: bold\">(12\/MAY\/2017).-&nbsp;<\/span>&nbsp;El secretario de Hacienda, Jos&eacute; Antonio Meade Kuribre&ntilde;a, afirm&oacute; que el reto que nuestro pa&iacute;s enfrenta en materia de robo de combustibles es un riesgo de seguridad interior y expres&oacute; su compromiso y apoyo a las Fuerzas Armadas en el combate a este delito.<\/p>\n<p style=\"margin: 1em 3em 1em 0px;padding: 0px;font-family: arial, helvetica, clean, sans-serif\">Al asistir como invitado a la inauguraci&oacute;n de dos sucursales de Banjercito, en Tijuana, el titular de la SHCP asegur&oacute; que la sustracci&oacute;n de gasolinas es una provocaci&oacute;n de las redes criminales, que de manera inmoral y sin escr&uacute;pulos corrompen, manipulan, intimidan y amedrentan a comunidades enteras.<\/p>\n<p style=\"margin: 1em 3em 1em 0px;padding: 0px;font-family: arial, helvetica, clean, sans-serif\">Meade Kuribre&ntilde;a estuvo acompa&ntilde;ado por los secretarios de la Defensa Nacional, general Salvador Cienfuegos Zepeda, y de Marina, almirante Vidal Francisco Sober&oacute;n Sanz.<\/p>\n<p style=\"margin: 1em 3em 1em 0px;padding: 0px;font-family: arial, helvetica, clean, sans-serif\">&ldquo;Hoy la Secretar&iacute;a de Hacienda y Cr&eacute;dito P&uacute;blico, que es tambi&eacute;n una instancia de seguridad, quiere decirle a las Fuerzas Armadas que estamos con ellos, que compartimos su dolor frente a sus hermanos ca&iacute;dos&rdquo;, expres&oacute; Meade.<\/p>\n<p style=\"margin: 1em 3em 1em 0px;padding: 0px;font-family: arial, helvetica, clean, sans-serif\">&ldquo;En este espacio queremos comprometer a que en este esfuerzo nuestras Fuerzas Armadas nunca se sientan solas&rdquo;, afirm&oacute; el funcionario federal, quien record&oacute; que el presidente Enrique Pe&ntilde;a Nieto instruy&oacute; a conformar una estrategia integral para combatir esta actividad criminal.<\/p>\n<p style=\"margin: 1em 3em 1em 0px;padding: 0px;font-family: arial, helvetica, clean, sans-serif\">Indic&oacute; que, cuando vemos un fen&oacute;meno como el robo de combustibles, tenemos que reconocer fallas en los diferentes niveles de gobierno y en las distintas instancias.<\/p>\n<p style=\"margin: 1em 3em 1em 0px;padding: 0px;font-family: arial, helvetica, clean, sans-serif\">&ldquo;No basta con reconocer el dolor de nuestras Fuerzas Armadas, es necesario que esa expresi&oacute;n de solidaridad se acompa&ntilde;e de compromisos. Las palabras de condolencia suenan huecas si no se acompa&ntilde;an de un compromiso de acci&oacute;n&rdquo;, dijo el secretario de Hacienda.<\/p>\n<p style=\"margin: 1em 3em 1em 0px;padding: 0px;font-family: arial, helvetica, clean, sans-serif\">&ldquo;El que regatee en su apoyo a actualizar nuestro marco normativo es tambi&eacute;n c&oacute;mplice de quienes nos saquean. El que no cumple y quiere que las Fuerzas Armadas se pongan por delante, es igualmente c&oacute;mplice de quienes nos saquean&rdquo;, afirm&oacute;.<\/p>\n<p style=\"margin: 1em 3em 1em 0px;padding: 0px;font-family: arial, helvetica, clean, sans-serif\">Por ello pidi&oacute; que otros actores hagan lo propio y est&eacute;n a la altura del reto que esto implica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Robo de combustible, riesgo de seguridad interior: Meade<\/p>\n","protected":false},"author":1,"featured_media":76454,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[5598],"class_list":["post-73950","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-meade"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2017\/05\/1494636906_9-760x400.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/73950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=73950"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/73950\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/76454"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=73950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=73950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=73950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}