{"id":73469,"date":"2017-04-20T09:38:54","date_gmt":"2017-04-20T09:38:54","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2017\/04\/20\/realizan-conferencia-retos-del-sistema-estatal-anticorrupcion\/"},"modified":"2017-04-20T09:38:54","modified_gmt":"2017-04-20T09:38:54","slug":"realizan-conferencia-retos-del-sistema-estatal-anticorrupcion","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2017\/04\/20\/realizan-conferencia-retos-del-sistema-estatal-anticorrupcion\/","title":{"rendered":"Realizan conferencia Retos del Sistema Estatal Anticorrupcion"},"content":{"rendered":"<p>Es necesario el rescate de los valores democr&aacute;ticos de la Rep&uacute;blica y la participaci&oacute;n social, destac&oacute; Jos&eacute; Octavio L&oacute;pez Presa, integrante del Comit&eacute; de Participaci&oacute;n Ciudadana del Sistema Nacional Anticorrupci&oacute;n, durante la presentaci&oacute;n de la conferencia &ldquo;El Sistema Estatal Anticorrupci&oacute;n&rdquo;.<\/p>\n<p>&nbsp;<\/p>\n<p>El diputado Mois&eacute;s G&oacute;mez Reyna, presidente del Congreso del Estado, dio la bienvenida a los asistentes, entre quienes se encontraban los diputados Jes&uacute;s Epifanio Salido Pavlovich y Ferm&iacute;n Trujillo Fuentes, coordinadores de los grupos parlamentarios del PRI y PANAL, respectivamente, as&iacute; como integrantes de la Comisi&oacute;n Anticorrupci&oacute;n y de la LXI Legislatura.<\/p>\n<p>&nbsp;<\/p>\n<p>G&oacute;mez Reyna destac&oacute; que la conferencia es parte de un ciclo de eventos que se decidi&oacute; implementar en el Congreso, en donde adem&aacute;s de consultar a la sociedad civil, se realiza a la par una conjugaci&oacute;n con expertos, analistas y acad&eacute;micos, con el fin de contar con todas las voces al momento de tomar decisiones de peso a favor de la ciudadan&iacute;a.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;En un sistema pol&iacute;tico que tiene una serie de complicaciones, estertores o complejidades, no s&oacute;lo se conjuga la primera visi&oacute;n de querer hacer las cosas o tener el inter&eacute;s de hacer las cosas, sino que tiene que contar con la suma del conocimiento para ver c&oacute;mo se hace; uno de los esp&iacute;ritus fundamentales del Sistema Nacional Anticorrupci&oacute;n es que el Consejo de Participaci&oacute;n Ciudadana tenga esta conjugaci&oacute;n, el de tener la aut&eacute;ntica visi&oacute;n y pulso de lo que la gente y la sociedad est&aacute; buscando&rdquo;, expres&oacute; G&oacute;mez Reyna.<\/p>\n<p>&nbsp;<\/p>\n<p>El expositor Jos&eacute; Octavio L&oacute;pez Presa subray&oacute; que la importancia de impulsar tanto el Sistema Nacional Anticorrupci&oacute;n como los estatales, es para evitar existan corruptos a futuro, y resalt&oacute; la importancia de aliarse los medios de comunicaci&oacute;n, sociedad civil y servidores p&uacute;blicos, conjugar visiones a la vez de lanzar un llamado a la sociedad a no perder la fuerza de la denuncia.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;La manera de c&oacute;mo reconstruir un sistema efectivo de denuncias es a trav&eacute;s de la sociedad civil, no es s&oacute;lo cuesti&oacute;n de sistemas de c&oacute;mputo, sino de confianza; adem&aacute;s de esto lo m&aacute;s importante del sistema anticorrupci&oacute;n es que las personas que lleguen a los puestos lleguen por m&eacute;rito personal, por concursos p&uacute;blicos, abiertos y profesionales, y no por &ldquo;dedazo&rdquo;; si logramos que esta mentalidad se instale, poco a poco iremos cambiando&rdquo;, asegur&oacute;.<\/p>\n<p>&nbsp;<\/p>\n<p>Durante la conferencia en donde intercambi&oacute; varios puntos de vista sobre el tema con acad&eacute;micos, estudiantes, expertos y legisladores, lo acompa&ntilde;aron en el pres&iacute;dium Leticia Cuesta, directora de Sonora Ciudadana; Soledad Durazo, acad&eacute;mica y comunicadora; Marco Paz Pellat, representante de la sociedad civil; Mirtha Alvarado, presidenta de CANACO; y Marcelo Meouchi, presidente de Coparmex.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Realizan conferencia Retos del Sistema Estatal Anticorrupcion<\/p>\n","protected":false},"author":1,"featured_media":75981,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[298],"class_list":["post-73469","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-congreso"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2017\/04\/1492706334_2.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/73469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=73469"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/73469\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/75981"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=73469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=73469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=73469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}