{"id":73120,"date":"2017-04-04T17:59:24","date_gmt":"2017-04-04T17:59:24","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2017\/04\/04\/el-mariscal-de-campo-tony-romo-pone-fin-a-su-carrera-en-la-nfl\/"},"modified":"2017-04-04T17:59:24","modified_gmt":"2017-04-04T17:59:24","slug":"el-mariscal-de-campo-tony-romo-pone-fin-a-su-carrera-en-la-nfl","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2017\/04\/04\/el-mariscal-de-campo-tony-romo-pone-fin-a-su-carrera-en-la-nfl\/","title":{"rendered":"El mariscal de campo Tony Romo pone fin a su carrera en la NFL"},"content":{"rendered":"<p>El mariscal de campo de los Dallas Cowboys, Tony Romo, pondr&aacute; fin a su carrera en el f&uacute;tbol americano y se convertir&aacute; en analista de televisi&oacute;n, con los Cowboys planeando cortarlo este martes, informaron fuentes de la liga a ESPN.<\/p>\n<p>&nbsp;<\/p>\n<p>Romo despert&oacute; el inter&eacute;s de CBS, Fox y NBC y termin&oacute; aceptando la propuesta de CBS.<\/p>\n<p>&nbsp;<\/p>\n<p>Sin embargo la decisi&oacute;n de retirarse del f&uacute;tbol americano ya ha sido tomada. Su carrera como mariscal de campo de los Cowboys &#8211;y jugador de la NFL&#8211; terminar&aacute; oficialmente este martes.<\/p>\n<p>&nbsp;<\/p>\n<p>Se esperaba que Dallas designara a Romo como un corte posterior al 1&deg; de junio, amortizando el golpe contra el tope salarial de los Cowboys esta temporada. En lugar de impactar con 24.7 millones de d&oacute;lares en el 2017, Romo impactar&iacute;a con 10.7 millones y 8.9 millones en el 2018. Los Cowboys ganar&iacute;an 14 millones de espacio bajo el tope salarial, pero no estar&iacute;an disponibles hasta el 2 de junio.<\/p>\n<p>&nbsp;<\/p>\n<p>La decisi&oacute;n de Romo se debi&oacute; a su salud, indicaron fuentes cercanas a la situaci&oacute;n a ESPN. Romo, 1uien cumplir&aacute; 37 a&ntilde;os de edad el 21 de abril, cree que su familia y su salud son primordiales en este momento de su vida. Estuvo limitado a jugar en cinco partidos las &uacute;ltimas dos temporadas debido a lesiones de clav&iacute;cula y en la espalda, y sufri&oacute; una fractura por compresi&oacute;n en su espalda en agosto pasado que dej&oacute; el camino libre al novato Dak Prescott.<\/p>\n<p>&nbsp;<\/p>\n<p>Ahora tendr&aacute; m&aacute;s tiempo para pasar con su familia al tiempo que mantiene los lazos con el deporte que ama. Romo pas&oacute; las &uacute;ltimas semanas ponderando su decisi&oacute;n, dijeron las fuentes a&nbsp;<strong><em>ESPN<\/em><\/strong>.<\/p>\n<p>Romo ya ha informado al due&ntilde;o de los Cowboys, Jerry Jones, de su decisi&oacute;n de retirarse por ahora, indicaron las fuentes. Las cadenas de televisi&oacute;n que le han realizado ofertas tambi&eacute;n est&aacute;n al tanto.<\/p>\n<p>Un ejecutivo de la NFL, sin embargo, se&ntilde;al&oacute; a&nbsp;<strong><em>ESPN<\/em><\/strong>&nbsp;a trav&eacute;s de un mensaje de texto que &#8220;Romo ahora es el mariscal de campo de emergencia de todos los equipos en caso que el titular se lesione&#8221; y que esos equipos tendr&iacute;an que &#8220;pagarle para salir del &#8220;retiro&#8221;&#8221;.<\/p>\n<p>Su retiro tambi&eacute;n impactar&aacute; a los equipos de la NFL, ya que se esperaba que Romo tuviera un mercado s&oacute;lido. Pero con su transici&oacute;n a televisi&oacute;n, Romo ya no estar&aacute; a consideraci&oacute;n para los&nbsp;<a style=\"border: 0px;font-style: inherit;font-variant: inherit;font-weight: inherit;line-height: inherit;font-family: inherit;margin: 0px;padding: 0px;vertical-align: baseline;background: transparent;color: #0066cc;text-decoration: none\" href=\"http:\/\/www.espn.com.mx\/futbol-americano\/nfl\/equipo\/_\/nombre\/hou\/houston-texans\">Houston Texans<\/a>&nbsp;y&nbsp;<a style=\"border: 0px;font-style: inherit;font-variant: inherit;font-weight: inherit;line-height: inherit;font-family: inherit;margin: 0px;padding: 0px;vertical-align: baseline;background: transparent;color: #0066cc;text-decoration: none\" href=\"http:\/\/www.espn.com.mx\/futbol-americano\/nfl\/equipo\/_\/nombre\/den\/denver-broncos\">Denver Broncos<\/a>, a menos que inesperadamente escriba otro cap&iacute;tulo en su viaje en la NFL y vuelva de la cabina de transmisi&oacute;n al campo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mariscal de campo Tony Romo pone fin a su carrera en la NFL<\/p>\n","protected":false},"author":1,"featured_media":75638,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[188],"tags":[523],"class_list":["post-73120","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-tony-romo"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2017\/04\/1491353964_tony-romo.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/73120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=73120"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/73120\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/75638"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=73120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=73120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=73120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}