{"id":72571,"date":"2017-03-17T09:57:15","date_gmt":"2017-03-17T09:57:15","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2017\/03\/17\/capacita-dif-cajeme-a-escuelas-de-educacion-especial\/"},"modified":"2017-03-17T09:57:15","modified_gmt":"2017-03-17T09:57:15","slug":"capacita-dif-cajeme-a-escuelas-de-educacion-especial","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2017\/03\/17\/capacita-dif-cajeme-a-escuelas-de-educacion-especial\/","title":{"rendered":"Capacita DIF Cajeme a escuelas de educaciOn especial"},"content":{"rendered":"<p>Ciudad Obreg&oacute;n, Sonora, 17 de marzo de 2017.- Con el prop&oacute;sito de brindar un adiestramiento integral a docentes y padres de familia acerca de los trabajos que se realizan en DIF Cajeme, en la b&uacute;squeda de que los derechos de todos los ni&ntilde;os y j&oacute;venes sean respetados y reciban atenci&oacute;n integral, la Subprocuradur&iacute;a &nbsp;de la Defensa del Menor y la Familia imparti&oacute; una Capacitaci&oacute;n y Orientaci&oacute;n dirigida a padres de familia y maestros de educaci&oacute;n especial.<\/p>\n<p>&nbsp;<\/p>\n<p>En su intervenci&oacute;n el Secretario del Ayuntamiento, Armando Alcal&aacute; Alcaraz, expres&oacute; que para el Presidente Municipal Faustino F&eacute;lix Ch&aacute;vez es importante que toda la ni&ntilde;ez de Cajeme est&eacute; dentro del marco de la inclusi&oacute;n; por ello, el lograr la transversalidad entre ayuntamiento y los agentes de educaci&oacute;n especial es un gran logro para abrir los caminos tendientes a mejorar las condiciones de la calidad de vida de los alumnos de educaci&oacute;n especial.<\/p>\n<p>&nbsp;<\/p>\n<p>Abel Morales Fierro, Director de DIF Cajeme, manifest&oacute; que &ldquo;el ser incansables en la lucha por el bienestar de los ni&ntilde;os es parte de los planes de la primera dama, y el lograr que los derechos de los ni&ntilde;os y el acompa&ntilde;amiento de la inclusi&oacute;n sean integrales, es el trabajo que d&iacute;a a d&iacute;a se brinda en la Subprocuradur&iacute;a de la Defensa del Menor&rdquo;.<\/p>\n<p>&nbsp;<\/p>\n<p>El Supervisor de Zona 12 de Educaci&oacute;n Especial Federal, Dolores Vega Valdez, dijo que este tipo de capacitaciones son necesarias para los padres de familia y agentes de la educaci&oacute;n especial, ya que el ser inclusivos es parte de los par&aacute;metros que marcan los nuevos planes de estudio que encuadra el gobierno, municipal, estatal y federal.<\/p>\n<p>&nbsp;<\/p>\n<p>Durante la capacitaci&oacute;n se presentaron tres conferencias, siendo &eacute;stas las denominadas &ldquo;&iquest;Por qu&eacute; mi alumno muestra problemas de aprendizaje?&rdquo;, que estuvo a cargo de la pediatra m&aacute;ster en neuropsicolog&iacute;a del desarrollo, detecci&oacute;n e intervenci&oacute;n en da&ntilde;o perinatal, Luz Mar&iacute;a Romo Mart&iacute;n del Campo; &ldquo;Relaci&oacute;n padres o agentes educativos con los menores, desde el punto de vista legal y terap&eacute;utico&rdquo;, por personal de la Subprocuradur&iacute;a y &ldquo;Acompa&ntilde;amiento y supervisi&oacute;n escolar del alumno&rdquo;, por la doctora en docencia Alejandra Valenzuela Valenzuela.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Capacita DIF Cajeme a escuelas de educaciOn especial<\/p>\n","protected":false},"author":1,"featured_media":75094,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[177],"class_list":["post-72571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estatal","tag-cajeme"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2017\/03\/1489769835_Matrimonios-colectivos-rueda-de-prensa-3.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/72571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=72571"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/72571\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/75094"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=72571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=72571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=72571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}