{"id":72121,"date":"2017-03-09T08:34:44","date_gmt":"2017-03-09T08:34:44","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2017\/03\/09\/los-milagros-si-existen\/"},"modified":"2017-03-09T08:34:44","modified_gmt":"2017-03-09T08:34:44","slug":"los-milagros-si-existen","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2017\/03\/09\/los-milagros-si-existen\/","title":{"rendered":"Los Milagros, si existen"},"content":{"rendered":"<p><strong>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;VOZ SPORT<\/strong><\/p>\n<p><strong><br \/><\/strong><\/p>\n<p><strong>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Los Milagros, si existen<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Por Rafael Renteria<\/p>\n<p>&nbsp;<\/p>\n<p>No por nada el Barcelona es considerado el mejor equipo del mundo. Su regreso &eacute;pico ayer en su cancha, ante su gente, debe ser considerado como un milagro. Llegar a ese partido perdiendo 4-0 ante el Paris Saint Germain (PSG) y terminarlo 6 a 1, es algo que en muy raqu&iacute;ticas ocasiones se puede ver en la historia de ese deporte.<\/p>\n<p>Este juego de octavos de final de la Champions League pasara como uno de los episodios &eacute;picos del futbol, luego que se viviera un partido inusual, de esos que son especiales de principio a fin y que los amantes a ese deporte no se cansaran de verlo en varias ocasiones.<\/p>\n<p>Llegar a menos de 10 minutos del final y necesitar 3 goles, el Barcelona con sus grandes figuras como Messi, Neymar y Suarez, desplegaron esa magia para anotarlos y darle la vuelta al juego.<\/p>\n<p>Igualmente debemos reconocer al resto del equipo, siendo unos guerreros que jam&aacute;s se dejaron vencer y dejar en un gran rid&iacute;culo a un PSG, que inmediatamente nos hizo recordar los grandes fiascos que han vivido otros equipos en el deporte profesional: Los Halcones de Atlanta en la NFL y el Cruz Azul en el futbol mexicano.<\/p>\n<p>No dejo de pensar en ese trabajo que tuvieron que hacer todos los jugadores del Barcelona para intentar al menos hacer lo mas decorosa posible lo que se preve&iacute;a seria una eliminaci&oacute;n casi firmada en los octavos de final de la Champions, pero esa magia que el Barcelona sabe plasmar en su cancha y sum&aacute;ndole a la falta de ganas de triunfar de unos jugadores parisinos, fue una combinaci&oacute;n que resulto en un marcador final que llamar&aacute; por mucho tiempo la atenci&oacute;n del mundo entero.<\/p>\n<p>Que si al Barcelona lo ayudo el &aacute;rbitro, que si hubo jugadas que los beneficiaron, que si los jugadores del PSG no le pusieron ese extra que se requer&iacute;a en partidos de este tipo, en fin, excusas y dimes y diretes hay y habr&aacute; muchos, pero lo que no podemos negar, es que los hecho ayer 8 de marzo, D&iacute;a Internacional de la Mujer, es un episodio que perdura para siempre, adem&aacute;s que ser&aacute; recordado como una de las grandes remontadas &eacute;picas que se han gestado en el deporte profesional.<\/p>\n<p>No quiero ni imaginarme la verg&uuml;enza que deben sentir los jugadores del Paris Saint Germain y su cuerpo t&eacute;cnico. Ser&aacute; un gran lastre en sus vidas, en sus carreras deportivas el haber dejado ir de esa manera una gran, pero gran ventaja de 4 a cero. Por otra parte el ego y la confianza de los jugadores blaugranas deber&aacute;n estar por las nubes y con ello, se convierten de nuevo en el gran favorito para ganar la orejona.<\/p>\n<p>Por algo la Champions League es considerada y con meritos el mejor torneo de competencia de futbol en el mundo, incluso por encima del Mundial.<\/p>\n<p>Finalmente me pregunto ahora, que pensara el Real Madrid de este resultado de su archirrival y al cual ya daba por muerto en esta competencia?&#8230;&#8230;&#8230;&#8230;.<\/p>\n<p>&nbsp;<\/p>\n<p>Este d&iacute;a Tony Romo ser&aacute; despedido del equipo de los Vaqueros de Dallas.<\/p>\n<p>Despu&eacute;s de un a&ntilde;o, la historia de Romo con Dallas llegara a su fin, luego que perdiera su puesto titular ante el novato Dak Prescott. Con esta baja, los Vaqueros se estar&aacute;n ahorrando 14 millones de d&oacute;lares en esta temporada y muchos m&aacute;s dinero de otros a&ntilde;os que le quedaban de contrato.<\/p>\n<p>Romo se ira de Dallas con grandes n&uacute;meros que lo colocan como de los mejores en la historia de la organizaci&oacute;n: en 14 a&ntilde;os con el equipo obtuvo 34 mil 183 yardas y 248 anotaciones, n&uacute;meros que lo dejan como el mejor de la franquicia. A sus 36 a&ntilde;os ya era l&oacute;gico pensar en salir del equipo o al retiro.<\/p>\n<p>Ahora en la NFL se preguntan cu&aacute;l ser&aacute; el equipo que decidir&iacute;a firmarlo: las apuestas indican que ser&aacute;n los equipos de Broncos de Denver y los Texanos de Houston quienes podr&iacute;an contratar sus servicios una vez que sea declarado agente libre.<\/p>\n<p>La gran inc&oacute;gnita sobre Tony Romo, ser&aacute; saber si podr&aacute; regresar a ese nivel que tuvo con Dallas en sus mejores a&ntilde;os. Repito, tiene 36 a&ntilde;os y est&aacute; a pocos d&iacute;as de cumplir 37, sin duda sus mejores a&ntilde;os ya se fueron y es muy poco probable que pueda tener un regreso de grandes latitudes.<\/p>\n<p>Quien decida darle la oportunidad deber&aacute; estar consciente que este elemento es m&aacute;s propenso a lesiones que lo alejen de la cancha por largo tiempo, tal cual le paso al final de la temporada antepasada y la mitad de la pasada. Pero de estar sano y atinado le puede dar un gran empuje con quien se enfunde el jersey y aportarle una sabia veteran&iacute;a para alcanzar mejores resultados.<\/p>\n<p>Acaso habr&aacute; otros equipos interesados en sus servicios? Yo digo que s&iacute;. No descartemos a unos Caf&eacute;s de Cleveland, Jets de Nueva York y hasta unos Rams de los &Aacute;ngeles. Es m&aacute;s, hasta Raiders de Oakland y los Cardenales de Arizona podr&iacute;an darle una chanza de probarse con ellos y apoyar a un Dereck Carr y pelear por otra parte el puesto con otro veterano como Carson Palmer.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Twitter: rafarenteria11<\/p>\n<p>Facebook: Rafael Renteria R.<\/p>\n<p>Correo Electr&oacute;nico: renteria_rafael@hotmail.com&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los Milagros, si existen<\/p>\n","protected":false},"author":1,"featured_media":72122,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[190],"tags":[5504],"class_list":["post-72121","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-renteria","tag-columna-9-marzo-17"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1489073684_image58c06442e530d8.44415156.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/72121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=72121"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/72121\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/72122"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=72121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=72121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=72121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}