{"id":7027,"date":"2014-05-20T09:32:27","date_gmt":"2014-05-20T09:32:27","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2014\/05\/20\/pea-nieto-gana-con-reeleccin-de-madero-en-el-pan-jaime-moreno\/"},"modified":"2014-05-20T09:32:27","modified_gmt":"2014-05-20T09:32:27","slug":"pea-nieto-gana-con-reeleccin-de-madero-en-el-pan-jaime-moreno","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2014\/05\/20\/pea-nieto-gana-con-reeleccin-de-madero-en-el-pan-jaime-moreno\/","title":{"rendered":"Pe&ntilde;a Nieto gana con reelecci&oacute;n de Madero en el PAN: Jaime Moreno"},"content":{"rendered":"<p>Por Redacci&oacute;n<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><span style=\"font-size: 14.0pt\">Hermosillo, Sonora.- El Presidente de la Rep&uacute;blica Enrique Pe&ntilde;a Nieto result&oacute; el ganador de la elecci&oacute;n del PAN el fin de semana al resultar reelecto Gustavo Madero con quien se ha entendido muy bien para sacar adelante las reformas constitucionales, se&ntilde;al&oacute; Jaime Moreno Berry.<\/span><\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><span style=\"font-size: 14.0pt\">&nbsp;<\/span><\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><span style=\"font-size: 14.0pt\">El Comisionado Pol&iacute;tico Nacional del Partido del Trabajo en Sonora, manifest&oacute; que es sabido por los mexicanos y los sonorenses los acuerdos que hicieron ambos pol&iacute;ticos para que se aprobara la reforma energ&eacute;tica, una prioridad para el Gobierno de Pe&ntilde;a Nieto y con Gustavo Madero al frente del PAN le seguir&aacute; siendo &uacute;til, adem&aacute;s de las posibles negociaciones que se pudieron dar para salvar de las deudas algunos gobiernos panistas que terminan en el 2015. <\/span><\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><span style=\"font-size: 14.0pt\">&nbsp;<\/span><\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><span style=\"font-size: 14.0pt\">&ldquo;Ayer los panistas le dan una gran alegr&iacute;a al Presidente refrendando en la dirigencia del PAN a Madero, con quien le ha ido de maravilla a Pe&ntilde;a Nieto, y al quedar otra vez como Presidente del PAN no ha de haber otra persona m&aacute;s feliz en este pa&iacute;s que Enrique Pe&ntilde;a Nieto&rdquo;, expres&oacute; en conferencia de prensa.<\/span><\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><span style=\"font-size: 14.0pt\">&nbsp;<\/span><\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><span style=\"font-size: 14.0pt\">En el caso del proceso que se desarroll&oacute; en Sonora, dijo si bien es un trabajo interno del PAN, no se puede dejar de ver desde fuera la aportaci&oacute;n que hizo el gobierno del estado con el uso de recursos p&uacute;blicos en la elecci&oacute;n de Madero, un asunto donde no debe meter las manos el gobierno pero lo hizo.<\/span><\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><span style=\"font-size: 14.0pt\">&nbsp;<\/span><\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><span style=\"font-size: 14.0pt\">&ldquo;Definitivamente s&iacute;, es un asunto interno cien por ciento de este partido pero nosotros vimos como todo el aparato del Gobierno del estado estuvo involucrado en este proceso, y qui&eacute;rase o no, aunque se hable de una libertad para votar, hubo cargada para que Madero fuera reelecto Presidente. Lo vimos en los eventos que se hicieron de precampa&ntilde;a donde los funcionarios en horas de trabajo llegaban en veh&iacute;culos oficiales, en horas de trabajo a estos eventos. Vimos como en algunas partes de la capital del estado llegaban con camionetas llenas de despensas, hacer reuniones previas a la elecci&oacute;n, como si fuera una elecci&oacute;n constitucional&rdquo;, coment&oacute;.<\/span><\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><span style=\"font-size: 14.0pt\">&nbsp;<\/span><\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><span style=\"font-size: 14.0pt\">Coment&oacute; que este escenario se puede repetir en el proceso electoral del 2015, de que el Gobierno del estado meta las manos.<\/span><\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><span style=\"font-size: 14.0pt\">&nbsp;<\/span><\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><span style=\"font-size: 14.0pt\">&ldquo;S&iacute; se van a utilizar esos m&eacute;todos y otros peores&rdquo;, se&ntilde;al&oacute;.<\/span><\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><span style=\"font-size: 14.0pt\">&nbsp;<\/span><\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><strong><span style=\"font-size: 14.0pt\">NO A LAS PENSIONES VITALICIAS<\/span><\/strong><\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><span style=\"font-size: 14.0pt\">Respecto a las pensiones vitalicias propuestas para los Magistrados del Poder Judicial de la Federaci&oacute;n, en la conferencia de prensa semanal, el Comisionado Pol&iacute;tico del Partido del Trabajo, manifest&oacute; no estar de acuerdo.<\/span><\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><span style=\"font-size: 14.0pt\">&nbsp;<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNoSpacing\" style=\"text-align: justify\"><span style=\"font-size: 14.0pt\">&ldquo;Es justo que esos dos a&ntilde;os tengan un ingreso asegurado para el desempe&ntilde;o de su funci&oacute;n particular, y a partir de los dos a&ntilde;os se les suspenda esa pensi&oacute;n, para darles una pensi&oacute;n vitalicia es como decir que efectivamente si hubo corrupci&oacute;n, si hubo anomal&iacute;as en la elecci&oacute;n de Pe&ntilde;a Nieto, y Pe&ntilde;a Nieto les quiere pagar con una pensi&oacute;n vitalicia&rdquo;, finaliz&oacute;.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Comisionado Pol&iacute;tico Nacional del Partido del Trabajo en Sonora, manifest&oacute; que es sabido por los mexicanos y los sonorenses los acuerdos que hicieron ambos pol&iacute;ticos para que se aprobara la reforma energ&eacute;tica<\/p>\n","protected":false},"author":1,"featured_media":22900,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[240],"class_list":["post-7027","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-pt-sonora"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2014\/05\/1400603547_2.JPG","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/7027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=7027"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/7027\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/22900"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=7027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=7027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=7027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}