{"id":7024,"date":"2014-05-20T09:24:18","date_gmt":"2014-05-20T09:24:18","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2014\/05\/20\/el-xito-de-los-proyectos-se-debe-a-que-nacieron-de-sueos-javier-gndara\/"},"modified":"2014-05-20T09:24:18","modified_gmt":"2014-05-20T09:24:18","slug":"el-xito-de-los-proyectos-se-debe-a-que-nacieron-de-sueos-javier-gndara","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2014\/05\/20\/el-xito-de-los-proyectos-se-debe-a-que-nacieron-de-sueos-javier-gndara\/","title":{"rendered":"El &eacute;xito de los proyectos se debe a que nacieron de sue&ntilde;os&quot;: Javier G&aacute;ndara"},"content":{"rendered":"<p>Por Redacci&oacute;n<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><span>&ldquo;La respuesta al desarrollo econ&oacute;mico son los proyectos nacidos de un sue&ntilde;o&rdquo;, asegur&oacute; Javier G&aacute;ndara Maga&ntilde;a en la ceremonia de Premiaci&oacute;n del Programa Desaf&iacute;o Emprendedor Ganfer, el cual se dise&ntilde;&oacute; con &Aacute;ngel Ventures M&eacute;xico para premiar a los mejores proyectos innovadores de Sonora.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><span>El presidente de la Fundaci&oacute;n Ganfer, acompa&ntilde;ado de su esposa Marcela Fern&aacute;ndez, expres&oacute; que esta convocatoria lanzada oficialmente el 30 de enero del a&ntilde;o en curso, tuvo una gran recepci&oacute;n entre los j&oacute;venes sonorenses, pues se presentaron m&aacute;s de 3 mil solicitudes, de las cuales quedaron 260 proyectos de 19 municipios, para llegar a 20 finalistas y 7 ganadores, quienes representan lo m&aacute;s destacado del esp&iacute;ritu emprendedor en el Estado.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><span>&ldquo;Hemos detectado que en Sonora tenemos un gran talento, aqu&iacute; en nuestro Estado la cultura del emprendedurismo es importante inculcarla, sembrar esa semilla, particularmente que se vea que hay alternativas adicionales a lo que es exclusivamente ubicarse en una fuente de empleo&rdquo;, expres&oacute; G&aacute;ndara Maga&ntilde;a.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><span>Por su parte, Hern&aacute;n Fern&aacute;ndez Lamadrid, representante de &Aacute;ngel Ventures M&eacute;xico, expres&oacute; que con este Desaf&iacute;o Emprendedor se demostr&oacute; que en Sonora se cuenta con mucho talento y ganas de sobresalir, lo cual es una necesidad actual en M&eacute;xico, y que gracias a la iniciativa de fundaci&oacute;n Ganfer es el principio de grandes cambios no s&oacute;lo en el Estado, sino en el Pa&iacute;s.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><span>Los ganadores de Desaf&iacute;o Emprendedor Ganfer fueron:<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><span>1er lugar (200 mil pesos): &ldquo;Kimo&rdquo;, dispositivo electr&oacute;nico compacto, que conectado a la televisi&oacute;n la convierte en &ldquo;inteligente&rdquo;. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><span>2do. lugar (150 mil pesos): &ldquo;Thermodriver&rdquo;, dispositivo adaptable al boiler para ahorro de gas.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><span>3er. lugar (100 mil pesos): &ldquo;Rocket Journey&rdquo;, aplicaci&oacute;n m&oacute;vil para el acondicionamiento f&iacute;sico.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><span>4to. lugar (75 mil pesos): &ldquo;Ronda&rdquo;, aplicaci&oacute;n para tel&eacute;fonos celulares.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><span>5to lugar (50 mil pesos), triple empate para los proyectos: &ldquo;Soluciones integrales para personas con discapacidad&rdquo;; &ldquo;Solarnaps&rdquo;, que se enfoca a la producci&oacute;n de energ&iacute;a el&eacute;ctrica dom&eacute;stica; y &ldquo;Peico&rdquo;, que desarrolla&nbsp; una m&aacute;quina para producir de 900 a mil 200 ladrillos por hora con reducci&oacute;n de costos.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&quot;La respuesta al desarrollo econ&oacute;mico son los proyectos nacidos de un sue&ntilde;o&quot;, asegur&oacute; Javier G&aacute;ndara Maga&ntilde;a en la ceremonia de Premiaci&oacute;n del Programa Desaf&iacute;o Emprendedor Ganfer, el cual se dise&ntilde;&oacute; con &Aacute;ngel Ventures M&eacute;xico para premiar a los mejores <\/p>\n","protected":false},"author":1,"featured_media":22897,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[1679],"class_list":["post-7024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-fundacion-ganfer"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2014\/05\/1400603058_ganadoresdesafioGANFER.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/7024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=7024"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/7024\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/22897"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=7024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=7024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=7024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}