{"id":70184,"date":"2017-02-02T16:32:22","date_gmt":"2017-02-02T16:32:22","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2017\/02\/02\/realizaran-en-hermosillo-nueva-jornada-de-descacharre\/"},"modified":"2017-02-02T16:32:22","modified_gmt":"2017-02-02T16:32:22","slug":"realizaran-en-hermosillo-nueva-jornada-de-descacharre","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2017\/02\/02\/realizaran-en-hermosillo-nueva-jornada-de-descacharre\/","title":{"rendered":"Realizaran en Hermosillo nueva jornada de descacharre"},"content":{"rendered":"<p>Por Rafael Renteria<\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\"><span>Hace una invitaci&oacute;n la Direcci&oacute;n de Servicios P&uacute;blicos Municipales a la sociedad hermosillense para que participen este domingo 5 de febrero en una nueva jornada m&aacute;s de limpieza y descacharre.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>Su director Luis Fernando P&eacute;rez Pumarino, se&ntilde;alo que de nueva cuenta en diferentes sectores de la ciudad se instalaran desde las 8 de la ma&ntilde;ana hasta las 5 de la tarde los 10 centros de acopio tradicionales y ah&iacute; las personas puedan llevar sus cacharros, colchones, televisores, pilas y cualquier otro tipo de art&iacute;culo que no les sirva m&aacute;s.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><strong><span>&nbsp;&ldquo;Estamos invit&aacute;ndolos para que acudan y puedan deshacerse de todo aquello que no es de su utilidad, tener una mejor calidad de vida y contribuir con la reducci&oacute;n de los focos de infecci&oacute;n que origina el tener cacharros en sus patios, techos, y dem&aacute;s. Por eso los invitamos tambi&eacute;n a tener limpios los frentes de sus casas, eliminar maleza y que todos como vecinos puedan hacer lo mismo&rdquo;, puntualiz&oacute;.<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><strong><span>&nbsp;<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><span>Finalmente el director de Servicios P&uacute;blicos Municipales dio a conocer la ubicaci&oacute;n de los 10 centros de acopio que se instalaran de nueva cuenta este domingo 5 de febrero en la ciudad: Los estacionamientos de las tiendas Soriana, con excepci&oacute;n de la Plaza Sendero, adem&aacute;s en Musaro y Capomo en la Nuevo Hermosillo, en el Mariachi entre las calles Narbona y Alejandro Lacy, salida a la Carretera 26 y bulevar las Quintas y en el Progreso y Reyes.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Realizaran en Hermosillo nueva jornada de descacharre<\/p>\n","protected":false},"author":1,"featured_media":70185,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[548],"class_list":["post-70184","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-servicios-publicos"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1486078342_boletin-46.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/70184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=70184"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/70184\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/70185"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=70184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=70184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=70184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}