{"id":70152,"date":"2017-02-02T08:57:37","date_gmt":"2017-02-02T08:57:37","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2017\/02\/02\/firman-10-mil-por-un-sonora-sin-fuero\/"},"modified":"2017-02-02T08:57:37","modified_gmt":"2017-02-02T08:57:37","slug":"firman-10-mil-por-un-sonora-sin-fuero","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2017\/02\/02\/firman-10-mil-por-un-sonora-sin-fuero\/","title":{"rendered":"Firman 10 mil por un Sonora Sin Fuero"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><strong><span lang=\"ES-MX\">Hermosillo, Sonora. A 2 de febrero de 2017.- <\/span><\/strong><span lang=\"ES-MX\">Diez mil firmas de ciudadanos que apoyan eliminar el Fuero en Sonora, ser&aacute;n entregadas a la mesa Directiva del Congreso del Estado, as&iacute; como a los grupos parlamentarios en los pr&oacute;ximos d&iacute;as, anunci&oacute; el diputado Carlos Le&oacute;n Garc&iacute;a.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span lang=\"ES-MX\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span lang=\"ES-MX\">Ante medios de comunicaci&oacute;n y en compa&ntilde;&iacute;a de la coordinadora, Mar&iacute;a Dolores Del R&iacute;o S&aacute;nchez; el diputado Le&oacute;n Garc&iacute;a ratific&oacute; la agenda de Movimiento Ciudadano en el Congreso, que se resumen en impulsar las propuestas de combate a la corrupci&oacute;n y que ya han fueron presentadas, pero no han querido ser discutidas ni sometidas a votaci&oacute;n.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span lang=\"ES-MX\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span lang=\"ES-MX\">&ldquo;La agenda la marcamos desde el primer d&iacute;a en el Congreso del Estado y es en materia de combate a la corrupci&oacute;n y eliminar los privilegios a los pol&iacute;ticos, hemos sido muy congruentes. &iquest;Qu&eacute; sigue? Sigue seguir insistiendo en los temas que ya presentamos en el Congreso y estaremos empujando con muchos ciudadanos para que se discutan y se aprueben iniciativas como la ley anti nepotismo; la 3 de 3&rdquo;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span lang=\"ES-MX\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span lang=\"ES-MX\">&ldquo;Hoy la Ley de transparencia exige al funcionario p&uacute;blico que presente la 3de3 pero quiero decirles que no hay una ley que castigue si alguien no la presenta, es simulaci&oacute;n. Buscamos castigar el nepotismo para que los pol&iacute;ticos no abusen del apellido. Hemos insistido tambi&eacute;n en la ratificaci&oacute;n de mandato, qu&eacute; as&iacute; como los pone, el ciudadano los pueda quitar. Si un gobierno no sirve que se vaya, no hay por qu&eacute; aguantarlos&rdquo;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span lang=\"ES-MX\">&ldquo;La ley antimoches o antisoborno, para que el dinero p&uacute;blico sea utilizado en mejores servicios y obras, pero no que se entregue al empresario para que se le devuelva al pol&iacute;tico&rdquo; Expres&oacute; el diputado Carlos Le&oacute;n.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span lang=\"ES-MX\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span lang=\"ES-MX\">El legislador dijo que son temas que los ciudadanos han estado exigiendo y que el insistir&aacute; para que sean atendidas.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span lang=\"ES-MX\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span lang=\"ES-MX\">Por su parte la coordinadora estatal de Movimiento Ciudadano se&ntilde;al&oacute; que &ldquo;el discurso no es suficiente, la &uacute;nica manera de que se transite a evitar la corrupci&oacute;n es cambiando las reglas que han permitido la corrupci&oacute;n. Lejos de avanzar, cada vez sale un nuevo indicador que dice que vamos hacia atr&aacute;s&rdquo; En referencia al &Iacute;ndice de Percepci&oacute;n de Corrupci&oacute;n, elaborada por Transparencia Mexicana&nbsp; y Transparencia Internacional,&nbsp; donde M&eacute;xico cay&oacute; del lugar 95 al 123, al obtener 30 puntos en una escala donde 100 indica la mejor evaluaci&oacute;n. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span lang=\"ES-MX\">&nbsp;<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span lang=\"ES-MX\">A la reuni&oacute;n con los medios de comunicaci&oacute;n tambi&eacute;n asistieron, los regidores de Hermosillo, Rosa Elena Trujillo Llanes, y Jos&eacute; Pedro Reyes Gracia; el presidente y secretaria del Consejo Ciudadano, Francisco Uriarte y Rita Olivia Burgos, respectivamente y el coordinador municipal de Movimiento Ciudadano en Hermosillo, Jes&uacute;s Romo Pablos;&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>10 mil ciudadanos avalan con su firma la propuesta del diputado Carlos Leon Garcia de un Sonora Sin Fuero.<\/p>\n","protected":false},"author":1,"featured_media":70153,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[3924],"class_list":["post-70152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-mc"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1486051058_CarlosLeon.JPG","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/70152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=70152"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/70152\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/70153"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=70152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=70152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=70152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}