{"id":70138,"date":"2017-02-01T15:21:09","date_gmt":"2017-02-01T15:21:09","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2017\/02\/01\/la-innovacion-y-transferencia-de-tecnologia-seran-una-politica-de-lp-en-sonora\/"},"modified":"2017-02-01T15:21:09","modified_gmt":"2017-02-01T15:21:09","slug":"la-innovacion-y-transferencia-de-tecnologia-seran-una-politica-de-lp-en-sonora","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2017\/02\/01\/la-innovacion-y-transferencia-de-tecnologia-seran-una-politica-de-lp-en-sonora\/","title":{"rendered":"La innovacion y transferencia de tecnologia seran una politica de LP en Sonora"},"content":{"rendered":"<p>Ciudad de M&eacute;xico, febrero 1 de 2017.- &ldquo;En Sonora, el tema de las exportaciones es altamente relevante y m&aacute;s que preocupados, estamos ocupados&rdquo;, expres&oacute; el Secretario de Agricultura, Ganader&iacute;a, Recursos Hidr&aacute;ulicos, Pesca y Acuacultura, Julio C&eacute;sar Corona Valenzuela, en su participaci&oacute;n en el Foro EF Agro, organizado por el Financiero y Bloomberg.<\/p>\n<p>&nbsp;<\/p>\n<p>Afirm&oacute; que no es una casualidad lo ganado, a lo largo de los a&ntilde;os, en el tema de las exportaciones que se llevan a cabo hacia los Estados Unidos, pues es el resultado de mucho trabajo, y en tal sentido subray&oacute; que M&eacute;xico est&aacute; en una posici&oacute;n privilegiada, ante los retos que impone el Gobierno del vecino pa&iacute;s.<\/p>\n<p>&nbsp;<\/p>\n<p>Sonora, siendo un estado altamente exportador, asume su papel como una entidad complementaria, pues \u0093nos necesitan para poder alimentar al pueblo Norteamericano, y eso nos fortalece pues la sanidad e inocuidad acompa&ntilde;ada de la experiencia de los productores lo hacen posible&rdquo;.<\/p>\n<p>&nbsp;<\/p>\n<p>Somos, dijo el titular de la SAGARHPA, adem&aacute;s de un pa&iacute;s complementario, un Pa&iacute;s con instituciones que se har&aacute;n valer, somos un pa&iacute;s con organizaciones gremiales muy s&oacute;lidas, entre ellas el Consejo Nacional Agropecuario.<\/p>\n<p>&nbsp;<\/p>\n<p>La solidez comercial que existe entre ambos pa&iacute;ses, dijo, es muy dif&iacute;cil de romper, de ah&iacute; que las cosas deben verse a largo y corto plazo con pol&iacute;ticas correctas hacia el campo.<\/p>\n<p>&nbsp;<\/p>\n<p>Corona Valenzuela mencion&oacute; que M&eacute;xico y Sonora est&aacute;n en una situaci&oacute;n privilegiada, pues tienen altos potenciales de recursos naturales, somos vecinos de Estados Unidos , y lo &uacute;nico que marcan las proyecciones del nuevo gobierno Estadounidense, lejos de debilitar las relaciones comerciales, se tienen que fortalecer por el bien de todos.<\/p>\n<p>&nbsp;<\/p>\n<p>Coment&oacute; que la innovaci&oacute;n y la transferencia de tecnolog&iacute;a ser&aacute; realmente la direcci&oacute;n que se le dar&aacute; a un sector productivo como el nuestro.<\/p>\n<p>&nbsp;<\/p>\n<p>En el &uacute;ltimo a&ntilde;o, inform&oacute;, se han tecnificado en la entidad 14 mil hect&aacute;reas, cinco veces m&aacute;s que en los recientes cinco a&ntilde;os, y en el tema ganadero se ha trabajado en el mejoramiento gen&eacute;tico, todo ello ha generado una mayor confianza en el actual gobierno que encabeza Claudia Pavlovich Arellano.<\/p>\n<p>&nbsp;<\/p>\n<p>Corona Valenzuela destac&oacute; que, \u0093la instrucci&oacute;n de la Gobernadora ha sido clara, generar las condiciones para contar con un sector agropecuario m&aacute;s s&oacute;lido, que es la forma m&aacute;s segura de romper cualquier frontera&rdquo;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La innovacion y la transferencia de tecnologia seran una politica de largo plazo en el campo sonorense<\/p>\n","protected":false},"author":1,"featured_media":70139,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[871],"class_list":["post-70138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-sagarpa"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1485987669_402748437.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/70138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=70138"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/70138\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/70139"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=70138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=70138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=70138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}