{"id":68482,"date":"2017-01-07T11:31:56","date_gmt":"2017-01-07T11:31:56","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2017\/01\/07\/entrega-gobernadora-unidades-basicas-de-rehabilitacion-a-dif-de-21-municpios\/"},"modified":"2017-01-07T11:31:56","modified_gmt":"2017-01-07T11:31:56","slug":"entrega-gobernadora-unidades-basicas-de-rehabilitacion-a-dif-de-21-municpios","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2017\/01\/07\/entrega-gobernadora-unidades-basicas-de-rehabilitacion-a-dif-de-21-municpios\/","title":{"rendered":"Entrega Gobernadora Unidades Basicas de Rehabilitacion a DIF de 21 municpios"},"content":{"rendered":"<p>Hermosillo, Sonora, enero 07 del 2017.- Miles de sonorenses se beneficiar&aacute;n al recibir en sus municipios las terapias de rehabilitaci&oacute;n que requieren, sin tener que trasladarse a Hermosillo, destac&oacute; la Gobernadora Claudia Pavlovich Arellano, al entregar Unidades B&aacute;sicas de Rehabilitaci&oacute;n (UBR).<\/p>\n<p>&nbsp;<\/p>\n<p>Destac&oacute; la gran labor que las presidentas de los DIF municipales realizan, pues sin su apoyo y el trabajo en equipo con los tres niveles de gobierno, el Sistema DIF en Sonora no pudiera seguir gestionando los grandes beneficios que los ciudadanos requieren y merecen.<\/p>\n<p>&nbsp;<\/p>\n<p>Estamos entregando 21 Unidades de Rehabilitaci&oacute;n, la verdad me da mucho gusto poderlo hacer, es una gesti&oacute;n que hicieron el DIF Estatal ante el DIF Nacional y aqu&iacute; est&aacute; la muestra de que los hechos hablan m&aacute;s que muchas palabras y estas unidades s&eacute; que van a atender a muchas personas que lo requieren, a muchas personas que lo necesitan y que s&eacute; que van a hacer uso de ellas y ustedes tambi&eacute;n las van a cuidar, indic&oacute;.<\/p>\n<p>&nbsp;<\/p>\n<p>Los municipios beneficiados son Agua Prieta, Altar, Benito Ju&aacute;rez, Cajeme, Carb&oacute;, Cumpas, Empalme, Etchojoa, General Plutarco El&iacute;as Calles, Huachinera, Hu&eacute;pac, Huatabampo, Magdalena, N&aacute;cori Chico, Navojoa, Nogales, Puerto Pe&ntilde;asco, Ray&oacute;n, San Luis R&iacute;o Colorado, Santa Ana y Ures.<\/p>\n<p>&nbsp;<\/p>\n<p>La Gobernadora Claudia Pavlovich felicit&oacute; a los 21 municipios que han atendido a m&aacute;s de 26 mil personas y otorgado m&aacute;s de 86 mil terapias, y manifest&oacute; su seguridad de que har&aacute;n buen uso del equipo entregado en beneficio de miles de sonorenses.<\/p>\n<p>&nbsp;<\/p>\n<p>Margarita Ibarra de Torres, Presidenta del Sistema DIF Sonora, inform&oacute; que el recurso para las UBR fue donado por el DIF Nacional, despu&eacute;s de gestionar y presentar el trabajo que se desarrolla a trav&eacute;s de los DIF municipales en terapias y rehabilitaci&oacute;n a personas con alguna discapacidad.<\/p>\n<p>&nbsp;<\/p>\n<p>Este apoyo tiene que servir para incrementar la cantidad de terapias, la atenci&oacute;n que estamos dando a las personas con discapacidad, el hecho de que ustedes se vayan fortaleciendo en su municipio, evita ese gasto tan grande de estarlos trayendo a Hermosillo a recibir sus terapias, explic&oacute;.<\/p>\n<p>&nbsp;<\/p>\n<p>Entre el equipo que se entreg&oacute; est&aacute;n mesa de inclinaci&oacute;n para adulto e infantil, colchonetas grandes, barras paralelas de acero inoxidable, colchonetas terap&eacute;uticas, l&aacute;mpara de infrarojos, tina remolino grande, bicicleta estacionaria, entre otros.<\/p>\n<p>&nbsp;<\/p>\n<p>As&iacute; mismo la Gobernadora Pavlovich entreg&oacute; mobiliario y equipo al sector salud, para que los ciudadanos reciban una atenci&oacute;n digna y de calidad como merecen.<\/p>\n<p>&nbsp;<\/p>\n<p>Estuvieron presentes Gilberto Ungson Beltr&aacute;n, Secretario de Salud; Karina Z&aacute;rate F&eacute;lix, Directora General del Sistema DIF Sonora; M&oacute;nica Becerril Coppel, Coordinadora del Centro de Rehabilitaci&oacute;n y Educaci&oacute;n Especial; Elsa Ancheta Peralta, Coordinadora del Consejo de Integraci&oacute;n de Discapacidad; Mar&iacute;a de Lourdes Ru&iacute;z S&aacute;nchez de Silva, en representaci&oacute;n de las 21 presidentas de los DIF municipales y Kiki D&iacute;az Brown y Epifanio Salido Pavlovich, diputados locales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entrega Gobernadora Pavlovich Unidades Basicas de Rehabilitacion a DIF de 21 municipios<\/p>\n","protected":false},"author":1,"featured_media":68483,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[237],"class_list":["post-68482","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-cpa"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1483813916_claudiadifentre.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/68482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=68482"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/68482\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/68483"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=68482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=68482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=68482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}