{"id":67085,"date":"2016-12-06T10:03:36","date_gmt":"2016-12-06T10:03:36","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2016\/12\/06\/firman-convenio-en-beneficio-de-personas-con-discapacidad\/"},"modified":"2016-12-06T10:03:36","modified_gmt":"2016-12-06T10:03:36","slug":"firman-convenio-en-beneficio-de-personas-con-discapacidad","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2016\/12\/06\/firman-convenio-en-beneficio-de-personas-con-discapacidad\/","title":{"rendered":"FIRMAN CONVENIO EN BENEFICIO DE PERSONAS CON DISCAPACIDAD"},"content":{"rendered":"<p>Hermosillo, Sonora; Diciembre 06 de 2016.- Con la firma de un convenio de colaboraci&oacute;n y la inauguraci&oacute;n del Centro de Capacitaci&oacute;n OXXO; el Centro Ocupacional &ldquo;Manos a la Vida&rdquo;, de DIF Sonora, busca integrar a m&aacute;s j&oacute;venes con discapacidad intelectual al &aacute;mbito laboral.<\/p>\n<p>&nbsp;<\/p>\n<p>La Presidenta de DIF Sonora, Sra. Margarita Ibarra Platt, encabez&oacute; este acto donde record&oacute; que hace un a&ntilde;o se tuvo el primer encuentro con representantes de la Cadena Comercial y &ldquo;hoy ese sue&ntilde;o de dar m&aacute;s espacios para una inclusi&oacute;n laboral se nos brind&oacute; y es una realidad, de que nuestros muchachos que est&aacute;n en Manos a la Vida puedan integrarse laboralmente en los s&uacute;per OXXO&rdquo;.<\/p>\n<p>&nbsp;<\/p>\n<p>A la par del convenio, se inaugur&oacute; un espacio que simula una tienda donde se capacitar&aacute; a los estudiantes para que una vez dominadas las actividades puedan integrarse a la cadena. Ah&iacute; podr&aacute;n familiarizarse con los productos, precios, atenci&oacute;n al cliente y ventas. Hoy son 4 jovenes quienes laboran en tiendas OXXO y 8 quienes se encuentran en capacitaci&oacute;n para ello.<\/p>\n<div>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Jovenes sonorenses podran integrarse al ambito laboral.<\/p>\n","protected":false},"author":1,"featured_media":67086,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[404],"class_list":["post-67085","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-dif-sonora"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1481043816_IMG_4935.JPG","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/67085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=67085"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/67085\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/67086"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=67085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=67085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=67085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}