{"id":6688,"date":"2014-05-06T10:50:22","date_gmt":"2014-05-06T10:50:22","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2014\/05\/06\/reconoce-nba-a-kevin-durant-como-el-jugador-ms-valioso\/"},"modified":"2014-05-06T10:50:22","modified_gmt":"2014-05-06T10:50:22","slug":"reconoce-nba-a-kevin-durant-como-el-jugador-ms-valioso","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2014\/05\/06\/reconoce-nba-a-kevin-durant-como-el-jugador-ms-valioso\/","title":{"rendered":"Reconoce NBA a Kevin Durant como &#039;el jugador m&aacute;s valioso&#039;"},"content":{"rendered":"<p>Por Redacci&oacute;n<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong style=\"margin: 0px;padding: 0px;border: 0px;font-family: inherit;vertical-align: baseline\">Kevin Durant<\/strong>, de&nbsp;<strong style=\"margin: 0px;padding: 0px;border: 0px;font-family: inherit;vertical-align: baseline\">Oklahoma City<\/strong>, gan&oacute; este martes su primer premio al&nbsp;<strong style=\"margin: 0px;padding: 0px;border: 0px;font-family: inherit;vertical-align: baseline\">Jugador M&aacute;s Valioso<\/strong>&nbsp;de la<strong style=\"margin: 0px;padding: 0px;border: 0px;font-family: inherit;vertical-align: baseline\">&nbsp;NBA<\/strong>.<\/p>\n<p>El Thunder anunci&oacute; el galard&oacute;n antes de una conferencia de prensa por la tarde.<\/p>\n<p>Durant, un alero de m&aacute;s de dos metros de altura, gan&oacute; su&nbsp;<strong style=\"margin: 0px;padding: 0px;border: 0px;font-family: inherit;vertical-align: baseline\">cuarto t&iacute;tulo de m&aacute;ximo anotador&nbsp;<\/strong>en cinco a&ntilde;os con un promedio de 32 puntos por partido.<\/p>\n<p>Mientras que Russell Westbrook, tres veces elegido para el Juego de Estrellas, estuvo fuera de la alineaci&oacute;n despu&eacute;s de su m&aacute;s reciente cirug&iacute;a de rodilla, Durant promedi&oacute; 35 puntos y 6.3 asistencias para que el Thunder tuviera foja de 20-7 y se mantuviera en la &eacute;lite de la liga.<\/p>\n<p>La racha de 41 partidos consecutivos con al menos 25 puntos de Durant fue la tercera m&aacute;s larga en la historia de la NBA.<\/p>\n<p>Durant termin&oacute; segundo detr&aacute;s de<strong style=\"margin: 0px;padding: 0px;border: 0px;font-family: inherit;vertical-align: baseline\">&nbsp;LeBron James<\/strong>&nbsp;los dos a&ntilde;os anteriores. Este a&ntilde;o, Durant logr&oacute; 119 votos al primer puesto. James fue segundo y Blake Griffin tercero.<\/p>\n<div>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Durant termin&oacute; segundo detr&aacute;s de LeBron James los dos a&ntilde;os anteriores. Este a&ntilde;o, Durant logr&oacute; 119 votos al primer puesto <\/p>\n","protected":false},"author":1,"featured_media":22577,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[188],"tags":[1918],"class_list":["post-6688","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-kevin-durant"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2014\/05\/1399398622_KevinDurantScores.jpg.CROP.promovar-mediumlarge.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/6688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=6688"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/6688\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/22577"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=6688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=6688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=6688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}