{"id":6669,"date":"2014-05-06T08:58:09","date_gmt":"2014-05-06T08:58:09","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2014\/05\/06\/todo-mundo-tendr-que-acatarla-ley-ulises-cristpulos\/"},"modified":"2014-05-06T08:58:09","modified_gmt":"2014-05-06T08:58:09","slug":"todo-mundo-tendr-que-acatarla-ley-ulises-cristpulos","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2014\/05\/06\/todo-mundo-tendr-que-acatarla-ley-ulises-cristpulos\/","title":{"rendered":"Todo mundo tendr&aacute; que acatarla ley: Ulises Crist&oacute;pulos"},"content":{"rendered":"<p>Por Redacci&oacute;n<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px 0px 0.0001pt;font-family: Arial, Helvetica, sans-serif;font-size: 12px;text-align: justify\"><strong style=\"margin: 0px\">Al advertir que no habr&aacute; Gobiernos, empresas ni particulares exentos del cumplimiento de la ley, el Delegado de Semarnat en Sonora se&ntilde;al&oacute; que el 100 por ciento de las obras y proyectos est&aacute;n obligados a cumplir con la normatividad ambiental.<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px 0px 0.0001pt;font-family: Arial, Helvetica, sans-serif;font-size: 12px;text-align: justify\"><strong style=\"margin: 0px\">&nbsp;<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px 0px 0.0001pt;font-family: Arial, Helvetica, sans-serif;font-size: 12px;text-align: justify\"><strong style=\"margin: 0px\">&ldquo;Para el cumplimiento de la Ley no hay pretextos, no hay que generar ni caer en provocaciones, tampoco buscar culpables ni involucrar a personas con supuestos fines pol&iacute;ticos, simplemente hay que acatar a plenitud las disposiciones legales&rdquo;, manifest&oacute; Ulises Crist&oacute;pulos R&iacute;os.<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px 0px 0.0001pt;font-family: Arial, Helvetica, sans-serif;font-size: 12px;text-align: justify\"><strong style=\"margin: 0px\">&nbsp;<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px 0px 0.0001pt;font-family: Arial, Helvetica, sans-serif;font-size: 12px;text-align: justify\"><strong style=\"margin: 0px\">Reiter&oacute; que ante la ilegalidad se actuar&aacute; con todo el rigor de la ley, por eso la Delegaci&oacute;n de Profepa realiza operativos permanentes en minas, empresas camaron&iacute;colas e industrias instaladas en Sonora, entre otros.<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px 0px 0.0001pt;font-family: Arial, Helvetica, sans-serif;font-size: 12px;text-align: justify\"><strong style=\"margin: 0px\">&nbsp;<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px 0px 0.0001pt;font-family: Arial, Helvetica, sans-serif;font-size: 12px;text-align: justify\"><strong style=\"margin: 0px\">El funcionario federal asegur&oacute; que cuando se trata de aplicar la ley salen sobrando los apellidos y niveles de gobierno, porque todos, sin excepci&oacute;n, est&aacute;n obligados a cumplir con la normatividad ambiental.<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px 0px 0.0001pt;font-family: Arial, Helvetica, sans-serif;font-size: 12px;text-align: justify\"><strong style=\"margin: 0px\">&nbsp;<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px 0px 0.0001pt;font-family: Arial, Helvetica, sans-serif;font-size: 12px;text-align: justify\"><strong style=\"margin: 0px\">&ldquo;Quiero hacer un nuevo reconocimiento a la Profepa y a su Delegado, Jorge Carlos Flores Monge por mantener la vigilancia en todo el territorio&rdquo;, Coment&oacute; Ulises Crist&oacute;pulos.<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px 0px 0.0001pt;font-family: Arial, Helvetica, sans-serif;font-size: 12px;text-align: justify\"><strong style=\"margin: 0px\">&nbsp;<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px 0px 0.0001pt;font-family: Arial, Helvetica, sans-serif;font-size: 12px;text-align: justify\"><strong style=\"margin: 0px\">En estos operativos de inspecci&oacute;n y vigilancia, la Delegaci&oacute;n de la Procuradur&iacute;a Federal de Protecci&oacute;n al Ambiente ha clausura un total de 11 minas en los municipios de Carb&oacute;, Rosario Tesopaco, Caborca, La Colorada, San Javier, San Miguel de Horcasitas y Hermosillo. &nbsp;<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px 0px 0.0001pt;font-family: Arial, Helvetica, sans-serif;font-size: 12px;text-align: justify\"><strong style=\"margin: 0px\">&nbsp;<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px 0px 0.0001pt;font-family: Arial, Helvetica, sans-serif;font-size: 12px;text-align: justify\"><strong style=\"margin: 0px\">Adem&aacute;s se han supervisado granjas camaron&iacute;colas y en los &uacute;ltimos d&iacute;as se procedi&oacute; a la clausura de la obra denominada Ramal Norte por no cumplir con los permisos ambientales correspondientes.<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px 0px 0.0001pt;font-family: Arial, Helvetica, sans-serif;font-size: 12px;text-align: justify\"><strong style=\"margin: 0px\">&nbsp;<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px 0px 0.0001pt;font-family: Arial, Helvetica, sans-serif;font-size: 12px;text-align: justify\"><strong style=\"margin: 0px\">El Delegado de Semarnat en Sonora advirti&oacute; que el Gobierno Federal actuar&aacute; de manera formal y legalmente; &ldquo;No hay ni habr&aacute; acuerdos verbales de ning&uacute;n tipo, solo hay cumplimiento de la ley&rdquo;.<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px 0px 0.0001pt;font-family: Arial, Helvetica, sans-serif;font-size: 12px;text-align: justify\"><strong style=\"margin: 0px\">&nbsp;<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px 0px 0.0001pt;font-family: Arial, Helvetica, sans-serif;font-size: 12px;text-align: justify\"><strong style=\"margin: 0px\">En este sentido, Crist&oacute;pulos R&iacute;os se&ntilde;al&oacute; que la instrucci&oacute;n del presidente de la Rep&uacute;blica, Enrique Pe&ntilde;a Nieto y el secretario, Juan Jos&eacute; Guerra Abud ha sido ser muy escrupulosos en el cumplimiento de la ley.<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px 0px 0.0001pt;font-family: Arial, Helvetica, sans-serif;font-size: 12px;text-align: justify\"><strong style=\"margin: 0px\">&nbsp;<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px 0px 0.0001pt;font-family: Arial, Helvetica, sans-serif;font-size: 12px;text-align: justify\"><strong style=\"margin: 0px\">Por &uacute;ltimo dijo que la autoridad federal no bajar&aacute; la guardia en la vigilancia de obras y proyectos programados para la entidad, porque solo aplicando la ley se pueden garantizar beneficios para los ciudadanos.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&quot;Para el cumplimiento de la Ley no hay pretextos, no hay que generar ni caer en provocaciones, tampoco buscar culpables ni involucrar a personas con supuestos fines pol&iacute;ticos, simplemente hay que acatar a plenitud las disposiciones legales&quot;<\/p>\n","protected":false},"author":1,"featured_media":22558,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[187],"class_list":["post-6669","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-semarnat"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2014\/05\/1399391889_ULISES.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/6669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=6669"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/6669\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/22558"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=6669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=6669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=6669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}