{"id":6277,"date":"2014-04-23T17:13:38","date_gmt":"2014-04-23T17:13:38","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2014\/04\/23\/promueve-senador-ernesto-gndara-mejores-condiciones-para-menores-de-edad\/"},"modified":"2014-04-23T17:13:38","modified_gmt":"2014-04-23T17:13:38","slug":"promueve-senador-ernesto-gndara-mejores-condiciones-para-menores-de-edad","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2014\/04\/23\/promueve-senador-ernesto-gndara-mejores-condiciones-para-menores-de-edad\/","title":{"rendered":"Promueve senador Ernesto G&aacute;ndara mejores condiciones para menores de edad"},"content":{"rendered":"<p>Por Redacci&oacute;n<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"margin: 0px 0px 1.35em;line-height: 21.299999237060547px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\">Porque los ni&ntilde;os y adolescentes deben de estudiar y no dedicarse a trabajar,&nbsp;<strong>Ernesto el &ldquo;Borrego&rdquo; G&aacute;ndara<\/strong>&nbsp;destac&oacute; la reforma al Art&iacute;culo 123 constitucional, aprobada este lunes en el Senado, que aumenta la edad m&iacute;nima para trabajar de 14 a 15 a&ntilde;os, propuesta por el Presidente&nbsp;<strong>Enrique Pe&ntilde;a Nieto<\/strong>.<\/p>\n<p class=\"ecxMsoNormal\" style=\"margin: 0px 0px 1.35em;line-height: 21.299999237060547px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\">&ldquo;Los ni&ntilde;os, ni&ntilde;as y adolescentes deben estar en la aulas, no en las f&aacute;bricas; buscamos consolidar una norma para el bienestar de la ni&ntilde;ez mexicana, ya que con esta medida se estar&aacute;n garantizando sus derechos humanos (respecto a la explotaci&oacute;n infantil) &nbsp;y se les brinda la oportunidad de culminar su educaci&oacute;n b&aacute;sica&rdquo;, extern&oacute;&nbsp;<strong>G&aacute;ndara Camou<\/strong>&nbsp;al finalizar la sesi&oacute;n en que se aprob&oacute; la iniciativa.<\/p>\n<p class=\"ecxMsoNormal\" style=\"margin: 0px 0px 1.35em;line-height: 21.299999237060547px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\">En la Comisi&oacute;n del Trabajo y Previsi&oacute;n Social en el Senado, que preside&nbsp;<strong>G&aacute;ndara Camou<\/strong>, la iniciativa recibi&oacute; el apoyo de todos los senadores de todos los partidos pol&iacute;ticos que la integran, al igual que en la votaci&oacute;n en el pleno de este lunes.<\/p>\n<p class=\"ecxMsoNormal\" style=\"margin: 0px 0px 1.35em;line-height: 21.299999237060547px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\">Con esta acci&oacute;n, agreg&oacute; el&nbsp;<strong>Senador G&aacute;ndara<\/strong>, damos cumplimiento a los compromisos adquiridos por M&eacute;xico ante organismos internacionales, como la Organizaci&oacute;n Internacional del Trabajo (OIT), que buscan erradicar la explotaci&oacute;n infantil.<\/p>\n<p class=\"ecxMsoNormal\" style=\"margin: 0px 0px 1.35em;line-height: 21.299999237060547px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\"><strong>Ernesto G&aacute;ndara<\/strong>&nbsp;consider&oacute; que a un ni&ntilde;o o ni&ntilde;a que trabaja se le coarta su derecho a la educaci&oacute;n por la incompatibilidad de los horarios escolares con los laborales; y aun siendo estos compatibles, los menores al empezar a tener un ingreso optan por abandonar las aulas, trunc&aacute;ndose muchas veces su educaci&oacute;n b&aacute;sica.<\/p>\n<p class=\"ecxMsoNormal\" style=\"margin: 0px 0px 1.35em;line-height: 21.299999237060547px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\">La iniciativa aprobada contempla reformar la fracci&oacute;n III del Art&iacute;culo 123 de la Constituci&oacute;n Mexicana, para que en lugar de 14 a&ntilde;os, la edad m&iacute;nima para trabajar sea de 15 a&ntilde;os; el dictamen fue turnado a los congresos locales de todos los estados para su aprobaci&oacute;n, para que posteriormente pueda ser promulgado por el Ejecutivo Federal.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&quot;Los ni&ntilde;os, ni&ntilde;as y adolescentes deben estar en la aulas, no en las f&aacute;bricas; buscamos consolidar una norma para el bienestar de la ni&ntilde;ez mexicana, ya que con esta medida se estar&aacute;n garantizando sus derechos humanos: EGC<\/p>\n","protected":false},"author":1,"featured_media":22183,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[360],"class_list":["post-6277","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-borrego-gandara"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2014\/04\/1398298418_ernesto-gandara-senador-podium-e1365037312428.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/6277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=6277"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/6277\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/22183"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=6277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=6277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=6277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}