{"id":58055,"date":"2016-07-07T17:35:46","date_gmt":"2016-07-07T17:35:46","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2016\/07\/07\/dialoga-el-presidente-de-hermosillo-con-vecinos-de-la-colonia-pimentel\/"},"modified":"2016-07-07T17:35:46","modified_gmt":"2016-07-07T17:35:46","slug":"dialoga-el-presidente-de-hermosillo-con-vecinos-de-la-colonia-pimentel","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2016\/07\/07\/dialoga-el-presidente-de-hermosillo-con-vecinos-de-la-colonia-pimentel\/","title":{"rendered":"Dialoga el Presidente de Hermosillo con vecinos de la colonia Pimentel"},"content":{"rendered":"<p>Por Rafael Renteria<\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxmsonormal\" style=\"margin: 0cm 0cm 16.2pt;line-height: 16.85pt;background-image: initial;background-attachment: initial;background-size: initial;background-position: initial;background-repeat: initial\"><span style=\"font-size: 14.0pt;color: #444444\">Resalta el Presidente Municipal Manuel Ignacio Acosta Guti&eacute;rrez ante vecinos de la colonia Pimentel, que en su administraci&oacute;n se est&aacute;n tomando acciones para que toda la ciudad cuente con espacios seguros y de la misma manera sus habitantes est&eacute;n en ambientes adecuados para su sano esparcimiento.<\/span><\/p>\n<p class=\"ecxmsonormal\" style=\"margin: 0cm 0cm 16.2pt;line-height: 16.85pt;background-image: initial;background-attachment: initial;background-size: initial;background-position: initial;background-repeat: initial\"><span style=\"font-size: 14.0pt;color: #444444\">&nbsp;<\/span><\/p>\n<p class=\"ecxmsonormal\" style=\"margin: 0cm 0cm 16.2pt;line-height: 16.85pt;background-image: initial;background-attachment: initial;background-size: initial;background-position: initial;background-repeat: initial\"><span style=\"font-size: 14.0pt;color: #444444\">Acosta Guti&eacute;rrez, expres&oacute; al reunirse con vecinos de la colonia Pimentel, que desde el primer d&iacute;a que tomo las riendas de la ciudad, han estado trabajando de manera incansable en acciones de seguridad ya que era una de las principales &aacute;reas en donde los ciudadanos le hab&iacute;an manifestado esa preocupaci&oacute;n en campa&ntilde;a y por ello les reafirm&ograve; su compromiso de seguir adelante esa labor diaria con el &uacute;nico objetivo que todos los habitantes en la ciudad puedan tener seguridad en sus casas y colonias.<\/span><\/p>\n<p class=\"ecxmsonormal\" style=\"margin: 0cm 0cm 16.2pt;line-height: 16.85pt;background-image: initial;background-attachment: initial;background-size: initial;background-position: initial;background-repeat: initial\"><span style=\"font-size: 14.0pt;color: #444444\">&nbsp;<\/span><\/p>\n<p class=\"ecxmsonormal\" style=\"margin: 0cm 0cm 16.2pt;line-height: 16.85pt;background-image: initial;background-attachment: initial;background-size: initial;background-position: initial;background-repeat: initial\"><strong><span style=\"font-size: 14.0pt;color: #444444\">&nbsp;&ldquo;Primero quiero decirles que me doli&oacute; mucho y estoy indignado por lo que le paso a do&ntilde;a Licha que fue una tragedia; yo tambi&eacute;n estoy del lado de la gente, ustedes y todos deben saber que no estoy de lado de los delincuentes de ninguna manera y no vamos a permitir incluso como lo dijo el profesor que los delincuentes se anden paseando libres porque no son due&ntilde;os de las calles&rdquo;.<\/span><\/strong><\/p>\n<p class=\"ecxmsonormal\" style=\"margin: 0cm 0cm 16.2pt;line-height: 16.85pt;background-image: initial;background-attachment: initial;background-size: initial;background-position: initial;background-repeat: initial\"><strong><span style=\"font-size: 14.0pt;color: #444444\">&ldquo;Vamos a seguir con mano firme, caminando porque la realidad es que somos muchos m&aacute;s las familias buenas que los maleantes y la verdad es que nosotros estamos actuando con todo el rigor de la ley porque a m&iacute; no me interese que cuando el d&iacute;a de ma&ntilde;ana mis hijos sigan tambi&eacute;n pagando las consecuencias de la falta de decisiones y por eso es que estamos actuando del lado de la gente&rdquo;, asever&oacute;.<\/span><\/strong><\/p>\n<p class=\"ecxmsonormal\" style=\"margin: 0cm 0cm 16.2pt;line-height: 16.85pt;background-image: initial;background-attachment: initial;background-size: initial;background-position: initial;background-repeat: initial\"><span style=\"font-size: 14.0pt;color: #444444\">&nbsp;<\/span><\/p>\n<p class=\"ecxmsonormal\" style=\"margin: 0cm 0cm 16.2pt;line-height: 16.85pt;background-image: initial;background-attachment: initial;background-size: initial;background-position: initial;background-repeat: initial\"><span style=\"font-size: 14.0pt;color: #444444\">El presidente municipal adem&aacute;s acompa&ntilde;ado de parte de varios integrantes de su gabinete les recalc&oacute; a los habitantes de la Pimentel, que una de las acciones inmediatas en ese sector es trabajar en un esquema de seguridad que le regrese a esa colonia lo tradicional y sencilla que siempre hab&iacute;a sido y esto se har&iacute;a en memoria de do&ntilde;a Licha, quien perdiera la vida hace varios d&iacute;as.<\/span><\/p>\n<p class=\"ecxmsonormal\" style=\"margin: 0cm 0cm 16.2pt;line-height: 16.85pt;background-image: initial;background-attachment: initial;background-size: initial;background-position: initial;background-repeat: initial\"><span style=\"font-size: 14.0pt;color: #444444\">&nbsp;<\/span><\/p>\n<p class=\"ecxmsonormal\" style=\"margin: 0cm 0cm 16.2pt;line-height: 16.85pt;background-image: initial;background-attachment: initial;background-size: initial;background-position: initial;background-repeat: initial\"><span style=\"font-size: 14.0pt;color: #444444\">Finalmente Acosta Guti&eacute;rrez ratific&oacute; su compromiso como primera autoridad de la ciudad, a seguir trabajando en el esquema de seguridad no solo para esa colonia sino para el resto de Hermosillo, as&iacute; como tambi&eacute;n en reforzar a los cuerpos policiacos para que generen reacciones m&aacute;s inmediatas ante los reportes de los ciudadanos y combatir de una manera m&aacute;s f&eacute;rrea a la delincuencia.<\/span><\/p>\n<p class=\"ecxmsonormal\" style=\"margin: 0cm 0cm 16.2pt;line-height: 16.85pt;background-image: initial;background-attachment: initial;background-size: initial;background-position: initial;background-repeat: initial\"><span style=\"font-size: 14.0pt;color: #444444\">&nbsp;<\/span><\/p>\n<p class=\"ecxmsonormal\" style=\"margin: 0cm 0cm 16.2pt;line-height: 16.85pt;background-image: initial;background-attachment: initial;background-size: initial;background-position: initial;background-repeat: initial\"><strong><span style=\"font-size: 14.0pt;color: #444444\">&ldquo;Aunado a las acciones que como gobierno estamos tomando para ofrecerles seguridad a todos los ciudadanos, se debe trabajar tambi&eacute;n desde sus casas en el fortalecimiento de los valores, que nos ayuden a ser un blindaje familiar ante todas esas influencias negativas externas que nos puedan desestabilizar como lo es la delincuencia&rdquo;.<\/span><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxmsonormal\" style=\"margin: 0cm 0cm 16.2pt;line-height: 16.85pt;background-image: initial;background-attachment: initial;background-size: initial;background-position: initial;background-repeat: initial\"><strong><span style=\"font-size: 14.0pt;color: #444444\">&ldquo;Por eso de nueva cuenta les reiter&oacute; mi compromiso a no descansar por darle a Hermosillo la mayor seguridad posible, a estar m&aacute;s cercanos a ustedes y sobre todo a que en el caso de aquellos sitios donde se est&eacute;n presentando mayores problemas pues a corregir ese desorden para que no existan m&aacute;s conflictos sociales, que generen desestabilidad entre sus habitantes&rdquo;, culmin&oacute;.<\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dialoga el Presidente de Hermosillo con vecinos de la colonia Pimentel<\/p>\n","protected":false},"author":1,"featured_media":58056,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[2273],"class_list":["post-58055","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-maloro"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1467938146_nota52416b.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/58055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=58055"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/58055\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/58056"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=58055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=58055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=58055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}