{"id":56754,"date":"2016-06-20T09:32:33","date_gmt":"2016-06-20T09:32:33","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2016\/06\/20\/identifican-a-los-seis-fallecidos-en-nochixtlan\/"},"modified":"2016-06-20T09:32:33","modified_gmt":"2016-06-20T09:32:33","slug":"identifican-a-los-seis-fallecidos-en-nochixtlan","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2016\/06\/20\/identifican-a-los-seis-fallecidos-en-nochixtlan\/","title":{"rendered":"Identifican a los seis fallecidos en Nochixtlan"},"content":{"rendered":"<p>CIUDAD DE M&Eacute;XICO (20\/JUN\/2016).- El gobernador de Oaxaca, Gabino Cu&eacute; Monteagudo, inform&oacute; que ya fueron identificadas las seis personas que fallecieron ayer domingo durante los disturbios ocurridos en Nochixtl&aacute;n e indic&oacute; que ninguna de ellas es maestro.<\/p>\n<p>&nbsp;<\/p>\n<p>En entrevista en el noticieron &ldquo;Primero Noticias&rdquo;, el mandatario dijo que los seis fallecidos son Anselmo Cruz Aquino, de 33 a&ntilde;os y comerciante; Jes&uacute;s Cadena S&aacute;nchez, de 19 a&ntilde;os de edad y estudiante de secundaria; Iralv&iacute;n Jim&eacute;nez Santiago, de 29 a&ntilde;os y regidor de Salud; Oscar Nicol&aacute;s Santiago, de 22 a&ntilde;os y campesino; Omar Gonz&aacute;lez Santiago, de 22 a&ntilde;os y empleado; as&iacute; como Oscar Luna Aguilar y\/o Andr&eacute;s Aguilar, de 23 a&ntilde;os y comerciante.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;Ninguno es profesor, todos se dedican a actividades diversas, estaban en el bloqueo o en el tianguis de la zona&rdquo;, agreg&oacute; Cu&eacute;.<\/p>\n<p>&nbsp;<\/p>\n<p>El gobernador dijo que en los bloqueos no s&oacute;lo hab&iacute;a profesores, sino ciudadanos o personas que pertenecen a alguna organizaci&oacute;n social, como aquellos que participaron en la APPO en 2006.<\/p>\n<p>&nbsp;<\/p>\n<p>Tambi&eacute;n coment&oacute; que por estos hechos fueron detenidas 21 personas y dos m&aacute;s fueron arrestadas ayer en Salina Cruz, quienes estaban saqueando.<\/p>\n<p>&nbsp;<\/p>\n<p>Expuso que todos los detenidos se encuentran desde anoche rindiendo su declaraci&oacute;n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador de Oaxaca asegura que ninguno de ellos es maestro<\/p>\n","protected":false},"author":1,"featured_media":56755,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[181],"class_list":["post-56754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-cnte"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1466440353_44.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/56754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=56754"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/56754\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/56755"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=56754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=56754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=56754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}