{"id":55780,"date":"2016-06-07T06:32:26","date_gmt":"2016-06-07T06:32:26","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2016\/06\/07\/nombran-nuevo-titular-de-la-zona-norte-de-la-estacion-de-bomberos\/"},"modified":"2016-06-07T06:32:26","modified_gmt":"2016-06-07T06:32:26","slug":"nombran-nuevo-titular-de-la-zona-norte-de-la-estacion-de-bomberos","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2016\/06\/07\/nombran-nuevo-titular-de-la-zona-norte-de-la-estacion-de-bomberos\/","title":{"rendered":"Nombran nuevo titular de la Zona Norte de la Estacion de Bomberos"},"content":{"rendered":"<p>Por Redacci&ograve;n<\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.3px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\"><span style=\"line-height: 18.4px;font-size: 12pt\">Hermosillo, Sonora; Junio 07 de 2016.- A partir de la jubilaci&oacute;n del Oficial Mart&iacute;n Quijada Enr&iacute;quez, el pasado viernes 3 de junio, el Oficial Luis Francisco Vega C&aacute;&ntilde;ez, fue designado Jefe de la Zona Norte de la Estaci&oacute;n de Bomberos.<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.3px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\"><span style=\"line-height: 18.4px;font-size: 12pt\">Guillermo Moreno R&iacute;os, Director de la Unidad Municipal de Protecci&oacute;n Civil (UMPC) inform&oacute; que&nbsp; Vega Ca&ntilde;ez cuenta con 23 a&ntilde;os de experiencia en la corporaci&oacute;n, con especialidad en rescate acu&aacute;tico certificado, operaci&oacute;n de veh&iacute;culos de emergencia, primeros auxilios y rescate t&eacute;cnico; y su designaci&oacute;n se hizo cumpliendo con los protocolos que marca la Comisi&oacute;n de Honor, Selecci&oacute;n y Escalaf&oacute;n del Departamento de Bomberos.<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.3px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\"><span style=\"line-height: 18.4px;font-size: 12pt\">Dicha comisi&oacute;n est&aacute; integrada por Jorge Andr&eacute;s Suilo Orozco, Secretario del Ayuntamiento; H&eacute;ctor Cu&eacute;llar Rosas, Presidente del Patronato; Rodolfo Barroso Herrera y Cairo, en calidad de Secretario; y el Regidor Jos&eacute; Pedro Reyes Gracia, como Presidente de la misma, adem&aacute;s de &eacute;l como Director de la UMPC.<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.3px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\"><span style=\"line-height: 18.4px;font-size: 12pt\">Detall&oacute; que a nombre del Presidente Municipal, Manuel Ignacio Maloro Acosta le&nbsp; dio posesi&oacute;n del cargo a Vega C&aacute;&ntilde;ez y le agradeci&oacute; por aceptar tan noble encomienda, ofreci&eacute;ndole todo el apoyo necesario para el mejor desempe&ntilde;o de su trabajo y responsabilidad en beneficio de los hermosillenses.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tiene la responsabilidad el Oficial Luis Francisco Vega C&Atilde;&iexcl;&Atilde;&plusmn;ez<\/p>\n","protected":false},"author":1,"featured_media":55781,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[1730],"class_list":["post-55780","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-bomberos"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1465306346_nota41716.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/55780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=55780"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/55780\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/55781"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=55780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=55780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=55780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}