{"id":55451,"date":"2016-06-03T16:47:04","date_gmt":"2016-06-03T16:47:04","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2016\/06\/03\/la-promocion-del-estado-de-sonora-en-voz-de-los-compradores-jorge-vidal-ahumada\/"},"modified":"2016-06-03T16:47:04","modified_gmt":"2016-06-03T16:47:04","slug":"la-promocion-del-estado-de-sonora-en-voz-de-los-compradores-jorge-vidal-ahumada","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2016\/06\/03\/la-promocion-del-estado-de-sonora-en-voz-de-los-compradores-jorge-vidal-ahumada\/","title":{"rendered":"La promocion del estado de Sonora en voz de los compradores: Jorge Vidal Ahumada"},"content":{"rendered":"<p>Por Redacci&ograve;n<\/p>\n<p>&nbsp;<\/p>\n<p style=\"color: #222222;font-family: arial, sans-serif;font-size: 12.8px\" dir=\"ltr\">Hermosillo, Sonora, Junio 03 de 2016.-&nbsp; Con ventas por 38 millones de d&oacute;lares para productores sonorenses y de distintos estados del pa&iacute;s se clausur&oacute;&nbsp; el evento Rueda de Agronegocios, anunci&oacute; el Secretario de Econom&iacute;a, Jorge Vidal Ahumada.<\/p>\n<p style=\"color: #222222;font-family: arial, sans-serif;font-size: 12.8px\" dir=\"ltr\">En este evento, que&nbsp; realiz&oacute; PROM&Eacute;XICO en coordinaci&oacute;n con el Gobierno de Sonora, se concretaron 748 citas para empresarios&nbsp; nacionales que mostraron su producto a 37 compradores que viajaron de diversas partes del mundo para estar presentes en esta localidad.<\/p>\n<p style=\"color: #222222;font-family: arial, sans-serif;font-size: 12.8px\" dir=\"ltr\">De las 139 compa&ntilde;&iacute;as que participaron para dar a conocer sus productos, 55 empresas pertenecen a sonorenses que se vieron beneficiados con la generaci&oacute;n de negocios.<\/p>\n<p style=\"color: #222222;font-family: arial, sans-serif;font-size: 12.8px\" dir=\"ltr\">&ldquo;Exponer al mundo los productos de Sonora es el objetivo de realizar este evento en el estado, los compradores correr&aacute;n la voz del &eacute;xito de los productos sonorenses y de esta manera se dar&aacute;n a conocer m&aacute;s y m&aacute;s&#8221;, se&ntilde;al&oacute; Vidal Ahumada.<\/p>\n<p style=\"color: #222222;font-family: arial, sans-serif;font-size: 12.8px\" dir=\"ltr\">Por su parte, Gilberto Mac&iacute;as, Coordinador Regional Noroeste de PROM&Eacute;XICO, dijo que con la realizaci&oacute;n de este evento, Sonora se convierte en sede nacional, entidad proveedora y que busca potenciar negocios.<\/p>\n<p style=\"color: #222222;font-family: arial, sans-serif;font-size: 12.8px\" dir=\"ltr\">&ldquo;A mayores ventas se generar&aacute; m&aacute;s empleo y m&aacute;s mercado interno&rdquo;, puntualiz&oacute; el funcionario federal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La promocion del estado de Sonora en voz de los compradores: Jorge Vidal Ahumada<\/p>\n","protected":false},"author":1,"featured_media":55452,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[3904],"class_list":["post-55451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-jorge-vidal"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1464997624_011694.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/55451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=55451"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/55451\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/55452"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=55451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=55451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=55451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}