{"id":54031,"date":"2016-05-20T11:42:27","date_gmt":"2016-05-20T11:42:27","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2016\/05\/20\/presenta-tesoreria-de-ap-informe-de-la-cuenta-publica\/"},"modified":"2016-05-20T11:42:27","modified_gmt":"2016-05-20T11:42:27","slug":"presenta-tesoreria-de-ap-informe-de-la-cuenta-publica","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2016\/05\/20\/presenta-tesoreria-de-ap-informe-de-la-cuenta-publica\/","title":{"rendered":"Presenta Tesoreria de AP informe de la Cuenta Publica"},"content":{"rendered":"<p>Por Redacci&ograve;n<\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNoSpacing\"><span lang=\"ES-MX\">El informe del primer trimestre del 2016, correspondiente a la Cuenta P&uacute;blica de la administraci&oacute;n municipal, fue expuesto por la Tesorera, Leticia Arvayo Sol&iacute;s, en la Sesi&oacute;n Extraordinaria de Cabildo realizada este jueves, la Tesorera Municipal se&ntilde;al&oacute; que en esta administraci&oacute;n se obtuvo una buena respuesta en el pago de prediales.<br \/> <!--[if !supportLineBreakNewLine]--><br \/> <!--[endif]--><\/span><\/p>\n<p class=\"MsoNoSpacing\"><a name=\"_GoBack\"><\/a><span lang=\"ES-MX\">Arvayo Sol&iacute;s, agreg&oacute; que se aument&oacute; el porcentaje en recursos propios, para demostrar que se obtienen m&aacute;s recursos propios que anteriormente no se aplicaban, dicho informe ser&aacute; enviado al Congreso del Estado, como explicaci&oacute;n de la utilizaci&oacute;n de los recursos, donde deber&aacute; ser aprobado.<\/span><strong><\/strong><\/p>\n<p class=\"MsoNoSpacing\"><span lang=\"ES-MX\">&nbsp;<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNoSpacing\"><span lang=\"ES-MX\">&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presenta Tesoreria de AP informe de la Cuenta Publica<\/p>\n","protected":false},"author":1,"featured_media":54032,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[3882],"class_list":["post-54031","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estatal","tag-ap"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1463769747_aprobacion.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/54031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=54031"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/54031\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/54032"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=54031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=54031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=54031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}