{"id":52424,"date":"2016-05-02T17:03:01","date_gmt":"2016-05-02T17:03:01","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2016\/05\/02\/une-dif-de-ap-a-familia-separada-por-leyes-migratorias\/"},"modified":"2016-05-02T17:03:01","modified_gmt":"2016-05-02T17:03:01","slug":"une-dif-de-ap-a-familia-separada-por-leyes-migratorias","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2016\/05\/02\/une-dif-de-ap-a-familia-separada-por-leyes-migratorias\/","title":{"rendered":"Une DIF de AP a familia separada por leyes migratorias"},"content":{"rendered":"<p>Por Redacci&ograve;n<\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNoSpacing\"><span>Las leyes migratorias de Estados Unidos han separado familias, pero la voluntad de una madre que fue repatriada fue m&aacute;s fuerte que los muros que dividen a las dos fronteras, ya que a base de tenacidad y con ayuda de la Subprocuradur&iacute;a&nbsp; de la Defensa del Menor y la Familia del DIF Agua Prieta y el consulado de M&eacute;xico en Phoenix, lograron unir&nbsp; a una familia despu&eacute;s de ocho meces de separaci&oacute;n.<\/span><\/p>\n<p class=\"MsoNoSpacing\"><span>A petici&oacute;n de un juez, la Subprocuradur&iacute;a de la Defensa del Menor le realiz&oacute; varios ex&aacute;menes a la se&ntilde;ora Nidia Sara&iacute; B. L, para comprobar que estuviera en buen estado de salud y tener las condiciones necesarias para que la ni&ntilde;a de tan solo 12 a&ntilde;os de edad, fuera regresada&nbsp; a los tiernos&nbsp; brazos de su madre y sus corazones se volvieran a juntar.<\/span><\/p>\n<p class=\"MsoNoSpacing\"><span>Las pruebas salieron favorables, por lo que la reintegraci&oacute;n estaba a punto de suceder, pues el pasado 29 de abril&nbsp; Nidia Sara&iacute;, demostr&oacute; que con la ayuda de DIF y por el amor de una madre se rompen barreras y se traspasan muros.<\/span><\/p>\n<p class=\"MsoNoSpacing\"><span>Fue la tarde de este viernes cuando madre e hija volvieron a verse tras tres a&ntilde;os de s&oacute;lo cortas visitas.<\/span><\/p>\n<p class=\"MsoNoSpacing\"><span>Las l&aacute;grimas de tristeza se cambiaron por felicidad al topar sus ojos y prometerse nunca volverse a separarse.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNoSpacing\"><span>La madre agradeci&oacute; las gestiones que la Subprocuradur&iacute;a de la Defensa del Menor y la Familia y el DIF, Agua Prieta, realizaron para que esta uni&oacute;n pudiera ser una realidad, y que esta familia pudiera unirse para ya no separarse.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une DIF de AP a familia separada por leyes migratorias<\/p>\n","protected":false},"author":1,"featured_media":52425,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[3882],"class_list":["post-52424","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estatal","tag-ap"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1462233782_Reintegraci\u00f3nfamiliar2.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/52424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=52424"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/52424\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/52425"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=52424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=52424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=52424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}