{"id":52376,"date":"2016-05-02T10:40:26","date_gmt":"2016-05-02T10:40:26","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2016\/05\/02\/mantiene-temo-galindo-dialogo-abierto-tadeo-velasco\/"},"modified":"2016-05-02T10:40:26","modified_gmt":"2016-05-02T10:40:26","slug":"mantiene-temo-galindo-dialogo-abierto-tadeo-velasco","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2016\/05\/02\/mantiene-temo-galindo-dialogo-abierto-tadeo-velasco\/","title":{"rendered":"MANTIENE TEMO GALINDO DIALOGO ABIERTO: TADEO VELASCO"},"content":{"rendered":"<p>Por Redacci&ograve;n<\/p>\n<p>&nbsp;<\/p>\n<p style=\"margin: 0.75em 0px;padding: 0px;border: 0px;font-size: 16.0016px;line-height: 25.6026px;font-family: lemonde-journal-1, lemonde-journal-2, serif;vertical-align: baseline;color: #111111\">Nogales, Sonora.- El Gobierno de la Ciudad, que encabeza Temo Galindo Delgado, permanece en constante di&aacute;logo con todas las fuerzas obreras de la ciudad, inform&oacute; Luis Tadeo Velasco Fimbres, al finalizar el Desfile del Primero de Mayo.<\/p>\n<p style=\"margin: 0.75em 0px;padding: 0px;border: 0px;font-size: 16.0016px;line-height: 25.6026px;font-family: lemonde-journal-1, lemonde-journal-2, serif;vertical-align: baseline;color: #111111\">El Secretario del Ayuntamiento dijo que &ldquo;el de Temo Galindo es un Gobierno abierto y transparente como nunca se ha dado, es por eso que se mantiene el di&aacute;logo dando como resultado un desfile tranquilo y en armon&iacute;a&rdquo;.<\/p>\n<p style=\"margin: 0.75em 0px;padding: 0px;border: 0px;font-size: 16.0016px;line-height: 25.6026px;font-family: lemonde-journal-1, lemonde-journal-2, serif;vertical-align: baseline;color: #111111\">Afirm&oacute; que el Alcalde est&aacute; dispuesto a escuchar a la gente y a los trabajadores de la comuna para que se lleven en buenos t&eacute;rminos las negociaciones en torno al contrato colectivo de trabajo que anualmente se firma entre el municipio y la parte sindical.<\/p>\n<p style=\"margin: 0.75em 0px;padding: 0px;border: 0px;font-size: 16.0016px;line-height: 25.6026px;font-family: lemonde-journal-1, lemonde-journal-2, serif;vertical-align: baseline;color: #111111\">Dijo que en la primera quincena de Mayo, los empleados sindicalizados del Gobierno de la Ciudad, tendr&aacute;n un aumento del cuatro por ciento sobre sus salarios que por ley les corresponde y esto es resultado de las buenas estrategias que Temo Galindo ha implementado para ir saneando las finanzas del municipio.<\/p>\n<p style=\"margin: 0.75em 0px;padding: 0px;border: 0px;font-size: 16.0016px;line-height: 25.6026px;font-family: lemonde-journal-1, lemonde-journal-2, serif;vertical-align: baseline;color: #111111\">El Secretario del Ayuntamiento, agreg&oacute; que los pasados administradores de la ciudad, dejaron una enorme deuda al Sindicato, la cual poco a poco se ha venido solventando gracias a los buenos manejos de los fondos y de la excelente relaci&oacute;n que existe con la parte sindical.<\/p>\n<p style=\"margin: 0.75em 0px;padding: 0px;border: 0px;font-size: 16.0016px;line-height: 25.6026px;font-family: lemonde-journal-1, lemonde-journal-2, serif;vertical-align: baseline;color: #111111\">Asegur&oacute; que durante toda esta administraci&oacute;n, los nogalenses tendr&aacute;n un gobierno de acuerdos y de puertas abiertas para escuchar a la gente.<\/p>\n<p style=\"margin: 0.75em 0px;padding: 0px;border: 0px;font-size: 16.0016px;line-height: 25.6026px;font-family: lemonde-journal-1, lemonde-journal-2, serif;vertical-align: baseline;color: #111111\">Precis&oacute; que en el transcurso de la semana entrante, se tendr&aacute; una respuesta a los ex trabajadores de acuerdo a lo que se les ha planteado como indemnizaci&oacute;n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MANTIENE TEMO GALINDO DIALOGO ABIERTO: TADEO VELASCO <\/p>\n","protected":false},"author":1,"featured_media":52377,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[4191],"class_list":["post-52376","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estatal","tag-nogales"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1462210826_Tadeo.aumento.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/52376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=52376"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/52376\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/52377"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=52376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=52376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=52376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}