{"id":48080,"date":"2016-03-08T15:34:23","date_gmt":"2016-03-08T15:34:23","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2016\/03\/08\/expone-la-ctm-sonora-taller-sobre-liderazgo-y-desarrollo-integral-de-la-mujer\/"},"modified":"2016-03-08T15:34:23","modified_gmt":"2016-03-08T15:34:23","slug":"expone-la-ctm-sonora-taller-sobre-liderazgo-y-desarrollo-integral-de-la-mujer","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2016\/03\/08\/expone-la-ctm-sonora-taller-sobre-liderazgo-y-desarrollo-integral-de-la-mujer\/","title":{"rendered":"Expone la CTM Sonora taller sobre liderazgo y desarrollo integral de la mujer"},"content":{"rendered":"<p>Por Rafael Renter&iacute;a<\/p>\n<p>&nbsp;<\/p>\n<\/p>\n<p style=\"margin-bottom: 0cm;font-weight: normal\"><span style=\"font-family: Times New Roman,serif\"><span style=\"font-size: large\">Re&uacute;ne la CTM en Sonora a un grupo considerable de mujeres de diferentes empresas en la ciudad de Hermosillo para que formar&aacute;n parte del taller Liderazgo y Desarrollo Integral de la Mujer y esto como parte de la conmemoraci&oacute;n del D&iacute;a Internacional de la Mujer.<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"margin-bottom: 0cm;font-weight: normal\">&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"margin-bottom: 0cm;font-weight: normal\"><span style=\"font-family: Times New Roman,serif\"><span style=\"font-size: large\">Ana Patricia P&eacute;rez R&iacute;os, Medica con especializaci&oacute;n en sicolog&iacute;a organizacional para el manejo y la gesti&oacute;n del estr&eacute;s, se&ntilde;al&oacute; que ese taller sobre liderazgo y desarrollo integral de la mujer estaba enfocado para hacerles ver a las participantes como a trav&eacute;s de sus acciones diarias en sus mismas casas, &aacute;reas laborales y sociedad en general han aportado a lo largo de los a&ntilde;os por el engrandecimiento del pa&iacute;s.<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"margin-bottom: 0cm\">&ldquo;<span style=\"font-family: Times New Roman,serif\"><span style=\"font-size: large\"><strong>La mujer tiene mucho para aportar, la mujer a venido descubri&eacute;ndose ya que antes imitaba comportamientos y actitudes m&aacute;s de los varones pero poco a poco se a ido descubriendo, mostrando todo su potencial. Por eso aqu&iacute; es mirar cuales son las oportunidades que ella esta aprovechando, compartiendo porque lo que m&aacute;s les interesa a es conservar la vida&rdquo;, dijo.<\/strong><\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"margin-bottom: 0cm\">&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"margin-bottom: 0cm;font-weight: normal\"><span style=\"font-family: Times New Roman,serif\"><span style=\"font-size: large\">Por otra parte agreg&oacute; que en la medida que la mujer toma conciencia de 3 aspectos b&aacute;sicos en su vida como lo son la familia, el trabajo y la sociedad y de que manera sus acciones pueden impactar para impactar al desarrollo humano del entorno en el que viven.<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"margin-bottom: 0cm;font-weight: normal\">&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"margin-bottom: 0cm;font-weight: normal\"><span style=\"font-family: Times New Roman,serif\"><span style=\"font-size: large\">Finalmente coment&oacute; que en el campo laboral en los &uacute;ltimos a&ntilde;os se ha visto un incremento de las mujeres gracias a su inclusi&oacute;n para desarrollarse de manera personal y sobre todo para participar activamente para su desenvolvimiento personal y familiar.<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Re&uacute;ne la CTM en Sonora a un grupo considerable de mujeres de diferentes empresas en la ciudad de Hermosillo para que formar&aacute;n parte del taller Liderazgo y Desarrollo Integral de la Mujer y esto como parte de la conmemoraci&oacute;n del D&iacute;a Internacional de <\/p>\n","protected":false},"author":1,"featured_media":48081,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[384],"class_list":["post-48080","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-ctm"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1457476463_logo-ctm.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/48080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=48080"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/48080\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/48081"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=48080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=48080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=48080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}