{"id":47089,"date":"2016-02-26T11:01:41","date_gmt":"2016-02-26T11:01:41","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2016\/02\/26\/lleva-el-voluntariado-dif-cajeme-apoyos-al-campo-5\/"},"modified":"2016-02-26T11:01:41","modified_gmt":"2016-02-26T11:01:41","slug":"lleva-el-voluntariado-dif-cajeme-apoyos-al-campo-5","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2016\/02\/26\/lleva-el-voluntariado-dif-cajeme-apoyos-al-campo-5\/","title":{"rendered":"Lleva el Voluntariado DIF Cajeme apoyos al campo 5"},"content":{"rendered":"<p>Por Redacci&ograve;n<\/p>\n<p>&nbsp;<\/p>\n<p>Como parte de las labores que realiza el Voluntariado DIF Cajeme,&nbsp; la se&ntilde;ora Ena Olea de F&eacute;lix, presidenta de este organismo, llev&oacute; apoyo alimentario al campo 5, con el que resultaron beneficiadas 60 familias.<\/p>\n<p>La Primera Dama del Municipio reiter&oacute; el compromiso que tiene el DIF Cajeme con la comunidad y la poblaci&oacute;n m&aacute;s vulnerable.<\/p>\n<p>&ldquo;Pueden contar con la plena confianza que estamos para atenderlos y&nbsp; apoyarlos en lo que necesiten, una de las ideas que tenemos como&nbsp; DIF Cajeme es visitar a todas las comunidades y ponernos a su servicio, para que nos platiquen cualquier necesidad que tengan y estar en posibilidades de apoyarlos&rdquo;, expres&oacute;.<\/p>\n<p>Fue Cecilia Zazueta la encargada de brindar unas palabras de bienvenida, d&oacute;nde agradeci&oacute; a la se&ntilde;ora Ena Olea de F&eacute;lix el detalle de llevar estas despensas y convivir de cerca con las familias.<\/p>\n<p>Asistieron al evento el subdirector de Comisar&iacute;as y Delegaciones, Mario V&aacute;zquez; el comisario de Pueblo Yaqui, Trinidad S&aacute;nchez y el Delegado del Campo 5 Emilio V&aacute;zquez.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Primera Dama del Municipio reiter&oacute; el compromiso que tiene el DIF Cajeme con la comunidad y la poblaci&oacute;n m&aacute;s vulnerable.<\/p>\n","protected":false},"author":1,"featured_media":47090,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[177],"class_list":["post-47089","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estatal","tag-cajeme"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1456509701_Entrega-de-despensas-7.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/47089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=47089"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/47089\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/47090"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=47089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=47089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=47089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}