{"id":46130,"date":"2016-02-12T10:22:10","date_gmt":"2016-02-12T10:22:10","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2016\/02\/12\/edgar-rivera-y-su-pase-a-rio-2016\/"},"modified":"2016-02-12T10:22:10","modified_gmt":"2016-02-12T10:22:10","slug":"edgar-rivera-y-su-pase-a-rio-2016","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2016\/02\/12\/edgar-rivera-y-su-pase-a-rio-2016\/","title":{"rendered":"&quot;Edgar Rivera y su pase a Rio 2016&quot;"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: center\" align=\"center\"><strong><span lang=\"ES-MX\">VOZ SPORT<\/span><\/strong><\/p>\n<p class=\"MsoNormal\" style=\"text-align: center\" align=\"center\"><strong><span lang=\"ES-MX\">&ldquo;Edgar Rivera y su pase a Rio 2016&rdquo;<\/span><\/strong><\/p>\n<p class=\"MsoNormal\" style=\"text-align: center\" align=\"center\"><strong><span lang=\"ES-MX\">&nbsp;<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><strong><span lang=\"ES-MX\">Por Rafael Renter&iacute;a<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><strong><span lang=\"ES-MX\">&nbsp;<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><strong><span lang=\"ES-MX\">&Eacute;dgar Rivera tiene ya asegurado su nombre en la historia del deporte estatal al ser el primer atleta clasificado de Sonora para los Juegos Ol&iacute;mpicos de R&iacute;o de Janeiro 2016.<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">Con apenas 24 a&ntilde;os de edad y proveniente de una familia de grandes atletas de alto rendimiento como sus hermanos Jorge, Adrian y Luis Alberto quien ya sabe lo que es estar en unos Juegos Ol&iacute;mpicos (Londres 2012), &Eacute;dgar hace apenas unos d&iacute;as tambi&eacute;n pudo emular la haza&ntilde;a de su hermano mayor al conseguir su boleto a Rio 2016 al ganar su &uacute;ltima competencia de salto de altura.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">Fue precisamente en Rep&uacute;blica Checa en donde el nacido en Agua Prieta Sonora, pudo conseguir el primer boleto de un sonorense para las pr&oacute;ximas olimpiadas cuando supero la marca que estaban requiriendo en salto de altura dentro del Circuito Europeo de Atletismo al saltar 2.30 metros&nbsp; y de esa forma establecer un record personal.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">&Eacute;dgar viene a ser el atleta sonorense numero 24 nacido en el estado de Sonora que estar&aacute; en unos Juegos Ol&iacute;mpicos pero el octavo dentro del Atletismo y con ello unir su nombre a otros grandes de esa disciplina como Juan Pedro Toledo, Alejandro C&aacute;rdenas y la m&aacute;s grande de todas Ana Gabriela Guevara. Aparte en esa lista tambi&eacute;n aparecen los nombres de Luz Mercedes Acosta, Alejandra Valencia, Stephen S&aacute;enz, Oscar Valdez y hasta su hermano Luis Alberto Rivera.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">Este joven deportista sonorense debe de estar m&aacute;s que contento por tal pase a la justa m&aacute;s importante en el mundo y sobre todo ser considerado como un potencial ganador de medallas por nuestro pa&iacute;s que apenas en Londres 2012 solo pudo ganar en general 7 preseas y ser la segunda cantidad m&aacute;s grande de su historia.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">Y como dato importante o curioso, los hermanos Rivera Morales podr&iacute;a estar en Rio de Janeiro a mitad del a&ntilde;o su Luis Alberto puede tambi&eacute;n conseguir su boleto en Salto de Longitud y de esa forma ser la primera pareja de hermanos mexicanos en ese tipo de competencias.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">Esperemos que la lista de sonorenses pueda crecer en los pr&oacute;ximos d&iacute;as y de esa forma nuestro estado pueda estar representado por un n&uacute;mero importante. Si mi memoria no me falla en el 2012 Sonora le aporto a la selecci&oacute;n mexicana 5 atletas y por eso que bueno ser&iacute;a que para este 2016 esa cantidad pueda superarse.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">&Eacute;dgar habr&aacute; de recibir muchos consejos de su hermano Luis quien ya sabe lo que es estar en esa justa mundial y ahora &eacute;l tendr&aacute; la oportunidad de vivir esa experiencia con un objetivo claro que deber&aacute; GANAR UNA MEDALLA PARA M&Eacute;XICO. &hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;<\/span><\/p>\n<p class=\"MsoNormal\"><strong><span lang=\"ES-MX\">Ayer se anunci&oacute; que tanto los Membrilleros de Magdalena como los Rojos de Caborca van a formar parte de la Liga Norte de M&eacute;xico (LNM).<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">Con esta inclusi&oacute;n de Magdalena y Caborca la LNM estar&aacute; conformada por 9 equipos (5 de Sonora y 4 de Baja California) por lo que tomar&aacute; m&aacute;s fuerza tomando en cuenta del gran nivel de beisbol que se juega en el norte mexicano.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">La gente de esas dos ciudades de Sonora que son grandes aficionados al beisbol habr&aacute;n de estar contentos porque sus equipos habr&aacute;n de formar en esta liga que tambi&eacute;n pondr&aacute; en la competencia a los Diablos de Hermosillo, Algodoneros de San Luis que estar&aacute;n jugando en estadio nuevo, Tiburones de Puerto Pe&ntilde;asco, Freseros de San Quintin, Marineros de Ensenada, Centinelas de Mexicali y los tambi&eacute;n nuevos en este torneo los Toritos de Tecate.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">Ya con la conformaci&oacute;n de 9 equipos la LNM estar&aacute; iniciando actividades el pr&oacute;ximo 6 de abril y todos tratar&aacute;n de arrebatarle el t&iacute;tulo a los Centinelas de Mexicali.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">Esta liga que puede ser considerada como semiprofesional tiene bastante talento y no por nada equipos de la LMP y LMB env&iacute;an a sus jugadores a que se fogueen y en otros de los casos los ven ah&iacute; y los firman para equipos profesionales&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;&hellip;.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><strong><span lang=\"ES-MX\">Finalmente este viernes a las 945 de la ma&ntilde;ana se estar&aacute; llevando a cabo la re inauguraci&oacute;n del estadio de Beisbol en el Cereso #1.<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">La invitaci&oacute;n la est&aacute; haciendo la Secretaria de Seguridad P&uacute;blica (SSP) para que los interesados puedan ir ah&iacute; al Cereso 1 que se encuentra en el bulevar de los Ganaderos para que puedan presenciar la re inauguraci&oacute;n de ese estadio as&iacute; como tambi&eacute;n se har&aacute; la entrega de esas autoridades de material deportivo.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify;background-image: initial;background-attachment: initial;background-size: initial;background-position: initial;background-repeat: initial\"><span style=\"font-size: 12pt;font-family: Arial, sans-serif\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><strong><span lang=\"ES-MX\">Twitter: rafarenteria11<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><strong><span lang=\"ES-MX\">Facebook: Rafael Renteria R.<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><strong><span lang=\"ES-MX\">Correo Electr&oacute;nico: renteria_rafael@hotmail.com<\/span><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&Eacute;dgar Rivera tiene ya asegurado su nombre en la historia del deporte estatal al ser el primer atleta clasificado de Sonora para los Juegos Ol&iacute;mpicos de R&iacute;o de Janeiro 2016.<\/p>\n","protected":false},"author":1,"featured_media":46131,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[190],"tags":[4368],"class_list":["post-46130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-renteria","tag-columna-12-feb-16"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1455297730_edaf.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/46130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=46130"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/46130\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/46131"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=46130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=46130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=46130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}