{"id":45051,"date":"2016-01-30T09:20:36","date_gmt":"2016-01-30T09:20:36","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2016\/01\/30\/advierte-uepc-sobre-bajas-temperaturas-nevadas-y-lluvias-en-sonora\/"},"modified":"2016-01-30T09:20:36","modified_gmt":"2016-01-30T09:20:36","slug":"advierte-uepc-sobre-bajas-temperaturas-nevadas-y-lluvias-en-sonora","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2016\/01\/30\/advierte-uepc-sobre-bajas-temperaturas-nevadas-y-lluvias-en-sonora\/","title":{"rendered":"Advierte UEPC sobre bajas temperaturas, nevadas y lluvias en Sonora"},"content":{"rendered":"<p>Por Redacci&oacute;n<\/p>\n<p>&nbsp;<\/p>\n<p>Hermosillo, 30 de enero de 2016.- La Gobernadora Claudia Pavlovich Arellano instruy&oacute; a todas las dependencias a mantenerse en alerta ante la probabilidad de un frente fr&iacute;o que afectar&aacute; al Estado de Sonora a partir del domingo por la noche y a lo largo de este lunes.<\/p>\n<p>Lluvias dispersas e intermitentes, as&iacute; como potencial para la ca&iacute;da de nieve o aguanieve a partir del domingo por la noche y a lo largo del lunes, ser&iacute;an provocados por el frente fr&iacute;o n&uacute;mero 35, que afectar&iacute;a gran parte de municipios del norte, noreste y oriente de Sonora.<\/p>\n<p>Los municipios que est&aacute;n considerados en esta alerta por el frente fr&iacute;o n&uacute;mero 35 se ubican en la regi&oacute;n serrana y en los municipios del norte, noreste y oriente de Sonora.<\/p>\n<p>Habr&iacute;a afectaciones importantes a Nogales, Imuris, Cananea, Santa Cruz, Naco, Agua Prieta, Fronteras, Nacozari, Bacerac, Bavispe, Huachinera, Bacadehuachi, N&aacute;cori Chico, Sahuaripa y Y&eacute;cora.<\/p>\n<p>Las instrucciones de la Gobernadora Pavlovich es mantenerse atentos a las necesidades de la poblaci&oacute;n ante este fen&oacute;meno climatol&oacute;gico adverso, dijo el Secretario de Gobierno, Miguel Pompa Corell,a en un comunicado difundido por la Unidad Estatal de Protecci&oacute;n Civil a cargo de Alberto Flores Chong.<\/p>\n<p>Este frente fr&iacute;o se asociar&aacute; con una baja presi&oacute;n de n&uacute;cleo fr&iacute;o localizada en el suroeste de Estados Unidos y con la corriente en chorro, condici&oacute;n que favorecer&aacute; un fuerte descenso de temperatura, lluvias y vientos fuertes con rachas que podr&iacute;an superar los 70 km\/h en la entidad y el Golfo de California.<\/p>\n<p>Se presentar&aacute;n condiciones favorables para la ocurrencia de nieve, aguanieve o lluvia congelante en zonas monta&ntilde;osas de Baja California, Sonora y Chihuahua, a partir del domingo por la noche y a lo largo del lunes. Las autoridades se mantendr&aacute;n en estrecha vigilancia, dijo.<\/p>\n<p>De acuerdo con los Servicios Meteorol&oacute;gicos de M&eacute;xico y los Estados Unidos, se espera que este nuevo frente fr&iacute;o ingrese la tarde de este domingo por el norte de Baja California en lo que su tr&aacute;nsito se desarrollar&aacute; el lunes por el Estado.<\/p>\n<p>Se recomienda a los automovilistas que pudieran utilizar los puertos de Cananea en el tramo carretero Imuris-Cananea y Puerto San Luis del tramo carretero Agua Prieta-Janos el domingo por la noche y durante lunes y martes que se informen previamente de las condiciones en esos trechos.<\/p>\n<p>La Unidad Estatal de Protecci&oacute;n Civil de com&uacute;n acuerdo con la Coordinaci&oacute;n Nacional de Protecci&oacute;n Civil y la Comisi&oacute;n Nacional del Agua, emiten la siguiente alerta Meteorol&oacute;gica, para las regiones noroeste, norte, noreste, centro y oriente, con especial atenci&oacute;n para los municipios de San Luis Rio Colorado, Plutarco El&iacute;as Calles, Caborca, Puerto Pe&ntilde;asco, Atil, Tubutama, Pitiquito, Saric, Altar, Oquitoa, Trincheras, Santa Ana, Benjam&iacute;n Hill, Imuris, Magdalena, Nogales, Santa Cruz, Cananea, Bacoachi, Fronteras, Naco, Agua Prieta, Cucurpe, Ban&aacute;michi, Huepac, San Felipe de Jes&uacute;s, Aconchi, Bavi&aacute;cora, Ures, Hermosillo, Guaymas, Empalme, La Colorada, T&oacute;nichi, San Javier, Onavas, Soyopa, Matape, Mazatan, Ray&oacute;n, Opodepe, Carb&oacute;, San Miguel de Horcasitas, Arizpe, Bacerac, Bavispe, Huachinera, Bacad&eacute;huachi, N&aacute;cori Chico, Villa Hidalgo, Nacozari, Cumpas, Moctezuma, Tepache, Divisaderos, Sahuaripa, Y&eacute;cora, Quiriego, Rosario y &Aacute;lamos.<\/p>\n<p>Dichos sistemas podr&iacute;an generar un ambiente de fr&iacute;o a muy fr&iacute;o sobre las regiones, norte, centro, noroeste, noreste y oriente de la entidad a partir del d&iacute;a lunes.<\/p>\n<p>Con la informaci&oacute;n actual, se espera que dichos sistemas, podr&iacute;an generar, a partir del d&iacute;a lunes, temperaturas de -2 a -8 cent&iacute;grados o menores, en las regiones fronterizas con Arizona y zonas serranas del Estado, de &ndash; 8 a -10 cent&iacute;grados en los municipios de la frontera con Chihuahua, as&iacute; mismo, se espera que se registren temperaturas m&iacute;nimas de 2 a 6 cent&iacute;grados en los municipios de la regi&oacute;n central y de 4 a 6 cent&iacute;grados en el sur de Sonora.<\/p>\n<p>Agreg&oacute;, que extremen precauciones todas las embarcaciones en costas de Sonora exhortando a no efectuar la navegaci&oacute;n a embarcaciones menores de 15 m, principalmente desde Guaymas hacia el norte del Golfo de California por viento y oleaje, a partir del d&iacute;a domingo. Recomendando se atiendan las indicaciones que emite la SCT a trav&eacute;s de las capitan&iacute;as de los puertos.<\/p>\n<p>Puso a consideraci&oacute;n de las personas de extremar los cuidados con el uso de los equipos de gas L.P., braceros, anafres en el interior de los domicilios y coment&oacute; que en caso de cualquier incidente solicitar apoyo a su Unidad Municipal de Protecci&oacute;n Civil.<\/p>\n<p>Ante este escenario de vientos fuertes y posible ambiente muy fr&iacute;o, la Unidad Estatal de Protecci&oacute;n Civil, emite la presente alerta a la poblaci&oacute;n en general, principalmente a quienes habitan regiones consideradas de alto riesgo, para que extremen precauciones y atiendan las siguientes recomendaciones, adicionales a las que dispongan las autoridades locales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Los municipios que est&aacute;n considerados en esta alerta por el frente fr&iacute;o n&uacute;mero 35 se ubican en la regi&oacute;n serrana y en los municipios del norte, noreste y oriente de Sonora.<\/p>\n","protected":false},"author":1,"featured_media":45052,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[231],"class_list":["post-45051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-uepc"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1454170883_d363.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/45051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=45051"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/45051\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/45052"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=45051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=45051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=45051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}