{"id":44406,"date":"2016-01-21T21:09:29","date_gmt":"2016-01-21T21:09:29","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2016\/01\/21\/peasco-va-a-continuar-por-buen-rumbo-dip-fed-everardo-lpez\/"},"modified":"2016-01-21T21:09:29","modified_gmt":"2016-01-21T21:09:29","slug":"peasco-va-a-continuar-por-buen-rumbo-dip-fed-everardo-lpez","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2016\/01\/21\/peasco-va-a-continuar-por-buen-rumbo-dip-fed-everardo-lpez\/","title":{"rendered":"Pe&ntilde;asco va a continuar por buen rumbo: Dip. Fed. Everardo L&oacute;pez"},"content":{"rendered":"<p>Por Redacci&oacute;n<\/p>\n<p>&nbsp;<\/p>\n<p>Como un plan de desarrollo ambicioso pero bien definido, as&iacute; calific&oacute; el Diputado Federal Everardo L&oacute;pez la presentaci&oacute;n del Plan de Desarrollo Municipal de Puerto Pe&ntilde;asco.<\/p>\n<p>El legislador federal acompa&ntilde;&oacute; al alcalde Ernesto &#8220;Kiko&#8221; Munro a la presentaci&oacute;n del Plan de Desarrollo Municipal, en donde destac&oacute; el mejoramiento del municipio en los primeros cien d&iacute;as de gobierno.<\/p>\n<p>&#8220;Veo con gusto el avance de Puerto Pe&ntilde;asco, una ciudad m&aacute;s limpia y ordenada, esto definitivamente es gracias a que el alcalde Kiko Munro es un presidente todo terreno, que va a las calles, que pl&aacute;tica y escucha a la gente para saber las necesidades de la cuidad&#8221;, explic&oacute;. <\/p>\n<p>Everardo L&oacute;pez dijo que los residentes de Pe&ntilde;asco y el presidente municipal cuentan con su respaldo para mejorar las condiciones de vida de Puerto Pe&ntilde;asco.<\/p>\n<p>&#8220;Kiko cuenta con todo mi respaldo para que el desarrollo del puerto contin&uacute;e, para que este plan que hoy presenta con metas a corto, mediano y largo plazo salga adelante&#8221;, extern&oacute; L&oacute;pez Cordova.<\/p>\n<p>&#8220;No tengo duda de que Pe&ntilde;asco seguir&aacute; transform&aacute;ndose, con una visi&oacute;n clara, respondiendo a la confianza que nos dio la gente y cumpliendo con los anhelos de los ciudadanos de la mano de todos los sectores&#8221;, concluy&oacute; el legislador. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Destaca Diputado labor de Kiko Munro en 100 d&iacute;as de gobierno<\/p>\n","protected":false},"author":1,"featured_media":44407,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[3061],"class_list":["post-44406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estatal","tag-everardo"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1453435769_evekiko.JPG","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/44406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=44406"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/44406\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/44407"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=44406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=44406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=44406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}