{"id":44158,"date":"2016-01-19T17:03:06","date_gmt":"2016-01-19T17:03:06","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2016\/01\/19\/se-ofertan-en-slrc-ms-de-600-empleos-copresan\/"},"modified":"2016-01-19T17:03:06","modified_gmt":"2016-01-19T17:03:06","slug":"se-ofertan-en-slrc-ms-de-600-empleos-copresan","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2016\/01\/19\/se-ofertan-en-slrc-ms-de-600-empleos-copresan\/","title":{"rendered":"Se ofertan en SLRC m&aacute;s de 600 empleos, COPRESAN."},"content":{"rendered":"<p>Por Redacci&oacute;n<\/p>\n<p>&nbsp;<\/p>\n<p>M&aacute;s de 600 oportunidades de empleo en el sector industrial son las que actualmente se ofertan en nuestra ciudad, y ser&aacute; la Direcci&oacute;n de Desarrollo Social Municipal un v&iacute;nculo con las empresas que requieren de personal, as&iacute; lo confirm&oacute; el Comisi&oacute;n de Promoci&oacute;n Econ&oacute;mica de San Luis R&iacute;o Colorado (COPRESAN).<\/p>\n<p>Carlos Mexia Medina, Director Ejecutivo de COPRESAN, inform&oacute; que la Direcci&oacute;n de Desarrollo Social Municipal ya trabaja en la integraci&oacute;n de un un registro de los vacantes que tiene la industria, para que los ciudadanos la consulten y puedan incluirse en la lista de ocupaci&oacute;n.<\/p>\n<p>El titular de la paramunicipal precis&oacute; que el Ayuntamiento de San Luis R&iacute;o Colorado busca coadyuvar en la canalizaci&oacute;n personal con el sector industrial, as&iacute; como comercial.<\/p>\n<p>&ldquo;Existen muchas empresas que est&aacute;n manifestando la necesidad de&nbsp; trabajadores, ya que se encuentran en etapa de crecimiento, es por eso la necesidad de informar y canalizar a las personas para que aprovechen esas&nbsp; vacantes, mediante las cuales obtendr&aacute;n un ingreso,&nbsp; la seguridad social y todas las prestaciones de Ley.<\/p>\n<p>Curiosamente son residentes del vecino estado de Baja California quienes est&aacute;n ocupando estas vacantes. Por eso vemos la necesidad de contribuir a que los residentes sepan d&oacute;nde est&aacute;n solicitando trabajadores, explic&oacute;.<\/p>\n<p>A trav&eacute;s de esta vinculaci&oacute;n, la comunidad sanluisina conocer&aacute; las opciones de trabajo y a su vez, las empresas podr&aacute;n encontrar a los candidatos&nbsp; id&oacute;neos, con los perfiles, habilidades y conocimientos&nbsp; que requieren&nbsp; para cubrir sus necesidades&nbsp; de producci&oacute;n.<\/p>\n<p>Precis&oacute; que el sector industrial no se limita a la contrataci&oacute;n de personas j&oacute;venes, en muchos de los casos, requieren de personas mayores, con experiencia y responsabilidad en tareas espec&iacute;ficas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trabajar&aacute; Ayuntamiento en la promoci&oacute;n de oportunidades de empleo.<\/p>\n","protected":false},"author":1,"featured_media":44159,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[4098],"class_list":["post-44158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estatal","tag-ayuntamiento-slrc"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1453248186_sf.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/44158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=44158"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/44158\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/44159"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=44158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=44158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=44158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}