{"id":43798,"date":"2016-01-13T11:31:01","date_gmt":"2016-01-13T11:31:01","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2016\/01\/13\/recibe-municipio-de-cajeme-apoyo-de-unison-con-mdicos-pasantes\/"},"modified":"2016-01-13T11:31:01","modified_gmt":"2016-01-13T11:31:01","slug":"recibe-municipio-de-cajeme-apoyo-de-unison-con-mdicos-pasantes","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2016\/01\/13\/recibe-municipio-de-cajeme-apoyo-de-unison-con-mdicos-pasantes\/","title":{"rendered":"Recibe Municipio de Cajeme apoyo de UNISON con m&eacute;dicos pasantes"},"content":{"rendered":"<p>Por Redacci&oacute;n<\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"margin: 0px 0px 1.35em;padding: 0px;border: 0px;font-size: 11pt;line-height: inherit;font-family: Calibri, sans-serif;vertical-align: baseline;text-align: justify;color: #444444\">Cinco m&eacute;dicos pasantes fueron asignados al Ayuntamiento de Cajeme, luego de que en la unidad local de la UNISON les fuera otorgada su plaza para servicio social.<\/p>\n<p class=\"ecxMsoNormal\" style=\"margin: 0px 0px 1.35em;padding: 0px;border: 0px;font-size: 11pt;line-height: inherit;font-family: Calibri, sans-serif;vertical-align: baseline;text-align: justify;color: #444444\">Filiberto Arenas, subdirector de Salud Municipal en representaci&oacute;n del Alcalde Faustino F&eacute;lix Ch&aacute;vez dio la bienvenida a los nuevos m&eacute;dicos, a quienes inform&oacute; que contar&aacute;n con el respaldo de un m&eacute;dico titulado, durante su estancia en el municipio.<\/p>\n<p class=\"ecxMsoNormal\" style=\"margin: 0px 0px 1.35em;padding: 0px;border: 0px;font-size: 11pt;line-height: inherit;font-family: Calibri, sans-serif;vertical-align: baseline;text-align: justify;color: #444444\">Asimismo, manifest&oacute; que durante un a&ntilde;o, los cinco j&oacute;venes estar&aacute;n realizando sus actividades en&nbsp;las&nbsp;unidades m&eacute;dicas&nbsp;municipales&nbsp;de Loma de Guam&uacute;chil, colonia Antonio Rosales, colonia Cajeme, USSI Sur y colonia Miravalle, adem&aacute;s de participar en la implementaci&oacute;n de jornadas m&eacute;dicas.<\/p>\n<p class=\"ecxMsoNormal\" style=\"margin: 0px 0px 1.35em;padding: 0px;border: 0px;font-size: 11pt;line-height: inherit;font-family: Calibri, sans-serif;vertical-align: baseline;text-align: justify;color: #444444\">En el evento de asignaci&oacute;n de plazas estuvieron presentes Alejandro G&oacute;mez Alcal&aacute;, coordinador de la carrera de Licenciatura en Medicina de la UNISON; David L&oacute;pez del Castillo, responsable de servicio social; Ren&eacute; Angulo Campos, coordinador de m&eacute;dicos pasantes de la Secretar&iacute;a de Salud; Abrahana Valenzuela, directora de Salud del municipio de &Aacute;lamos y Mar&iacute;a Jos&eacute; Olivas Gil, directora del DIF &Aacute;lamos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Realizar&aacute;n su servicio social en casas de salud urbanas y rurales del Municipio<\/p>\n","protected":false},"author":1,"featured_media":43799,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[177],"class_list":["post-43798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estatal","tag-cajeme"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1452709861_7789olknj.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/43798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=43798"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/43798\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/43799"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=43798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=43798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=43798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}