{"id":43732,"date":"2016-01-12T13:51:01","date_gmt":"2016-01-12T13:51:01","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2016\/01\/12\/presidenta-del-dif-san-luis-atiende-poblados-del-valle\/"},"modified":"2016-01-12T13:51:01","modified_gmt":"2016-01-12T13:51:01","slug":"presidenta-del-dif-san-luis-atiende-poblados-del-valle","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2016\/01\/12\/presidenta-del-dif-san-luis-atiende-poblados-del-valle\/","title":{"rendered":"Presidenta del DIF San Luis atiende poblados del Valle."},"content":{"rendered":"<p>Por Redacci&ograve;n<\/p>\n<p>&nbsp;<\/p>\n<p>La Presidenta de DIF Municipal, Lupita S&aacute;nchez de Reina,&nbsp; inici&oacute; esta semana con acciones de atenci&oacute;n directa en los poblados del Valle de San Luis R&iacute;o Colorado.<\/p>\n<p>La primera dama, acompa&ntilde;ada por personal de DIF, recorri&oacute; los hogares de los poblados de Independencia y Lagunitas para atender de manera personal las necesidades de las familias.<\/p>\n<p>Los residentes de los poblados recibieron tambi&eacute;n regalos, ya que gracias al apoyo de la comunidad sanluisina se han podido entregar miles de obsequios.<\/p>\n<p>La Presidenta del Sistema DIF Municipal coment&oacute; que el recorrido por los distintos poblados del valle ser&aacute; constante, ya que se estar&aacute;n realizando actividades conjuntas, buscando siempre brindarles todos los servicios que ofrece la dependencia, entre los que se encuentran las asesor&iacute;as legales, apoyo de trabajo social, atenci&oacute;n m&eacute;dica, charlas, cursos, etc.<\/p>\n<p>Lupita S&aacute;nchez de Reina aprovech&oacute; la oportunidad para entregar a las familias de Lagunitas e Independencia cobijas para que puedan cubrirse del&nbsp;fr&iacute;o&nbsp;que se ha dejado sentir en la ciudad las&nbsp;&uacute;ltimas semanas.<\/p>\n<p>Adem&aacute;s dijo que todos los poblados del valle y el Golfo de Santa Clara continuar&aacute;n recibiendo atenci&oacute;n de parte de la instituci&oacute;n buscando siempre la conjunci&oacute;n de esfuerzos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Presidenta de DIF Municipal, Lupita S&aacute;nchez de Reina,  inici&oacute; esta semana con acciones de atenci&oacute;n directa en los poblados del Valle de San Luis R&iacute;o Colorado.<\/p>\n","protected":false},"author":1,"featured_media":43733,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[3830],"class_list":["post-43732","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estatal","tag-slrc"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1452631861_0.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/43732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=43732"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/43732\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/43733"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=43732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=43732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=43732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}