{"id":41240,"date":"2015-11-25T08:54:37","date_gmt":"2015-11-25T08:54:37","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2015\/11\/25\/ana-guevara-de-parte-de-la-conade\/"},"modified":"2015-11-25T08:54:37","modified_gmt":"2015-11-25T08:54:37","slug":"ana-guevara-de-parte-de-la-conade","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2015\/11\/25\/ana-guevara-de-parte-de-la-conade\/","title":{"rendered":"&quot;Ana Guevara de parte de la Conade&quot;"},"content":{"rendered":"<p class=\"MsoNormal\"><strong><span lang=\"ES-MX\">Por Rafael Renter&iacute;a<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><strong><span lang=\"ES-MX\">&nbsp;<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><strong><span lang=\"ES-MX\">Vaya que la disputa por el poder del deporte en M&eacute;xico est&aacute; viviendo tiempos &aacute;lgidos, ya que actualmente hay dos bloques que est&aacute;n d&aacute;ndose con todo con tal de salir con la victoria.<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">Por un lado el frente de Alfredo Castillo, titular de la Conade esta denunciando cuentas claras y fraudes de parte de varias federaciones deportivas en el pa&iacute;s y por el otro lado esas mismas federaciones as&iacute; como el Comit&eacute; Ol&iacute;mpico Mexicano que alegan autoritarismo hacia ellos, lo cual ya se dio a conocer incluso en el Comit&eacute; Ol&iacute;mpico Internacional (COI).<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">El caso es que este hecho quiz&aacute;s in&eacute;dito en nuestro pa&iacute;s, debido a que antes ninguna autoridad que rige al deporte en M&eacute;xico les ped&iacute;a cuentas claras o hac&iacute;an como que se las ped&iacute;an, est&aacute; causando mucho de qu&eacute; hablar ya que al existir cientos de millones de pesos en juego es normal que alguien tenga que pegar de gritos.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">Precisamente una de esas voces y con mucho peso en M&eacute;xico, es la actual senadora sonorense Ana Gabriela Guevara quien claramente ha dicho que apoya la batalla que ha emprendido el director de la Conade a pesar de todo lo que se diga de &eacute;l en el sentido que no sabe nada del deporte mexicano.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">Ana ha sido siempre elocuente en su discurso al decir que es necesario que en M&eacute;xico se acabe con la corrupci&oacute;n en el deporte y tal parece que ha visto en Alfredo Castillo como el fiscal que pudiera ir sacando poco a poco lo que no sirve de las federaciones deportivas mexicanas que por muchos a&ntilde;os han hecho y deshecho a su antojo sin rendir cuentas pero sobre todo resultados a nadie.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">Y esta guerra de lana porque de eso es solamente, empez&oacute; haces meses cuando se anunci&oacute; el recorte presupuestal por parte de la federaci&oacute;n y fue cuando quienes reciben el recurso sintieron que adem&aacute;s que se les reducir&iacute;an sus partidas tambi&eacute;n les pondr&iacute;an m&aacute;s reglas para disponer de cada peso que al final de todo es dinero p&uacute;blico, &oacute;sea, dinero de todos nosotros.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">A coces como de la ex velocista sonorense y considera la mejor corredora del planeta hace varios a&ntilde;os, se le han estado sumando otros deportistas de gran nombre como el tambi&eacute;n sonorense Luis Rivera, Paola Espinoza, Gustavo Ay&oacute;n y otros m&aacute;s que han declarado lo mismo en el sentido que es urgente terminar con la corrupci&oacute;n que as&iacute; como se ha metido hasta las c&eacute;lulas de la pol&iacute;tica ha hecho lo mismo con el deporte mexicano.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">Eso que se ha comentado que incluso esta situaci&oacute;n pudiera hacer que el deporte mexicano podr&iacute;a quedar desafilado del Comit&eacute; Ol&iacute;mpico Internacional y no competir como naci&oacute;n en los pr&oacute;ximas olimpiadas, lo veo como algo que no puede pasar y si si, pues ser&iacute;a el momento id&oacute;neo para empezar de cero y poner reglas claras en cuanto al manejo de recursos se refiere.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">Aqu&iacute; en M&eacute;xico es normal el dar dinero, dinero p&uacute;blico y no se condiciona a resultados. Si hici&eacute;ramos cuentas m&aacute;s del 90% del recurso que se ha erogado por muchos a&ntilde;os de que nos ha servido como pa&iacute;s? Cuantas medallas se han obtenido, atletas reconocidos a nivel mundial? Y asi varios etc. Simplemente somos una naci&oacute;n que no concuerda con lo que eroga a lo que ha ganado en materia deportiva.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">Porque otros directores nacionales de Conade o los mismos presidentes de la rep&uacute;blica nunca han pegado de gritos para fiscalizar de una mejor forma el recurso que se ha destinado a las federaciones deportivas? Esto no quiere decir que todas sean malas o hagan de ese dinero uso a su discreci&oacute;n, pero no es un secreto que es algo que no se piden muchas cuentas y luego no se sabe en qu&eacute; se fue algo que esta etiquetado para alguna pr&aacute;ctica deportiva.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">Todos esos atletas de primer nivel que tiene nuestro pa&iacute;s y que tambi&eacute;n han alzado la voz por esta situaci&oacute;n en especifico, han dicho en su momento lo mal que esta el deporte mexicano y no solo en lo deportivo sino en las formas en c&oacute;mo se maneja as&iacute; como el dinero que se invierte en ello.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">Simplemente en mismo Alfredo Castillo ha denunciado que en M&eacute;xico existen 8 federaciones deportivas que forman parte de un fraude de m&aacute;s de 300 millones de pesos. Esa cantidad se me hace muy poca para lo que se la ha invertido al deporte a lo largo de su historia, pero bueno al menos siento que si se quiere empezar por algo se haga ya y se pongan varios candados para no volver a vivir estos mismos episodios.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">El deporte mexicano necesita crecer y lo digo en todos los sentidos: en su manejo, recursos y resultados. El deportista mexicano por lo regular le batalla un sinf&iacute;n de cosas para llegar a su meta, ellos no viven como los gringos, los canadienses, los ingleses que pr&aacute;cticamente les pagan todo para que entrenen y por eso estamos como estamos. Las pol&iacute;ticas p&uacute;blicas en el deporte mexicano son obsoletas&nbsp; y las becas obviamente no alcanzan para muchos.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">A lo mejor de este alboroto ya puede surgir la creaci&oacute;n de una Secretaria del Deporte, ya que seg&uacute;n con ella todos los niveles deportivos estar&iacute;an alineados en una misma sinton&iacute;a incluso con el deporte estudiantil y as&iacute; conseguir mejores resultados.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">Yo ver para creer, porque si esto queda solo en un mero choro medi&aacute;tico: que gueva me dar&aacute; seguir gastando saliva y que la cosa no cambie. Esta es la oportunidad de aprovechar el empuje de una mujer como Ana Gabriela Guevara que sin dudarlo tiene m&aacute;s autoridad que el mismo director de la Conade como para dirigir algo que sea de beneficio para todo el deporte de nuestro pa&iacute;s.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">Ya basta vivir igual que siempre y con los mismos resultados. <\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES-MX\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><strong><span lang=\"ES-MX\">Twitter: rafarenteria11<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><strong><span lang=\"ES-MX\">Facebook: Rafael Renteria R.<\/span><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\"><strong><span lang=\"ES-MX\">Correo Electr&oacute;nico: renteria_rafael@hotmail.com<\/span><\/strong><span style=\"font-size: 12pt;line-height: 115%;font-family: Arial, sans-serif\">&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vaya que la disputa por el poder del deporte en M&eacute;xico est&aacute; viviendo tiempos &aacute;lgidos, ya que actualmente hay dos bloques que est&aacute;n d&aacute;ndose con todo con tal de salir con la victoria.<\/p>\n","protected":false},"author":1,"featured_media":41241,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[190],"tags":[4115],"class_list":["post-41240","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-renteria","tag-columna-25-nov-15"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1448466877_ana-gabriela-guevara.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/41240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=41240"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/41240\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/41241"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=41240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=41240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=41240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}